{"id":83824,"date":"2021-10-03T17:24:43","date_gmt":"2021-10-03T16:24:43","guid":{"rendered":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?p=83824"},"modified":"2025-03-22T08:48:49","modified_gmt":"2025-03-22T07:48:49","slug":"histoire-et-patrimoine-de-saint-thierry-marne","status":"publish","type":"post","link":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-thierry-marne\/","title":{"rendered":"Histoire et patrimoine de Saint-Thierry (Marne)"},"content":{"rendered":"<p><strong>Histoire et patrimoine de Saint-Thierry (Marne)<\/strong><br \/>\n<a href=\"https:\/\/www.saint-thierry.fr\/sites\/ccnc_stthierry\/files\/page\/document\/histoire_de_la_commune.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/www.saint-thierry.fr\/sites\/ccnc_stthierry\/files\/page\/document\/histoire_de_la_commune.pdf<\/a><\/p>\n<p style=\"text-align: justify;\"><em><a href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/10\/saintthierry51.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-83825\" src=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/10\/saintthierry51-300x249.png\" alt=\"\" width=\"300\" height=\"249\" srcset=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/10\/saintthierry51-300x249.png 300w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/10\/saintthierry51.png 441w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>un site r\u00e9f\u00e9renc\u00e9 sur le nouvel\u00a0<a href=\"http:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\" target=\"_blank\" rel=\"noopener noreferrer\">Annuaire Historique des Communes de France<\/a><\/em><\/p>\n<p style=\"text-align: justify;\"><span id=\"page3R_mcid0\" class=\"markedContent\"><span dir=\"ltr\" role=\"presentation\">C\u2019est au de\u0301but du XIIe\u0300me sie\u0300cle que l\u2019on retrouve les traces officielles du village de Saint<\/span><span dir=\"ltr\" role=\"presentation\">&#8211;<\/span><span dir=\"ltr\" role=\"presentation\">Thierry<\/span><span dir=\"ltr\" role=\"presentation\">,<\/span> <span dir=\"ltr\" role=\"presentation\">issu de la <\/span><span dir=\"ltr\" role=\"presentation\">localit\u00e9<\/span> <span dir=\"ltr\" role=\"presentation\">du Mont d\u2019Hor<\/span><span dir=\"ltr\" role=\"presentation\">,<\/span> <span dir=\"ltr\" role=\"presentation\">qui se constitue<\/span> <span dir=\"ltr\" role=\"presentation\">durant la <\/span><span dir=\"ltr\" role=\"presentation\">p\u00e9riode<\/span> <span dir=\"ltr\" role=\"presentation\">carolingienne. <\/span> <\/span><span id=\"page3R_mcid1\" class=\"markedContent\"><span dir=\"ltr\" role=\"presentation\">Le v<\/span><span dir=\"ltr\" role=\"presentation\">i<\/span><span dir=\"ltr\" role=\"presentation\">llage est d\u2019abord <\/span> <span dir=\"ltr\" role=\"presentation\">une ferme <\/span> <span dir=\"ltr\" role=\"presentation\">nomm\u00e9e<\/span> <span dir=\"ltr\" role=\"presentation\">GAUGIS ou GAUGY, donation faite par le roi <\/span><span dir=\"ltr\" role=\"presentation\">d\u2019Austrasie, fils de Clovis. <\/span> <\/span><span id=\"page3R_mcid2\" class=\"markedContent\"><span dir=\"ltr\" role=\"presentation\">Il doit son no<\/span><span dir=\"ltr\" role=\"presentation\">m a\u0300 Thierry, disciple de saint <\/span><span dir=\"ltr\" role=\"presentation\">Remi, <\/span><span dir=\"ltr\" role=\"presentation\">fondateur au<\/span> <span dir=\"ltr\" role=\"presentation\">VI\u00e8me<\/span> <span dir=\"ltr\" role=\"presentation\">si\u00e8cle<\/span> <span dir=\"ltr\" role=\"presentation\">d\u2019un <\/span><span dir=\"ltr\" role=\"presentation\">monast\u00e8re<\/span> <span dir=\"ltr\" role=\"presentation\">au <\/span><span dir=\"ltr\" role=\"presentation\">lieu dit \u00ab Hor \u00bb.<\/span><\/span>..<\/p>\n<p><em>(image et extrait du site officiel de la commune&#8230;<a href=\"https:\/\/www.saint-thierry.fr\/sites\/ccnc_stthierry\/files\/page\/document\/histoire_de_la_commune.pdf\" target=\"_blank\" rel=\"noopener\"> lire la suite<\/a>)<\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/amzn.to\/4bT0gui\" target=\"_blank\" rel=\"noopener\"><strong>Ouvrages sur la Marne<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/amzn.to\/4bT0gui\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-97336\" src=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2022\/09\/marnehistoire.jpg\" alt=\"\" width=\"303\" height=\"425\" srcset=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2022\/09\/marnehistoire.jpg 303w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2022\/09\/marnehistoire-214x300.jpg 214w\" sizes=\"auto, (max-width: 303px) 100vw, 303px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Histoire et patrimoine de Saint-Thierry (Marne) https:\/\/www.saint-thierry.fr\/sites\/ccnc_stthierry\/files\/page\/document\/histoire_de_la_commune.pdf un site r\u00e9f\u00e9renc\u00e9 sur le nouvel\u00a0Annuaire Historique des Communes de France C\u2019est au de\u0301but du XIIe\u0300me sie\u0300cle que l\u2019on retrouve les traces officielles du village de Saint&#8211;Thierry, issu de la localit\u00e9 du Mont d\u2019Hor, qui se constitue durant la p\u00e9riode carolingienne. Le village est d\u2019abord une ferme nomm\u00e9e &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-thierry-marne\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":117,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[139,16,8],"tags":[],"class_list":["post-83824","post","type-post","status-publish","format-standard","hentry","category-51-marne","category-histoire-regionale","category-patrimoine","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire et patrimoine de Saint-Thierry (Marne) - Histoire de France - Communiqu\u00e9s<\/title>\n<meta name=\"description\" content=\"C\u2019est au de\u0301but du XIIe\u0300me sie\u0300cle que l\u2019on retrouve les traces officielles du village de Saint-Thierry, issu de la localit\u00e9 du Mont d\u2019Hor\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-thierry-marne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire et patrimoine de Saint-Thierry (Marne) - Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"og:description\" content=\"C\u2019est au de\u0301but du XIIe\u0300me sie\u0300cle que l\u2019on retrouve les traces officielles du village de Saint-Thierry, issu de la localit\u00e9 du Mont d\u2019Hor\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-thierry-marne\/\" \/>\n<meta property=\"og:site_name\" content=\"Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-03T16:24:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-22T07:48:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/10\/saintthierry51.png\" \/>\n\t<meta property=\"og:image:width\" content=\"441\" \/>\n\t<meta property=\"og:image:height\" content=\"366\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"administrateur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrateur\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-thierry-marne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-thierry-marne\\\/\"},\"author\":{\"name\":\"administrateur\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\"},\"headline\":\"Histoire et patrimoine de Saint-Thierry (Marne)\",\"datePublished\":\"2021-10-03T16:24:43+00:00\",\"dateModified\":\"2025-03-22T07:48:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-thierry-marne\\\/\"},\"wordCount\":145,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-thierry-marne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/saintthierry51-300x249.png\",\"articleSection\":[\"51 - Marne\",\"histoire locale\",\"patrimoine\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-thierry-marne\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-thierry-marne\\\/\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-thierry-marne\\\/\",\"name\":\"Histoire et patrimoine de Saint-Thierry (Marne) - Histoire de France - Communiqu\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-thierry-marne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-thierry-marne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/saintthierry51-300x249.png\",\"datePublished\":\"2021-10-03T16:24:43+00:00\",\"dateModified\":\"2025-03-22T07:48:49+00:00\",\"description\":\"C\u2019est au de\u0301but du XIIe\u0300me sie\u0300cle que l\u2019on retrouve les traces officielles du village de Saint-Thierry, issu de la localit\u00e9 du Mont d\u2019Hor\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-thierry-marne\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-thierry-marne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-thierry-marne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/saintthierry51.png\",\"contentUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/saintthierry51.png\",\"width\":441,\"height\":366},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-thierry-marne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Histoire et patrimoine de Saint-Thierry (Marne)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\",\"name\":\"Histoire de France - Communiqu\u00e9s\",\"description\":\"Histoire et patrimoine\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\",\"name\":\"administrateur\",\"logo\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.charles-de-flahaut.fr\",\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\",\"name\":\"administrateur\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/author\\\/hist_8la_ad\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire et patrimoine de Saint-Thierry (Marne) - Histoire de France - Communiqu\u00e9s","description":"C\u2019est au de\u0301but du XIIe\u0300me sie\u0300cle que l\u2019on retrouve les traces officielles du village de Saint-Thierry, issu de la localit\u00e9 du Mont d\u2019Hor","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-thierry-marne\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire et patrimoine de Saint-Thierry (Marne) - Histoire de France - Communiqu\u00e9s","og_description":"C\u2019est au de\u0301but du XIIe\u0300me sie\u0300cle que l\u2019on retrouve les traces officielles du village de Saint-Thierry, issu de la localit\u00e9 du Mont d\u2019Hor","og_url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-thierry-marne\/","og_site_name":"Histoire de France - Communiqu\u00e9s","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_published_time":"2021-10-03T16:24:43+00:00","article_modified_time":"2025-03-22T07:48:49+00:00","og_image":[{"width":441,"height":366,"url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/10\/saintthierry51.png","type":"image\/png"}],"author":"administrateur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"administrateur","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-thierry-marne\/#article","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-thierry-marne\/"},"author":{"name":"administrateur","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56"},"headline":"Histoire et patrimoine de Saint-Thierry (Marne)","datePublished":"2021-10-03T16:24:43+00:00","dateModified":"2025-03-22T07:48:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-thierry-marne\/"},"wordCount":145,"commentCount":0,"publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-thierry-marne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/10\/saintthierry51-300x249.png","articleSection":["51 - Marne","histoire locale","patrimoine"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-thierry-marne\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-thierry-marne\/","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-thierry-marne\/","name":"Histoire et patrimoine de Saint-Thierry (Marne) - Histoire de France - Communiqu\u00e9s","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-thierry-marne\/#primaryimage"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-thierry-marne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/10\/saintthierry51-300x249.png","datePublished":"2021-10-03T16:24:43+00:00","dateModified":"2025-03-22T07:48:49+00:00","description":"C\u2019est au de\u0301but du XIIe\u0300me sie\u0300cle que l\u2019on retrouve les traces officielles du village de Saint-Thierry, issu de la localit\u00e9 du Mont d\u2019Hor","breadcrumb":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-thierry-marne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-thierry-marne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-thierry-marne\/#primaryimage","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/10\/saintthierry51.png","contentUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/10\/saintthierry51.png","width":441,"height":366},{"@type":"BreadcrumbList","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-thierry-marne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Histoire et patrimoine de Saint-Thierry (Marne)"}]},{"@type":"WebSite","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/","name":"Histoire de France - Communiqu\u00e9s","description":"Histoire et patrimoine","publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9","name":"administrateur","logo":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/www.charles-de-flahaut.fr","https:\/\/www.facebook.com\/Sites.HistoiredeFrance"]},{"@type":"Person","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56","name":"administrateur","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/author\/hist_8la_ad\/"}]}},"views":27,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/83824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=83824"}],"version-history":[{"count":3,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/83824\/revisions"}],"predecessor-version":[{"id":101198,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/83824\/revisions\/101198"}],"wp:attachment":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=83824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=83824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=83824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}