{"id":83198,"date":"2021-09-01T15:14:30","date_gmt":"2021-09-01T14:14:30","guid":{"rendered":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?p=83198"},"modified":"2025-03-28T10:03:38","modified_gmt":"2025-03-28T09:03:38","slug":"histoire-et-patrimoine-de-gertwiller-bas-rhin","status":"publish","type":"post","link":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-gertwiller-bas-rhin\/","title":{"rendered":"Histoire et patrimoine de Gertwiller (Bas-Rhin)"},"content":{"rendered":"<p><strong>Histoire et patrimoine de Gertwiller (Bas-Rhin)<\/strong><br \/>\n<a href=\"https:\/\/www.paysdebarr.fr\/fr\/les-communes\/gertwiller\/commune\" target=\"_blank\" rel=\"noopener\">https:\/\/www.paysdebarr.fr\/fr\/les-communes\/gertwiller\/commune<\/a><\/p>\n<p style=\"text-align: justify;\"><em><a href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/09\/gertwiller67-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-83199\" src=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/09\/gertwiller67-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/09\/gertwiller67-300x225.jpg 300w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/09\/gertwiller67-1024x768.jpg 1024w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/09\/gertwiller67-768x576.jpg 768w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/09\/gertwiller67-1536x1152.jpg 1536w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/09\/gertwiller67-2048x1536.jpg 2048w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/09\/gertwiller67-703x527.jpg 703w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>un site r\u00e9f\u00e9renc\u00e9 sur le nouvel\u00a0<a href=\"http:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\" target=\"_blank\" rel=\"noopener noreferrer\">Annuaire Historique des Communes de France<\/a><\/em><\/p>\n<p style=\"text-align: justify;\">L&rsquo;existence du village est attest\u00e9e d\u00e8s 718 sous la d\u00e9nomination de GERTENWILRE. A cette \u00e9poque le Duc ETICHON (ou ATTICH) \u00e9tait l&rsquo;un des souverains les plus importants d&rsquo;Alsace. Il fit don \u00e0 sa fille Odile de sa forteresse ALTITONA ; l&rsquo;ancienne HOHENBURG ; elle la transforma en monast\u00e8re de femmes&#8230;.<\/p>\n<p><em>(image et extrait du site paysdebarr.fr&#8230;<a href=\"https:\/\/www.paysdebarr.fr\/fr\/les-communes\/gertwiller\/commune\" target=\"_blank\" rel=\"noopener\"> lire la suite<\/a>)<\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/amzn.to\/440xV35\" target=\"_blank\" rel=\"noopener\"><strong>Ouvrages sur le Bas-Rhin<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/amzn.to\/440xV35\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96511\" src=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2022\/10\/basrhin2.webp\" alt=\"\" width=\"337\" height=\"480\" srcset=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2022\/10\/basrhin2.webp 337w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2022\/10\/basrhin2-211x300.webp 211w\" sizes=\"auto, (max-width: 337px) 100vw, 337px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Histoire et patrimoine de Gertwiller (Bas-Rhin) https:\/\/www.paysdebarr.fr\/fr\/les-communes\/gertwiller\/commune un site r\u00e9f\u00e9renc\u00e9 sur le nouvel\u00a0Annuaire Historique des Communes de France L&rsquo;existence du village est attest\u00e9e d\u00e8s 718 sous la d\u00e9nomination de GERTENWILRE. A cette \u00e9poque le Duc ETICHON (ou ATTICH) \u00e9tait l&rsquo;un des souverains les plus importants d&rsquo;Alsace. Il fit don \u00e0 sa fille Odile de sa &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-gertwiller-bas-rhin\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":117,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[155,16,8],"tags":[],"class_list":["post-83198","post","type-post","status-publish","format-standard","hentry","category-67-bas-rhin","category-histoire-regionale","category-patrimoine","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire et patrimoine de Gertwiller (Bas-Rhin) - Histoire de France - Communiqu\u00e9s<\/title>\n<meta name=\"description\" content=\"L&#039;existence du village est attest\u00e9e d\u00e8s 718 sous la d\u00e9nomination de GERTENWILRE. A cette \u00e9poque le Duc ETICHON (ou ATTICH)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-gertwiller-bas-rhin\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire et patrimoine de Gertwiller (Bas-Rhin) - Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"og:description\" content=\"L&#039;existence du village est attest\u00e9e d\u00e8s 718 sous la d\u00e9nomination de GERTENWILRE. A cette \u00e9poque le Duc ETICHON (ou ATTICH)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-gertwiller-bas-rhin\/\" \/>\n<meta property=\"og:site_name\" content=\"Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-01T14:14:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-28T09:03:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/09\/gertwiller67-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"administrateur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrateur\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-gertwiller-bas-rhin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-gertwiller-bas-rhin\\\/\"},\"author\":{\"name\":\"administrateur\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\"},\"headline\":\"Histoire et patrimoine de Gertwiller (Bas-Rhin)\",\"datePublished\":\"2021-09-01T14:14:30+00:00\",\"dateModified\":\"2025-03-28T09:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-gertwiller-bas-rhin\\\/\"},\"wordCount\":102,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-gertwiller-bas-rhin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/gertwiller67-300x225.jpg\",\"articleSection\":[\"67 - Bas-Rhin\",\"histoire locale\",\"patrimoine\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-gertwiller-bas-rhin\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-gertwiller-bas-rhin\\\/\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-gertwiller-bas-rhin\\\/\",\"name\":\"Histoire et patrimoine de Gertwiller (Bas-Rhin) - Histoire de France - Communiqu\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-gertwiller-bas-rhin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-gertwiller-bas-rhin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/gertwiller67-300x225.jpg\",\"datePublished\":\"2021-09-01T14:14:30+00:00\",\"dateModified\":\"2025-03-28T09:03:38+00:00\",\"description\":\"L'existence du village est attest\u00e9e d\u00e8s 718 sous la d\u00e9nomination de GERTENWILRE. A cette \u00e9poque le Duc ETICHON (ou ATTICH)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-gertwiller-bas-rhin\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-gertwiller-bas-rhin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-gertwiller-bas-rhin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/gertwiller67-300x225.jpg\",\"contentUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/gertwiller67-300x225.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-gertwiller-bas-rhin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Histoire et patrimoine de Gertwiller (Bas-Rhin)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\",\"name\":\"Histoire de France - Communiqu\u00e9s\",\"description\":\"Histoire et patrimoine\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\",\"name\":\"administrateur\",\"logo\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.charles-de-flahaut.fr\",\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\",\"name\":\"administrateur\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/author\\\/hist_8la_ad\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire et patrimoine de Gertwiller (Bas-Rhin) - Histoire de France - Communiqu\u00e9s","description":"L'existence du village est attest\u00e9e d\u00e8s 718 sous la d\u00e9nomination de GERTENWILRE. A cette \u00e9poque le Duc ETICHON (ou ATTICH)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-gertwiller-bas-rhin\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire et patrimoine de Gertwiller (Bas-Rhin) - Histoire de France - Communiqu\u00e9s","og_description":"L'existence du village est attest\u00e9e d\u00e8s 718 sous la d\u00e9nomination de GERTENWILRE. A cette \u00e9poque le Duc ETICHON (ou ATTICH)","og_url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-gertwiller-bas-rhin\/","og_site_name":"Histoire de France - Communiqu\u00e9s","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_published_time":"2021-09-01T14:14:30+00:00","article_modified_time":"2025-03-28T09:03:38+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/09\/gertwiller67-scaled.jpg","type":"image\/jpeg"}],"author":"administrateur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"administrateur","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-gertwiller-bas-rhin\/#article","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-gertwiller-bas-rhin\/"},"author":{"name":"administrateur","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56"},"headline":"Histoire et patrimoine de Gertwiller (Bas-Rhin)","datePublished":"2021-09-01T14:14:30+00:00","dateModified":"2025-03-28T09:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-gertwiller-bas-rhin\/"},"wordCount":102,"commentCount":0,"publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-gertwiller-bas-rhin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/09\/gertwiller67-300x225.jpg","articleSection":["67 - Bas-Rhin","histoire locale","patrimoine"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-gertwiller-bas-rhin\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-gertwiller-bas-rhin\/","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-gertwiller-bas-rhin\/","name":"Histoire et patrimoine de Gertwiller (Bas-Rhin) - Histoire de France - Communiqu\u00e9s","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-gertwiller-bas-rhin\/#primaryimage"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-gertwiller-bas-rhin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/09\/gertwiller67-300x225.jpg","datePublished":"2021-09-01T14:14:30+00:00","dateModified":"2025-03-28T09:03:38+00:00","description":"L'existence du village est attest\u00e9e d\u00e8s 718 sous la d\u00e9nomination de GERTENWILRE. A cette \u00e9poque le Duc ETICHON (ou ATTICH)","breadcrumb":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-gertwiller-bas-rhin\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-gertwiller-bas-rhin\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-gertwiller-bas-rhin\/#primaryimage","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/09\/gertwiller67-300x225.jpg","contentUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/09\/gertwiller67-300x225.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-gertwiller-bas-rhin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Histoire et patrimoine de Gertwiller (Bas-Rhin)"}]},{"@type":"WebSite","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/","name":"Histoire de France - Communiqu\u00e9s","description":"Histoire et patrimoine","publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9","name":"administrateur","logo":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/www.charles-de-flahaut.fr","https:\/\/www.facebook.com\/Sites.HistoiredeFrance"]},{"@type":"Person","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56","name":"administrateur","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/author\/hist_8la_ad\/"}]}},"views":47,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/83198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=83198"}],"version-history":[{"count":3,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/83198\/revisions"}],"predecessor-version":[{"id":101650,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/83198\/revisions\/101650"}],"wp:attachment":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=83198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=83198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=83198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}