{"id":83094,"date":"2021-08-29T14:59:08","date_gmt":"2021-08-29T13:59:08","guid":{"rendered":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?p=83094"},"modified":"2025-03-29T13:33:23","modified_gmt":"2025-03-29T12:33:23","slug":"histoire-du-hommet-darthenay-manche","status":"publish","type":"post","link":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-du-hommet-darthenay-manche\/","title":{"rendered":"Histoire du Hommet d&rsquo;Arthenay (Manche)"},"content":{"rendered":"<p><strong>Histoire du Hommet d&rsquo;Arthenay (Manche)<\/strong><br \/>\n<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Le_Hommet-d%27Arthenay#Histoire\" target=\"_blank\" rel=\"noopener\">https:\/\/fr.wikipedia.org\/wiki\/Le_Hommet-d%27Arthenay#Histoire<\/a><\/p>\n<p style=\"text-align: justify;\"><em><a href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/08\/lehommetdarthenay50.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-83095\" src=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/08\/lehommetdarthenay50.jpg\" alt=\"\" width=\"280\" height=\"210\" \/><\/a>un site r\u00e9f\u00e9renc\u00e9 sur le nouvel\u00a0<a href=\"http:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\" target=\"_blank\" rel=\"noopener noreferrer\">Annuaire Historique des Communes de France<\/a><\/em><\/p>\n<p style=\"text-align: justify;\">Les recherches effectu\u00e9es jusqu&rsquo;\u00e0 maintenant laissent croire que l&rsquo;origine du Hommet remonte en <a title=\"889\" href=\"https:\/\/fr.wikipedia.org\/wiki\/889\">889<\/a>, apr\u00e8s la prise de <a title=\"Saint-L\u00f4\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Saint-L%C3%B4\">Saint-L\u00f4<\/a> par les Normands. En effet, un des chefs normands se fixa aux environs de la ville de Saint-L\u00f4, dans une r\u00e9gion qu&rsquo;en raison de sa configuration, il d\u00e9nomma \u00ab Le Hommet \u00bb du mot scandinave \u00ab Holm \u00bb, qui signifie entour\u00e9 d&rsquo;eau en partie&#8230;.<\/p>\n<p><em>(source wikipedia&#8230; <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Le_Hommet-d%27Arthenay#Histoire\" target=\"_blank\" rel=\"noopener\">lire la suite<\/a>)<\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/amzn.to\/4j2Mcki\" target=\"_blank\" rel=\"noopener\"><strong>Ouvrages sur la Manche<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/amzn.to\/4j2Mcki\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-100997\" src=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2025\/03\/manche1.jpg\" alt=\"\" width=\"324\" height=\"445\" srcset=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2025\/03\/manche1.jpg 324w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2025\/03\/manche1-218x300.jpg 218w\" sizes=\"auto, (max-width: 324px) 100vw, 324px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Histoire du Hommet d&rsquo;Arthenay (Manche) https:\/\/fr.wikipedia.org\/wiki\/Le_Hommet-d%27Arthenay#Histoire un site r\u00e9f\u00e9renc\u00e9 sur le nouvel\u00a0Annuaire Historique des Communes de France Les recherches effectu\u00e9es jusqu&rsquo;\u00e0 maintenant laissent croire que l&rsquo;origine du Hommet remonte en 889, apr\u00e8s la prise de Saint-L\u00f4 par les Normands. En effet, un des chefs normands se fixa aux environs de la ville de Saint-L\u00f4, dans &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-du-hommet-darthenay-manche\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":117,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[138,16],"tags":[],"class_list":["post-83094","post","type-post","status-publish","format-standard","hentry","category-50-manche","category-histoire-regionale","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire du Hommet d&#039;Arthenay (Manche) - Histoire de France - Communiqu\u00e9s<\/title>\n<meta name=\"description\" content=\"Les recherches effectu\u00e9es jusqu&#039;\u00e0 maintenant laissent croire que l&#039;origine du Hommet remonte en 889, apr\u00e8s la prise de Saint-L\u00f4\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-du-hommet-darthenay-manche\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire du Hommet d&#039;Arthenay (Manche) - Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Les recherches effectu\u00e9es jusqu&#039;\u00e0 maintenant laissent croire que l&#039;origine du Hommet remonte en 889, apr\u00e8s la prise de Saint-L\u00f4\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-du-hommet-darthenay-manche\/\" \/>\n<meta property=\"og:site_name\" content=\"Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-29T13:59:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-29T12:33:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/08\/lehommetdarthenay50.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"280\" \/>\n\t<meta property=\"og:image:height\" content=\"210\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"administrateur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrateur\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-du-hommet-darthenay-manche\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-du-hommet-darthenay-manche\\\/\"},\"author\":{\"name\":\"administrateur\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\"},\"headline\":\"Histoire du Hommet d&rsquo;Arthenay (Manche)\",\"datePublished\":\"2021-08-29T13:59:08+00:00\",\"dateModified\":\"2025-03-29T12:33:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-du-hommet-darthenay-manche\\\/\"},\"wordCount\":109,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-du-hommet-darthenay-manche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/lehommetdarthenay50.jpg\",\"articleSection\":[\"50 - Manche\",\"histoire locale\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-du-hommet-darthenay-manche\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-du-hommet-darthenay-manche\\\/\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-du-hommet-darthenay-manche\\\/\",\"name\":\"Histoire du Hommet d'Arthenay (Manche) - Histoire de France - Communiqu\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-du-hommet-darthenay-manche\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-du-hommet-darthenay-manche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/lehommetdarthenay50.jpg\",\"datePublished\":\"2021-08-29T13:59:08+00:00\",\"dateModified\":\"2025-03-29T12:33:23+00:00\",\"description\":\"Les recherches effectu\u00e9es jusqu'\u00e0 maintenant laissent croire que l'origine du Hommet remonte en 889, apr\u00e8s la prise de Saint-L\u00f4\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-du-hommet-darthenay-manche\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-du-hommet-darthenay-manche\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-du-hommet-darthenay-manche\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/lehommetdarthenay50.jpg\",\"contentUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/lehommetdarthenay50.jpg\",\"width\":280,\"height\":210},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-du-hommet-darthenay-manche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Histoire du Hommet d&rsquo;Arthenay (Manche)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\",\"name\":\"Histoire de France - Communiqu\u00e9s\",\"description\":\"Histoire et patrimoine\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\",\"name\":\"administrateur\",\"logo\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.charles-de-flahaut.fr\",\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\",\"name\":\"administrateur\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/author\\\/hist_8la_ad\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire du Hommet d'Arthenay (Manche) - Histoire de France - Communiqu\u00e9s","description":"Les recherches effectu\u00e9es jusqu'\u00e0 maintenant laissent croire que l'origine du Hommet remonte en 889, apr\u00e8s la prise de Saint-L\u00f4","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-du-hommet-darthenay-manche\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire du Hommet d'Arthenay (Manche) - Histoire de France - Communiqu\u00e9s","og_description":"Les recherches effectu\u00e9es jusqu'\u00e0 maintenant laissent croire que l'origine du Hommet remonte en 889, apr\u00e8s la prise de Saint-L\u00f4","og_url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-du-hommet-darthenay-manche\/","og_site_name":"Histoire de France - Communiqu\u00e9s","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_published_time":"2021-08-29T13:59:08+00:00","article_modified_time":"2025-03-29T12:33:23+00:00","og_image":[{"width":280,"height":210,"url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/08\/lehommetdarthenay50.jpg","type":"image\/jpeg"}],"author":"administrateur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"administrateur","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-du-hommet-darthenay-manche\/#article","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-du-hommet-darthenay-manche\/"},"author":{"name":"administrateur","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56"},"headline":"Histoire du Hommet d&rsquo;Arthenay (Manche)","datePublished":"2021-08-29T13:59:08+00:00","dateModified":"2025-03-29T12:33:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-du-hommet-darthenay-manche\/"},"wordCount":109,"commentCount":0,"publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-du-hommet-darthenay-manche\/#primaryimage"},"thumbnailUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/08\/lehommetdarthenay50.jpg","articleSection":["50 - Manche","histoire locale"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-du-hommet-darthenay-manche\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-du-hommet-darthenay-manche\/","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-du-hommet-darthenay-manche\/","name":"Histoire du Hommet d'Arthenay (Manche) - Histoire de France - Communiqu\u00e9s","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-du-hommet-darthenay-manche\/#primaryimage"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-du-hommet-darthenay-manche\/#primaryimage"},"thumbnailUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/08\/lehommetdarthenay50.jpg","datePublished":"2021-08-29T13:59:08+00:00","dateModified":"2025-03-29T12:33:23+00:00","description":"Les recherches effectu\u00e9es jusqu'\u00e0 maintenant laissent croire que l'origine du Hommet remonte en 889, apr\u00e8s la prise de Saint-L\u00f4","breadcrumb":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-du-hommet-darthenay-manche\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-du-hommet-darthenay-manche\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-du-hommet-darthenay-manche\/#primaryimage","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/08\/lehommetdarthenay50.jpg","contentUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/08\/lehommetdarthenay50.jpg","width":280,"height":210},{"@type":"BreadcrumbList","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-du-hommet-darthenay-manche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Histoire du Hommet d&rsquo;Arthenay (Manche)"}]},{"@type":"WebSite","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/","name":"Histoire de France - Communiqu\u00e9s","description":"Histoire et patrimoine","publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9","name":"administrateur","logo":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/www.charles-de-flahaut.fr","https:\/\/www.facebook.com\/Sites.HistoiredeFrance"]},{"@type":"Person","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56","name":"administrateur","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/author\/hist_8la_ad\/"}]}},"views":137,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/83094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=83094"}],"version-history":[{"count":3,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/83094\/revisions"}],"predecessor-version":[{"id":101731,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/83094\/revisions\/101731"}],"wp:attachment":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=83094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=83094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=83094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}