{"id":82010,"date":"2021-07-24T17:48:00","date_gmt":"2021-07-24T16:48:00","guid":{"rendered":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?p=82010"},"modified":"2025-11-26T17:26:04","modified_gmt":"2025-11-26T16:26:04","slug":"histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire","status":"publish","type":"post","link":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\/","title":{"rendered":"Histoire et patrimoine de Saint-Didier en Brionnais (Sa\u00f4ne-et-Loire)"},"content":{"rendered":"<p><strong>Histoire et patrimoine de Saint-Didier en Brionnais (Sa\u00f4ne-et-Loire)<\/strong><br \/>\n<a href=\"https:\/\/www.saintdidierenbrionnais.fr\/histoire\" target=\"_blank\" rel=\"noopener\">https:\/\/www.saintdidierenbrionnais.fr\/histoire<\/a><\/p>\n<p style=\"text-align: justify;\"><em><a href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/07\/saintdidierenbrionnais71.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-82011\" src=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/07\/saintdidierenbrionnais71.png\" alt=\"\" width=\"246\" height=\"130\" \/><\/a>un site r\u00e9f\u00e9renc\u00e9 sur le nouvel\u00a0<a href=\"http:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\" target=\"_blank\" rel=\"noopener noreferrer\">Annuaire Historique des Communes de France<\/a><\/em><\/p>\n<div id=\"bgLayers_comp-kh15km94\" class=\"X-jRX\" style=\"text-align: justify;\" data-hook=\"bgLayers\">\n<div id=\"bgMedia_comp-kh15km94\" class=\"_1J6n9\"><span class=\"color_12\">Sur le territoire de la commune, la pr\u00e9sence d&rsquo;activit\u00e9 humaine est av\u00e9r\u00e9e \u00e0 l&rsquo;\u00e9poque gallo-romaine. C&rsquo;est attest\u00e9 par la d\u00e9couverte, faite en 1934, par un ancien maire de la commune, Louis Lacroix, d&rsquo;ossements, de tuiles romaines, de poteries anciennes, du col d&rsquo;une amphore en terre cuite blanche. Une partie de ces objets est au mus\u00e9e de la Tour de Marcigny.<\/span>&#8230;<\/div>\n<\/div>\n<div class=\"\" data-mesh-id=\"comp-kh15km94inlineContent\" data-testid=\"inline-content\">\n<div data-mesh-id=\"comp-kh15km94inlineContent-gridContainer\" data-testid=\"mesh-container-content\">\n<div id=\"comp-ki3rdsu1\" class=\"_2bafp\" data-testid=\"richTextElement\">\n<p style=\"text-align: justify;\"><em>(image et extrait du site officiel de la commune&#8230; <a href=\"https:\/\/www.saintdidierenbrionnais.fr\/histoire\" target=\"_blank\" rel=\"noopener\">lire la suite<\/a>)<\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/amzn.to\/3M1A2wY\" target=\"_blank\" rel=\"noopener\"><strong>Ouvrages sur la Sa\u00f4ne-et-Loire<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/amzn.to\/3M1A2wY\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-96095 aligncenter\" src=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2022\/11\/saoneetloire.webp\" alt=\"\" width=\"262\" height=\"262\" srcset=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2022\/11\/saoneetloire.webp 480w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2022\/11\/saoneetloire-300x300.webp 300w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2022\/11\/saoneetloire-150x150.webp 150w\" sizes=\"auto, (max-width: 262px) 100vw, 262px\" \/><\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Histoire et patrimoine de Saint-Didier en Brionnais (Sa\u00f4ne-et-Loire) https:\/\/www.saintdidierenbrionnais.fr\/histoire un site r\u00e9f\u00e9renc\u00e9 sur le nouvel\u00a0Annuaire Historique des Communes de France Sur le territoire de la commune, la pr\u00e9sence d&rsquo;activit\u00e9 humaine est av\u00e9r\u00e9e \u00e0 l&rsquo;\u00e9poque gallo-romaine. C&rsquo;est attest\u00e9 par la d\u00e9couverte, faite en 1934, par un ancien maire de la commune, Louis Lacroix, d&rsquo;ossements, de tuiles &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":117,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[159,16,8],"tags":[],"class_list":["post-82010","post","type-post","status-publish","format-standard","hentry","category-71-saone-et-loire","category-histoire-regionale","category-patrimoine","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire et patrimoine de Saint-Didier en Brionnais (Sa\u00f4ne-et-Loire) - Histoire de France - Communiqu\u00e9s<\/title>\n<meta name=\"description\" content=\"Sur le territoire de la commune, la pr\u00e9sence d&#039;activit\u00e9 humaine est av\u00e9r\u00e9e \u00e0 l&#039;\u00e9poque gallo-romaine. C&#039;est attest\u00e9 par la d\u00e9couverte...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire et patrimoine de Saint-Didier en Brionnais (Sa\u00f4ne-et-Loire) - Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Sur le territoire de la commune, la pr\u00e9sence d&#039;activit\u00e9 humaine est av\u00e9r\u00e9e \u00e0 l&#039;\u00e9poque gallo-romaine. C&#039;est attest\u00e9 par la d\u00e9couverte...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\/\" \/>\n<meta property=\"og:site_name\" content=\"Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-24T16:48:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-26T16:26:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/07\/saintdidierenbrionnais71.png\" \/>\n\t<meta property=\"og:image:width\" content=\"246\" \/>\n\t<meta property=\"og:image:height\" content=\"130\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"administrateur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrateur\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\\\/\"},\"author\":{\"name\":\"administrateur\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\"},\"headline\":\"Histoire et patrimoine de Saint-Didier en Brionnais (Sa\u00f4ne-et-Loire)\",\"datePublished\":\"2021-07-24T16:48:00+00:00\",\"dateModified\":\"2025-11-26T16:26:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\\\/\"},\"wordCount\":122,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/saintdidierenbrionnais71.png\",\"articleSection\":[\"71 - Sa\u00f4ne-et-Loire\",\"histoire locale\",\"patrimoine\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\\\/\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\\\/\",\"name\":\"Histoire et patrimoine de Saint-Didier en Brionnais (Sa\u00f4ne-et-Loire) - Histoire de France - Communiqu\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/saintdidierenbrionnais71.png\",\"datePublished\":\"2021-07-24T16:48:00+00:00\",\"dateModified\":\"2025-11-26T16:26:04+00:00\",\"description\":\"Sur le territoire de la commune, la pr\u00e9sence d'activit\u00e9 humaine est av\u00e9r\u00e9e \u00e0 l'\u00e9poque gallo-romaine. C'est attest\u00e9 par la d\u00e9couverte...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/saintdidierenbrionnais71.png\",\"contentUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/saintdidierenbrionnais71.png\",\"width\":246,\"height\":130},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Histoire et patrimoine de Saint-Didier en Brionnais (Sa\u00f4ne-et-Loire)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\",\"name\":\"Histoire de France - Communiqu\u00e9s\",\"description\":\"Histoire et patrimoine\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\",\"name\":\"administrateur\",\"logo\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.charles-de-flahaut.fr\",\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\",\"name\":\"administrateur\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/author\\\/hist_8la_ad\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire et patrimoine de Saint-Didier en Brionnais (Sa\u00f4ne-et-Loire) - Histoire de France - Communiqu\u00e9s","description":"Sur le territoire de la commune, la pr\u00e9sence d'activit\u00e9 humaine est av\u00e9r\u00e9e \u00e0 l'\u00e9poque gallo-romaine. C'est attest\u00e9 par la d\u00e9couverte...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire et patrimoine de Saint-Didier en Brionnais (Sa\u00f4ne-et-Loire) - Histoire de France - Communiqu\u00e9s","og_description":"Sur le territoire de la commune, la pr\u00e9sence d'activit\u00e9 humaine est av\u00e9r\u00e9e \u00e0 l'\u00e9poque gallo-romaine. C'est attest\u00e9 par la d\u00e9couverte...","og_url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\/","og_site_name":"Histoire de France - Communiqu\u00e9s","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_published_time":"2021-07-24T16:48:00+00:00","article_modified_time":"2025-11-26T16:26:04+00:00","og_image":[{"width":246,"height":130,"url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/07\/saintdidierenbrionnais71.png","type":"image\/png"}],"author":"administrateur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"administrateur","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\/#article","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\/"},"author":{"name":"administrateur","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56"},"headline":"Histoire et patrimoine de Saint-Didier en Brionnais (Sa\u00f4ne-et-Loire)","datePublished":"2021-07-24T16:48:00+00:00","dateModified":"2025-11-26T16:26:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\/"},"wordCount":122,"commentCount":0,"publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/07\/saintdidierenbrionnais71.png","articleSection":["71 - Sa\u00f4ne-et-Loire","histoire locale","patrimoine"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\/","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\/","name":"Histoire et patrimoine de Saint-Didier en Brionnais (Sa\u00f4ne-et-Loire) - Histoire de France - Communiqu\u00e9s","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\/#primaryimage"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/07\/saintdidierenbrionnais71.png","datePublished":"2021-07-24T16:48:00+00:00","dateModified":"2025-11-26T16:26:04+00:00","description":"Sur le territoire de la commune, la pr\u00e9sence d'activit\u00e9 humaine est av\u00e9r\u00e9e \u00e0 l'\u00e9poque gallo-romaine. C'est attest\u00e9 par la d\u00e9couverte...","breadcrumb":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\/#primaryimage","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/07\/saintdidierenbrionnais71.png","contentUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/07\/saintdidierenbrionnais71.png","width":246,"height":130},{"@type":"BreadcrumbList","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-didier-en-brionnais-saone-et-loire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Histoire et patrimoine de Saint-Didier en Brionnais (Sa\u00f4ne-et-Loire)"}]},{"@type":"WebSite","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/","name":"Histoire de France - Communiqu\u00e9s","description":"Histoire et patrimoine","publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9","name":"administrateur","logo":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/www.charles-de-flahaut.fr","https:\/\/www.facebook.com\/Sites.HistoiredeFrance"]},{"@type":"Person","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56","name":"administrateur","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/author\/hist_8la_ad\/"}]}},"views":36,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/82010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=82010"}],"version-history":[{"count":4,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/82010\/revisions"}],"predecessor-version":[{"id":112815,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/82010\/revisions\/112815"}],"wp:attachment":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=82010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=82010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=82010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}