{"id":80688,"date":"2021-04-26T16:41:07","date_gmt":"2021-04-26T15:41:07","guid":{"rendered":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?p=80688"},"modified":"2025-12-12T09:18:55","modified_gmt":"2025-12-12T08:18:55","slug":"histoire-et-patrimoine-de-coarraze-pyrenees-atlantique","status":"publish","type":"post","link":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\/","title":{"rendered":"Histoire et patrimoine de Coarraze (Pyr\u00e9n\u00e9es-Atlantiques)"},"content":{"rendered":"<p><strong>Histoire et patrimoine de Coarraze (Pyr\u00e9n\u00e9es-Atlantiques)<\/strong><br \/>\n<a href=\"https:\/\/coarraze.fr\/histoire\/\" target=\"_blank\" rel=\"noopener\">https:\/\/coarraze.fr\/histoire\/<\/a><\/p>\n<p style=\"text-align: justify;\"><em><a href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/04\/coarraze64.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-80689\" src=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/04\/coarraze64-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/04\/coarraze64.jpg 300w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/04\/coarraze64-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>un site r\u00e9f\u00e9renc\u00e9 sur le nouvel <a href=\"http:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\" target=\"_blank\" rel=\"noopener noreferrer\">Annuaire Historique des Communes de France<\/a><\/em><\/p>\n<p style=\"text-align: justify;\">\u00c0 la fin du Moyen \u00e2ge, Coarraze est un lieu \u00ab d\u00e9fensif \u00bb qui domine le gave \u00e0 l&rsquo;extr\u00e9mit\u00e9 Est du B\u00e9arn. C&rsquo;est un village f\u00e9odal group\u00e9 au pied du promontoire o\u00f9 sera construit le premier ch\u00e2teau vers le 14\u00e8me si\u00e8cle. Contrairement aux bastides voisines &#8211; Nay (1302) &#8211; Montaut (1308) &#8211; Lestelle (1335) &#8211; qui peuvent s&rsquo;administrer elles-m\u00eames car elles ont obtenu des franchises du vicomte de B\u00e9arn, qui esp\u00e8re ainsi contribuer au d\u00e9veloppement \u00e9conomique de la vicomt\u00e9, Coarraze reste sous l&rsquo;autorit\u00e9 du seigneur&#8230;<\/p>\n<p><em>(image et extrait du site officiel de la commune&#8230; <a href=\"https:\/\/coarraze.fr\/histoire\/\" target=\"_blank\" rel=\"noopener\">lire la suite<\/a>)<\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/amzn.to\/4iYLciq\" target=\"_blank\" rel=\"noopener\"><strong>Ouvrages sur Coarraze<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/amzn.to\/4iYLciq\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-113564 aligncenter\" src=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/04\/coarraze.jpg\" alt=\"\" width=\"311\" height=\"466\" srcset=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/04\/coarraze.jpg 311w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/04\/coarraze-200x300.jpg 200w\" sizes=\"auto, (max-width: 311px) 100vw, 311px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Histoire et patrimoine de Coarraze (Pyr\u00e9n\u00e9es-Atlantiques) https:\/\/coarraze.fr\/histoire\/ un site r\u00e9f\u00e9renc\u00e9 sur le nouvel Annuaire Historique des Communes de France \u00c0 la fin du Moyen \u00e2ge, Coarraze est un lieu \u00ab d\u00e9fensif \u00bb qui domine le gave \u00e0 l&rsquo;extr\u00e9mit\u00e9 Est du B\u00e9arn. C&rsquo;est un village f\u00e9odal group\u00e9 au pied du promontoire o\u00f9 sera construit le premier &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":117,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[152,16,8],"tags":[],"class_list":["post-80688","post","type-post","status-publish","format-standard","hentry","category-64-pyrenees-atlantique","category-histoire-regionale","category-patrimoine","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire et patrimoine de Coarraze (Pyr\u00e9n\u00e9es-Atlantiques) - Histoire de France - Communiqu\u00e9s<\/title>\n<meta name=\"description\" content=\"\u00c0 la fin du Moyen \u00e2ge, Coarraze est un lieu \u00ab d\u00e9fensif \u00bb qui domine le gave \u00e0 l&#039;extr\u00e9mit\u00e9 Est du B\u00e9arn. C&#039;est un village f\u00e9odal\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire et patrimoine de Coarraze (Pyr\u00e9n\u00e9es-Atlantiques) - Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"og:description\" content=\"\u00c0 la fin du Moyen \u00e2ge, Coarraze est un lieu \u00ab d\u00e9fensif \u00bb qui domine le gave \u00e0 l&#039;extr\u00e9mit\u00e9 Est du B\u00e9arn. C&#039;est un village f\u00e9odal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\/\" \/>\n<meta property=\"og:site_name\" content=\"Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-26T15:41:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-12T08:18:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/04\/coarraze64.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"administrateur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrateur\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\\\/\"},\"author\":{\"name\":\"administrateur\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\"},\"headline\":\"Histoire et patrimoine de Coarraze (Pyr\u00e9n\u00e9es-Atlantiques)\",\"datePublished\":\"2021-04-26T15:41:07+00:00\",\"dateModified\":\"2025-12-12T08:18:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\\\/\"},\"wordCount\":141,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/coarraze64-300x300.jpg\",\"articleSection\":[\"64 - Pyr\u00e9n\u00e9es-Atlantique\",\"histoire locale\",\"patrimoine\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\\\/\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\\\/\",\"name\":\"Histoire et patrimoine de Coarraze (Pyr\u00e9n\u00e9es-Atlantiques) - Histoire de France - Communiqu\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/coarraze64-300x300.jpg\",\"datePublished\":\"2021-04-26T15:41:07+00:00\",\"dateModified\":\"2025-12-12T08:18:55+00:00\",\"description\":\"\u00c0 la fin du Moyen \u00e2ge, Coarraze est un lieu \u00ab d\u00e9fensif \u00bb qui domine le gave \u00e0 l'extr\u00e9mit\u00e9 Est du B\u00e9arn. C'est un village f\u00e9odal\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/coarraze64.jpg\",\"contentUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/coarraze64.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Histoire et patrimoine de Coarraze (Pyr\u00e9n\u00e9es-Atlantiques)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\",\"name\":\"Histoire de France - Communiqu\u00e9s\",\"description\":\"Histoire et patrimoine\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\",\"name\":\"administrateur\",\"logo\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.charles-de-flahaut.fr\",\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\",\"name\":\"administrateur\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/author\\\/hist_8la_ad\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire et patrimoine de Coarraze (Pyr\u00e9n\u00e9es-Atlantiques) - Histoire de France - Communiqu\u00e9s","description":"\u00c0 la fin du Moyen \u00e2ge, Coarraze est un lieu \u00ab d\u00e9fensif \u00bb qui domine le gave \u00e0 l'extr\u00e9mit\u00e9 Est du B\u00e9arn. C'est un village f\u00e9odal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire et patrimoine de Coarraze (Pyr\u00e9n\u00e9es-Atlantiques) - Histoire de France - Communiqu\u00e9s","og_description":"\u00c0 la fin du Moyen \u00e2ge, Coarraze est un lieu \u00ab d\u00e9fensif \u00bb qui domine le gave \u00e0 l'extr\u00e9mit\u00e9 Est du B\u00e9arn. C'est un village f\u00e9odal","og_url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\/","og_site_name":"Histoire de France - Communiqu\u00e9s","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_published_time":"2021-04-26T15:41:07+00:00","article_modified_time":"2025-12-12T08:18:55+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/04\/coarraze64.jpg","type":"image\/jpeg"}],"author":"administrateur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"administrateur","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\/#article","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\/"},"author":{"name":"administrateur","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56"},"headline":"Histoire et patrimoine de Coarraze (Pyr\u00e9n\u00e9es-Atlantiques)","datePublished":"2021-04-26T15:41:07+00:00","dateModified":"2025-12-12T08:18:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\/"},"wordCount":141,"commentCount":0,"publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/04\/coarraze64-300x300.jpg","articleSection":["64 - Pyr\u00e9n\u00e9es-Atlantique","histoire locale","patrimoine"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\/","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\/","name":"Histoire et patrimoine de Coarraze (Pyr\u00e9n\u00e9es-Atlantiques) - Histoire de France - Communiqu\u00e9s","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\/#primaryimage"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/04\/coarraze64-300x300.jpg","datePublished":"2021-04-26T15:41:07+00:00","dateModified":"2025-12-12T08:18:55+00:00","description":"\u00c0 la fin du Moyen \u00e2ge, Coarraze est un lieu \u00ab d\u00e9fensif \u00bb qui domine le gave \u00e0 l'extr\u00e9mit\u00e9 Est du B\u00e9arn. C'est un village f\u00e9odal","breadcrumb":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\/#primaryimage","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/04\/coarraze64.jpg","contentUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/04\/coarraze64.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-coarraze-pyrenees-atlantique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Histoire et patrimoine de Coarraze (Pyr\u00e9n\u00e9es-Atlantiques)"}]},{"@type":"WebSite","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/","name":"Histoire de France - Communiqu\u00e9s","description":"Histoire et patrimoine","publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9","name":"administrateur","logo":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/www.charles-de-flahaut.fr","https:\/\/www.facebook.com\/Sites.HistoiredeFrance"]},{"@type":"Person","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56","name":"administrateur","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/author\/hist_8la_ad\/"}]}},"views":39,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/80688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=80688"}],"version-history":[{"count":4,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/80688\/revisions"}],"predecessor-version":[{"id":113566,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/80688\/revisions\/113566"}],"wp:attachment":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=80688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=80688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=80688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}