{"id":79557,"date":"2021-01-19T18:09:43","date_gmt":"2021-01-19T17:09:43","guid":{"rendered":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?p=79557"},"modified":"2025-12-21T13:45:26","modified_gmt":"2025-12-21T12:45:26","slug":"histoire-de-couffe-loire-atlantique","status":"publish","type":"post","link":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-couffe-loire-atlantique\/","title":{"rendered":"Histoire de Couff\u00e9 (Loire-Atlantique)"},"content":{"rendered":"<p><strong>Histoire de Couff\u00e9 (Loire-Atlantique)<\/strong><br \/>\n<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Couff%C3%A9#Histoire\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/fr.wikipedia.org\/wiki\/Couff%C3%A9#Histoire<\/a><\/p>\n<p style=\"text-align: justify;\"><em><a href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/01\/couffe44.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-79558\" src=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/01\/couffe44-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/01\/couffe44-200x300.jpg 200w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/01\/couffe44.jpg 280w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>un site r\u00e9f\u00e9renc\u00e9 sur le nouvel\u00a0\u00a0<a href=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\" target=\"_blank\" rel=\"noopener noreferrer\">Annuaire Historique des Communes de France<\/a><\/em><\/p>\n<p style=\"text-align: justify;\">Durant l\u2019Antiquit\u00e9 , une voie romaine reliant Nantes \u00e0 Angers passait par Couff\u00e9\u00a0: \u00ab\u00a0elle servait probablement de limite entre Couff\u00e9 et Oudon.\u00a0\u00bb Et d\u2019ailleurs, au <abbr class=\"abbr\" title=\"18\u1d49 si\u00e8cle\"><span class=\"romain\">XVIII<\/span><sup>e<\/sup><\/abbr>\u00a0si\u00e8cle, un berger \u00e0 d\u00e9couvert dans un terrier, six jarres et une poterie qui contenaient quelques pi\u00e8ces de monnaie en argent et en bronze datant du <abbr class=\"abbr\" title=\"3\u1d49 si\u00e8cle\"><span class=\"romain\">III<\/span><sup>e<\/sup><\/abbr> si\u00e8cle&#8230;<\/p>\n<p><em>(source wikipedia&#8230; <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Couff%C3%A9#Histoire\" target=\"_blank\" rel=\"noopener noreferrer\">lire la suite<\/a>)<\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/amzn.to\/4p29WaJ\" target=\"_blank\" rel=\"noopener\"><strong>Ouvrages sur la Loire-Atlantique<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/amzn.to\/4p29WaJ\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-103323 aligncenter\" src=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2025\/04\/loireatlantique3.jpg\" alt=\"\" width=\"320\" height=\"445\" srcset=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2025\/04\/loireatlantique3.jpg 320w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2025\/04\/loireatlantique3-216x300.jpg 216w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Histoire de Couff\u00e9 (Loire-Atlantique) https:\/\/fr.wikipedia.org\/wiki\/Couff%C3%A9#Histoire un site r\u00e9f\u00e9renc\u00e9 sur le nouvel\u00a0\u00a0Annuaire Historique des Communes de France Durant l\u2019Antiquit\u00e9 , une voie romaine reliant Nantes \u00e0 Angers passait par Couff\u00e9\u00a0: \u00ab\u00a0elle servait probablement de limite entre Couff\u00e9 et Oudon.\u00a0\u00bb Et d\u2019ailleurs, au XVIIIe\u00a0si\u00e8cle, un berger \u00e0 d\u00e9couvert dans un terrier, six jarres et une poterie qui &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-couffe-loire-atlantique\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":117,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[132,16],"tags":[],"class_list":["post-79557","post","type-post","status-publish","format-standard","hentry","category-44-loire-atlantique","category-histoire-regionale","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire de Couff\u00e9 (Loire-Atlantique) - Histoire de France - Communiqu\u00e9s<\/title>\n<meta name=\"description\" content=\"Durant l\u2019Antiquit\u00e9 , une voie romaine reliant Nantes \u00e0 Angers passait par Couff\u00e9\u00a0: \u00ab\u00a0elle servait probablement de limite entre...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-couffe-loire-atlantique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire de Couff\u00e9 (Loire-Atlantique) - Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Durant l\u2019Antiquit\u00e9 , une voie romaine reliant Nantes \u00e0 Angers passait par Couff\u00e9\u00a0: \u00ab\u00a0elle servait probablement de limite entre...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-couffe-loire-atlantique\/\" \/>\n<meta property=\"og:site_name\" content=\"Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-19T17:09:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-21T12:45:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/01\/couffe44.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"280\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"administrateur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrateur\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-couffe-loire-atlantique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-couffe-loire-atlantique\\\/\"},\"author\":{\"name\":\"administrateur\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\"},\"headline\":\"Histoire de Couff\u00e9 (Loire-Atlantique)\",\"datePublished\":\"2021-01-19T17:09:43+00:00\",\"dateModified\":\"2025-12-21T12:45:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-couffe-loire-atlantique\\\/\"},\"wordCount\":99,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-couffe-loire-atlantique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/couffe44-200x300.jpg\",\"articleSection\":[\"44 - Loire Atlantique\",\"histoire locale\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-couffe-loire-atlantique\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-couffe-loire-atlantique\\\/\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-couffe-loire-atlantique\\\/\",\"name\":\"Histoire de Couff\u00e9 (Loire-Atlantique) - Histoire de France - Communiqu\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-couffe-loire-atlantique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-couffe-loire-atlantique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/couffe44-200x300.jpg\",\"datePublished\":\"2021-01-19T17:09:43+00:00\",\"dateModified\":\"2025-12-21T12:45:26+00:00\",\"description\":\"Durant l\u2019Antiquit\u00e9 , une voie romaine reliant Nantes \u00e0 Angers passait par Couff\u00e9\u00a0: \u00ab\u00a0elle servait probablement de limite entre...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-couffe-loire-atlantique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-couffe-loire-atlantique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-couffe-loire-atlantique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/couffe44.jpg\",\"contentUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/couffe44.jpg\",\"width\":280,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-couffe-loire-atlantique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Histoire de Couff\u00e9 (Loire-Atlantique)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\",\"name\":\"Histoire de France - Communiqu\u00e9s\",\"description\":\"Histoire et patrimoine\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\",\"name\":\"administrateur\",\"logo\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.charles-de-flahaut.fr\",\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\",\"name\":\"administrateur\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/author\\\/hist_8la_ad\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire de Couff\u00e9 (Loire-Atlantique) - Histoire de France - Communiqu\u00e9s","description":"Durant l\u2019Antiquit\u00e9 , une voie romaine reliant Nantes \u00e0 Angers passait par Couff\u00e9\u00a0: \u00ab\u00a0elle servait probablement de limite entre...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-couffe-loire-atlantique\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire de Couff\u00e9 (Loire-Atlantique) - Histoire de France - Communiqu\u00e9s","og_description":"Durant l\u2019Antiquit\u00e9 , une voie romaine reliant Nantes \u00e0 Angers passait par Couff\u00e9\u00a0: \u00ab\u00a0elle servait probablement de limite entre...","og_url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-couffe-loire-atlantique\/","og_site_name":"Histoire de France - Communiqu\u00e9s","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_published_time":"2021-01-19T17:09:43+00:00","article_modified_time":"2025-12-21T12:45:26+00:00","og_image":[{"width":280,"height":420,"url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/01\/couffe44.jpg","type":"image\/jpeg"}],"author":"administrateur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"administrateur","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-couffe-loire-atlantique\/#article","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-couffe-loire-atlantique\/"},"author":{"name":"administrateur","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56"},"headline":"Histoire de Couff\u00e9 (Loire-Atlantique)","datePublished":"2021-01-19T17:09:43+00:00","dateModified":"2025-12-21T12:45:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-couffe-loire-atlantique\/"},"wordCount":99,"commentCount":0,"publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-couffe-loire-atlantique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/01\/couffe44-200x300.jpg","articleSection":["44 - Loire Atlantique","histoire locale"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-couffe-loire-atlantique\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-couffe-loire-atlantique\/","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-couffe-loire-atlantique\/","name":"Histoire de Couff\u00e9 (Loire-Atlantique) - Histoire de France - Communiqu\u00e9s","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-couffe-loire-atlantique\/#primaryimage"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-couffe-loire-atlantique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/01\/couffe44-200x300.jpg","datePublished":"2021-01-19T17:09:43+00:00","dateModified":"2025-12-21T12:45:26+00:00","description":"Durant l\u2019Antiquit\u00e9 , une voie romaine reliant Nantes \u00e0 Angers passait par Couff\u00e9\u00a0: \u00ab\u00a0elle servait probablement de limite entre...","breadcrumb":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-couffe-loire-atlantique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-couffe-loire-atlantique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-couffe-loire-atlantique\/#primaryimage","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/01\/couffe44.jpg","contentUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/01\/couffe44.jpg","width":280,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-couffe-loire-atlantique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Histoire de Couff\u00e9 (Loire-Atlantique)"}]},{"@type":"WebSite","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/","name":"Histoire de France - Communiqu\u00e9s","description":"Histoire et patrimoine","publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9","name":"administrateur","logo":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/www.charles-de-flahaut.fr","https:\/\/www.facebook.com\/Sites.HistoiredeFrance"]},{"@type":"Person","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56","name":"administrateur","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/author\/hist_8la_ad\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/79557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=79557"}],"version-history":[{"count":3,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/79557\/revisions"}],"predecessor-version":[{"id":114196,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/79557\/revisions\/114196"}],"wp:attachment":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=79557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=79557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=79557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}