{"id":7928,"date":"2014-09-02T08:33:22","date_gmt":"2014-09-02T07:33:22","guid":{"rendered":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/?p=7928"},"modified":"2015-05-27T14:01:18","modified_gmt":"2015-05-27T13:01:18","slug":"histoire-et-patrimoine-de-villemarechal-seine-et-marne","status":"publish","type":"post","link":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\/","title":{"rendered":"Histoire et patrimoine de Villemar\u00e9chal (Seine-et-Marne)"},"content":{"rendered":"<p><strong>Histoire et patrimoine de Villemar\u00e9chal (Seine-et-Marne)<\/strong><br \/>\n<a href=\"http:\/\/www.villemarechal.fr\/fr\/information\/49919\/histoire\" target=\"_blank\">http:\/\/www.villemarechal.fr\/fr\/information\/49919\/histoire<\/a><\/p>\n<p><em>un nouveau site r\u00e9f\u00e9renc\u00e9 sur <a href=\"http:\/\/www.histoire-communes.jpflahaut.fr\/\" target=\"_blank\">Histoire et patrimoine des villes et villages de France<\/a><\/em><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2014\/09\/villemarechal.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-7929\" src=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2014\/09\/villemarechal.jpg\" alt=\"villemarechal\" width=\"245\" height=\"197\" \/><\/a>Le site est occup\u00e9 depuis tr\u00e8s longtemps, comme le montre cette hache datant du n\u00e9olithique et trouv\u00e9e non loin de la Chapelle Saint Vulfrand, pr\u00e8s de la Fontaine ou les polissoirs que l\u2019on peut voir dans la commune ou les communes voisines. Mais bien avant d\u00e9j\u00e0, les Magdal\u00e9niens circulaient sur le territoire&#8230;<\/p>\n<p><em>(image et extrait du site web officiel de la commune &#8230; <a href=\"http:\/\/cities.reseaudescommunes.fr\/cities\/532\/documents\/lm57tbt1k4ud77y.pdf\" target=\"_blank\">lire la suite<\/a>)<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>A lire \u00e9galement<\/strong> : <a href=\"http:\/\/www.villemarechal.fr\/fr\/information\/6273\/patrimoine\" target=\"_blank\">le patrimoine de Villemar\u00e9chal<\/a><\/p>\n<p><iframe loading=\"lazy\" style=\"width: 120px; height: 240px;\" src=\"\/\/ws-eu.amazon-adsystem.com\/widgets\/q?ServiceVersion=20070822&amp;OneJS=1&amp;Operation=GetAdHtml&amp;MarketPlace=FR&amp;source=ac&amp;ref=tf_til&amp;ad_type=product_link&amp;tracking_id=charledeflaha-21&amp;marketplace=amazon&amp;region=FR&amp;placement=B0014NDW8Y&amp;asins=B0014NDW8Y&amp;linkId=JHJCVZMOZHT4X7DU&amp;show_border=true&amp;link_opens_in_new_window=true\" width=\"300\" height=\"150\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><br \/>\n<\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Histoire et patrimoine de Villemar\u00e9chal (Seine-et-Marne) http:\/\/www.villemarechal.fr\/fr\/information\/49919\/histoire un nouveau site r\u00e9f\u00e9renc\u00e9 sur Histoire et patrimoine des villes et villages de France Le site est occup\u00e9 depuis tr\u00e8s longtemps, comme le montre cette hache datant du n\u00e9olithique et trouv\u00e9e non loin de la Chapelle Saint Vulfrand, pr\u00e8s de la Fontaine ou les polissoirs que l\u2019on peut &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":117,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[164,16,8],"tags":[],"class_list":["post-7928","post","type-post","status-publish","format-standard","hentry","category-77-seine-et-marne","category-histoire-regionale","category-patrimoine","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire et patrimoine de Villemar\u00e9chal (Seine-et-Marne) - Histoire de France - Communiqu\u00e9s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire et patrimoine de Villemar\u00e9chal (Seine-et-Marne) - Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Histoire et patrimoine de Villemar\u00e9chal (Seine-et-Marne) http:\/\/www.villemarechal.fr\/fr\/information\/49919\/histoire un nouveau site r\u00e9f\u00e9renc\u00e9 sur Histoire et patrimoine des villes et villages de France Le site est occup\u00e9 depuis tr\u00e8s longtemps, comme le montre cette hache datant du n\u00e9olithique et trouv\u00e9e non loin de la Chapelle Saint Vulfrand, pr\u00e8s de la Fontaine ou les polissoirs que l\u2019on peut &hellip; Lire la suite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\/\" \/>\n<meta property=\"og:site_name\" content=\"Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-02T07:33:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-05-27T13:01:18+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2014\/09\/villemarechal.jpg\" \/>\n<meta name=\"author\" content=\"administrateur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrateur\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\\\/\"},\"author\":{\"name\":\"administrateur\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\"},\"headline\":\"Histoire et patrimoine de Villemar\u00e9chal (Seine-et-Marne)\",\"datePublished\":\"2014-09-02T07:33:22+00:00\",\"dateModified\":\"2015-05-27T13:01:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\\\/\"},\"wordCount\":117,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/villemarechal.jpg\",\"articleSection\":[\"77 - Seine-et-Marne\",\"histoire locale\",\"patrimoine\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\\\/\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\\\/\",\"name\":\"Histoire et patrimoine de Villemar\u00e9chal (Seine-et-Marne) - Histoire de France - Communiqu\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/villemarechal.jpg\",\"datePublished\":\"2014-09-02T07:33:22+00:00\",\"dateModified\":\"2015-05-27T13:01:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/villemarechal.jpg\",\"contentUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/villemarechal.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Histoire et patrimoine de Villemar\u00e9chal (Seine-et-Marne)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\",\"name\":\"Histoire de France - Communiqu\u00e9s\",\"description\":\"Histoire et patrimoine\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\",\"name\":\"administrateur\",\"logo\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.charles-de-flahaut.fr\",\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\",\"name\":\"administrateur\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/author\\\/hist_8la_ad\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire et patrimoine de Villemar\u00e9chal (Seine-et-Marne) - Histoire de France - Communiqu\u00e9s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire et patrimoine de Villemar\u00e9chal (Seine-et-Marne) - Histoire de France - Communiqu\u00e9s","og_description":"Histoire et patrimoine de Villemar\u00e9chal (Seine-et-Marne) http:\/\/www.villemarechal.fr\/fr\/information\/49919\/histoire un nouveau site r\u00e9f\u00e9renc\u00e9 sur Histoire et patrimoine des villes et villages de France Le site est occup\u00e9 depuis tr\u00e8s longtemps, comme le montre cette hache datant du n\u00e9olithique et trouv\u00e9e non loin de la Chapelle Saint Vulfrand, pr\u00e8s de la Fontaine ou les polissoirs que l\u2019on peut &hellip; Lire la suite","og_url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\/","og_site_name":"Histoire de France - Communiqu\u00e9s","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_published_time":"2014-09-02T07:33:22+00:00","article_modified_time":"2015-05-27T13:01:18+00:00","og_image":[{"url":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2014\/09\/villemarechal.jpg","type":"","width":"","height":""}],"author":"administrateur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"administrateur","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\/#article","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\/"},"author":{"name":"administrateur","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56"},"headline":"Histoire et patrimoine de Villemar\u00e9chal (Seine-et-Marne)","datePublished":"2014-09-02T07:33:22+00:00","dateModified":"2015-05-27T13:01:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\/"},"wordCount":117,"commentCount":0,"publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\/#primaryimage"},"thumbnailUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2014\/09\/villemarechal.jpg","articleSection":["77 - Seine-et-Marne","histoire locale","patrimoine"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\/","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\/","name":"Histoire et patrimoine de Villemar\u00e9chal (Seine-et-Marne) - Histoire de France - Communiqu\u00e9s","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\/#primaryimage"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\/#primaryimage"},"thumbnailUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2014\/09\/villemarechal.jpg","datePublished":"2014-09-02T07:33:22+00:00","dateModified":"2015-05-27T13:01:18+00:00","breadcrumb":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\/#primaryimage","url":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2014\/09\/villemarechal.jpg","contentUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2014\/09\/villemarechal.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-villemarechal-seine-et-marne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Histoire et patrimoine de Villemar\u00e9chal (Seine-et-Marne)"}]},{"@type":"WebSite","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/","name":"Histoire de France - Communiqu\u00e9s","description":"Histoire et patrimoine","publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9","name":"administrateur","logo":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/www.charles-de-flahaut.fr","https:\/\/www.facebook.com\/Sites.HistoiredeFrance"]},{"@type":"Person","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56","name":"administrateur","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/author\/hist_8la_ad\/"}]}},"views":461,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/7928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=7928"}],"version-history":[{"count":4,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/7928\/revisions"}],"predecessor-version":[{"id":13235,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/7928\/revisions\/13235"}],"wp:attachment":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=7928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=7928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=7928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}