{"id":79177,"date":"2021-01-08T08:59:11","date_gmt":"2021-01-08T07:59:11","guid":{"rendered":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?p=79177"},"modified":"2025-12-23T21:51:26","modified_gmt":"2025-12-23T20:51:26","slug":"d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne","status":"publish","type":"post","link":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\/","title":{"rendered":"D.R.E.B. D\u00e9couvrir ou Red\u00e9couvrir Ensemble \u00e0 Boudou (Tarn et Garonne)"},"content":{"rendered":"<p><strong>D.R.E.B. D\u00e9couvrir ou Red\u00e9couvrir Ensemble \u00e0 Boudou (Tarn et Garonne)<\/strong><br \/>\n<a href=\"http:\/\/dreb.eklablog.com\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/dreb.eklablog.com<\/a><\/p>\n<p style=\"text-align: justify;\"><em><a href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/01\/boudou82.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-79179\" src=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/01\/boudou82-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" srcset=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/01\/boudou82-300x199.jpg 300w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/01\/boudou82-768x509.jpg 768w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/01\/boudou82-703x465.jpg 703w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/01\/boudou82.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>un blog r\u00e9f\u00e9renc\u00e9 sur le nouvel\u00a0 <a href=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\" target=\"_blank\" rel=\"noopener noreferrer\">Annuaire Historique des Communes de France<\/a><\/em><\/p>\n<p style=\"text-align: justify;\">Le but est de visiter un par un, tous les villages du Tarn et Garonne. (Y a du boulot !! 195 communes\u00a0<a href=\"http:\/\/dreb.eklablog.com\/les-195-communes-du-tarn-et-garonne-p1397714\" target=\"_blank\" rel=\"noopener noreferrer\">\u00ab\u00a0cliquer ICI\u00a0\u00bb)<\/a> sur une apr\u00e8s midi ou sur une journ\u00e9e, une ou deux fois par mois. En commen\u00e7ant par les plus petits, les moins connus, les moins cit\u00e9s dans les brochures touristiques, ceux o\u00f9 on ne pense pas \u00e0 s\u2019arr\u00eater&#8230;<\/p>\n<p><em>(image et extrait du blog&#8230; <a href=\"http:\/\/dreb.eklablog.com\" target=\"_blank\" rel=\"noopener noreferrer\">lire la suite<\/a>)<\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/amzn.to\/48THaEA\" target=\"_blank\" rel=\"noopener\"><strong>Ouvrages sur le Tarn-et-Garonne<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/amzn.to\/48THaEA\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-103758 aligncenter\" src=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2025\/04\/tarnetgaronne1.jpg\" alt=\"\" width=\"336\" height=\"445\" srcset=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2025\/04\/tarnetgaronne1.jpg 336w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2025\/04\/tarnetgaronne1-227x300.jpg 227w\" sizes=\"auto, (max-width: 336px) 100vw, 336px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>D.R.E.B. D\u00e9couvrir ou Red\u00e9couvrir Ensemble \u00e0 Boudou (Tarn et Garonne) http:\/\/dreb.eklablog.com un blog r\u00e9f\u00e9renc\u00e9 sur le nouvel\u00a0 Annuaire Historique des Communes de France Le but est de visiter un par un, tous les villages du Tarn et Garonne. (Y a du boulot !! 195 communes\u00a0\u00ab\u00a0cliquer ICI\u00a0\u00bb) sur une apr\u00e8s midi ou sur une journ\u00e9e, une &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":117,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[170,16,8],"tags":[],"class_list":["post-79177","post","type-post","status-publish","format-standard","hentry","category-82-tarn-et-garonne","category-histoire-regionale","category-patrimoine","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D.R.E.B. D\u00e9couvrir ou Red\u00e9couvrir Ensemble \u00e0 Boudou (Tarn et Garonne) - Histoire de France - Communiqu\u00e9s<\/title>\n<meta name=\"description\" content=\"Le but est de visiter un par un, tous les villages du Tarn et Garonne. sur une apr\u00e8s midi ou sur une journ\u00e9e, une ou deux fois par mois.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D.R.E.B. D\u00e9couvrir ou Red\u00e9couvrir Ensemble \u00e0 Boudou (Tarn et Garonne) - Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Le but est de visiter un par un, tous les villages du Tarn et Garonne. sur une apr\u00e8s midi ou sur une journ\u00e9e, une ou deux fois par mois.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\/\" \/>\n<meta property=\"og:site_name\" content=\"Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-08T07:59:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-23T20:51:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/01\/boudou82.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"678\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"administrateur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrateur\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\\\/\"},\"author\":{\"name\":\"administrateur\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\"},\"headline\":\"D.R.E.B. D\u00e9couvrir ou Red\u00e9couvrir Ensemble \u00e0 Boudou (Tarn et Garonne)\",\"datePublished\":\"2021-01-08T07:59:11+00:00\",\"dateModified\":\"2025-12-23T20:51:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\\\/\"},\"wordCount\":123,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/boudou82-300x199.jpg\",\"articleSection\":[\"82 - Tarn-et-Garonne\",\"histoire locale\",\"patrimoine\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\\\/\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\\\/\",\"name\":\"D.R.E.B. D\u00e9couvrir ou Red\u00e9couvrir Ensemble \u00e0 Boudou (Tarn et Garonne) - Histoire de France - Communiqu\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/boudou82-300x199.jpg\",\"datePublished\":\"2021-01-08T07:59:11+00:00\",\"dateModified\":\"2025-12-23T20:51:26+00:00\",\"description\":\"Le but est de visiter un par un, tous les villages du Tarn et Garonne. sur une apr\u00e8s midi ou sur une journ\u00e9e, une ou deux fois par mois.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/boudou82.jpg\",\"contentUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/boudou82.jpg\",\"width\":1024,\"height\":678},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D.R.E.B. D\u00e9couvrir ou Red\u00e9couvrir Ensemble \u00e0 Boudou (Tarn et Garonne)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\",\"name\":\"Histoire de France - Communiqu\u00e9s\",\"description\":\"Histoire et patrimoine\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\",\"name\":\"administrateur\",\"logo\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.charles-de-flahaut.fr\",\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\",\"name\":\"administrateur\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/author\\\/hist_8la_ad\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D.R.E.B. D\u00e9couvrir ou Red\u00e9couvrir Ensemble \u00e0 Boudou (Tarn et Garonne) - Histoire de France - Communiqu\u00e9s","description":"Le but est de visiter un par un, tous les villages du Tarn et Garonne. sur une apr\u00e8s midi ou sur une journ\u00e9e, une ou deux fois par mois.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\/","og_locale":"fr_FR","og_type":"article","og_title":"D.R.E.B. D\u00e9couvrir ou Red\u00e9couvrir Ensemble \u00e0 Boudou (Tarn et Garonne) - Histoire de France - Communiqu\u00e9s","og_description":"Le but est de visiter un par un, tous les villages du Tarn et Garonne. sur une apr\u00e8s midi ou sur une journ\u00e9e, une ou deux fois par mois.","og_url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\/","og_site_name":"Histoire de France - Communiqu\u00e9s","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_published_time":"2021-01-08T07:59:11+00:00","article_modified_time":"2025-12-23T20:51:26+00:00","og_image":[{"width":1024,"height":678,"url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/01\/boudou82.jpg","type":"image\/jpeg"}],"author":"administrateur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"administrateur","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\/#article","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\/"},"author":{"name":"administrateur","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56"},"headline":"D.R.E.B. D\u00e9couvrir ou Red\u00e9couvrir Ensemble \u00e0 Boudou (Tarn et Garonne)","datePublished":"2021-01-08T07:59:11+00:00","dateModified":"2025-12-23T20:51:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\/"},"wordCount":123,"commentCount":0,"publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/01\/boudou82-300x199.jpg","articleSection":["82 - Tarn-et-Garonne","histoire locale","patrimoine"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\/","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\/","name":"D.R.E.B. D\u00e9couvrir ou Red\u00e9couvrir Ensemble \u00e0 Boudou (Tarn et Garonne) - Histoire de France - Communiqu\u00e9s","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\/#primaryimage"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/01\/boudou82-300x199.jpg","datePublished":"2021-01-08T07:59:11+00:00","dateModified":"2025-12-23T20:51:26+00:00","description":"Le but est de visiter un par un, tous les villages du Tarn et Garonne. sur une apr\u00e8s midi ou sur une journ\u00e9e, une ou deux fois par mois.","breadcrumb":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\/#primaryimage","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/01\/boudou82.jpg","contentUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2021\/01\/boudou82.jpg","width":1024,"height":678},{"@type":"BreadcrumbList","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/d-r-e-b-decouvrir-ou-redecouvrir-ensemble-a-boudou-tarn-et-garonne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/"},{"@type":"ListItem","position":2,"name":"D.R.E.B. D\u00e9couvrir ou Red\u00e9couvrir Ensemble \u00e0 Boudou (Tarn et Garonne)"}]},{"@type":"WebSite","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/","name":"Histoire de France - Communiqu\u00e9s","description":"Histoire et patrimoine","publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9","name":"administrateur","logo":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/www.charles-de-flahaut.fr","https:\/\/www.facebook.com\/Sites.HistoiredeFrance"]},{"@type":"Person","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56","name":"administrateur","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/author\/hist_8la_ad\/"}]}},"views":79,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/79177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=79177"}],"version-history":[{"count":3,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/79177\/revisions"}],"predecessor-version":[{"id":114396,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/79177\/revisions\/114396"}],"wp:attachment":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=79177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=79177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=79177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}