{"id":75044,"date":"2020-05-27T20:31:56","date_gmt":"2020-05-27T19:31:56","guid":{"rendered":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?p=75044"},"modified":"2026-03-27T09:38:57","modified_gmt":"2026-03-27T08:38:57","slug":"histoire-et-patrimoine-de-valleiry-haute-savoie","status":"publish","type":"post","link":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-valleiry-haute-savoie\/","title":{"rendered":"Histoire et patrimoine de Valleiry (Haute-Savoie)"},"content":{"rendered":"<p><strong>Histoire et patrimoine de Valleiry (Haute-Savoie)<\/strong><br \/>\n<a href=\"http:\/\/www.valleiry.fr\/La-Ville\/La-commune\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/www.valleiry.fr\/La-Ville\/La-commune<\/a><\/p>\n<p style=\"text-align: justify;\"><em><a href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2020\/05\/valleiry74.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-75045\" src=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2020\/05\/valleiry74-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2020\/05\/valleiry74-300x200.jpg 300w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2020\/05\/valleiry74-768x512.jpg 768w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2020\/05\/valleiry74.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>un site r\u00e9f\u00e9renc\u00e9 sur le nouvel\u00a0\u00a0<a href=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\" target=\"_blank\" rel=\"noopener noreferrer\">Annuaire Historique des Communes de France<\/a><\/em><\/p>\n<p style=\"text-align: justify;\">Valleiry doit probablement son nom \u00e0 Vallerius Ca\u00efus, fils de Titus, tribun militaire romain de la seconde l\u00e9gion qui avait \u00e9difi\u00e9 une villa romaine dans la r\u00e9gion.<br \/>\nLes romains de l\u2019\u00e9poque apport\u00e8rent le culte de Jupiter (JO VIS) et le hameau de la Joux aurait \u00e9t\u00e9 \u00e0 l\u2019origine construit aux abords d\u2019un temple qui lui aurait \u00e9t\u00e9 d\u00e9di\u00e9&#8230;<\/p>\n<p><em>(image et extrait du site officiel de la commune&#8230; <a href=\"http:\/\/www.valleiry.fr\/La-Ville\/La-commune\" target=\"_blank\" rel=\"noopener noreferrer\">lire la suite<\/a>)<\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/amzn.to\/48drPxE\" target=\"_blank\" rel=\"noopener\"><strong>Ouvrages sur Valleiry<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/amzn.to\/48drPxE\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-116666 aligncenter\" src=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2020\/05\/valleiry.jpg\" alt=\"\" width=\"307\" height=\"425\" srcset=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2020\/05\/valleiry.jpg 307w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2020\/05\/valleiry-217x300.jpg 217w\" sizes=\"auto, (max-width: 307px) 100vw, 307px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/amzn.to\/42EepbA\" target=\"_blank\" rel=\"noopener\"><strong>Ouvrages sur la Savoie<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/amzn.to\/42EepbA\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-102953\" src=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2025\/04\/savoie1.jpg\" alt=\"\" width=\"328\" height=\"445\" srcset=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2025\/04\/savoie1.jpg 328w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2025\/04\/savoie1-221x300.jpg 221w\" sizes=\"auto, (max-width: 328px) 100vw, 328px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Histoire et patrimoine de Valleiry (Haute-Savoie) http:\/\/www.valleiry.fr\/La-Ville\/La-commune un site r\u00e9f\u00e9renc\u00e9 sur le nouvel\u00a0\u00a0Annuaire Historique des Communes de France Valleiry doit probablement son nom \u00e0 Vallerius Ca\u00efus, fils de Titus, tribun militaire romain de la seconde l\u00e9gion qui avait \u00e9difi\u00e9 une villa romaine dans la r\u00e9gion. Les romains de l\u2019\u00e9poque apport\u00e8rent le culte de Jupiter (JO &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-valleiry-haute-savoie\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":117,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[161,16,8],"tags":[],"class_list":["post-75044","post","type-post","status-publish","format-standard","hentry","category-73-savoie","category-histoire-regionale","category-patrimoine","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire et patrimoine de Valleiry (Haute-Savoie) - Histoire de France - Communiqu\u00e9s<\/title>\n<meta name=\"description\" content=\"Valleiry doit probablement son nom \u00e0 Vallerius Ca\u00efus, fils de Titus, tribun militaire romain de la seconde l\u00e9gion\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-valleiry-haute-savoie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire et patrimoine de Valleiry (Haute-Savoie) - Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Valleiry doit probablement son nom \u00e0 Vallerius Ca\u00efus, fils de Titus, tribun militaire romain de la seconde l\u00e9gion\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-valleiry-haute-savoie\/\" \/>\n<meta property=\"og:site_name\" content=\"Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-27T19:31:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-27T08:38:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2020\/05\/valleiry74.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"administrateur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrateur\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-valleiry-haute-savoie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-valleiry-haute-savoie\\\/\"},\"author\":{\"name\":\"administrateur\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\"},\"headline\":\"Histoire et patrimoine de Valleiry (Haute-Savoie)\",\"datePublished\":\"2020-05-27T19:31:56+00:00\",\"dateModified\":\"2026-03-27T08:38:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-valleiry-haute-savoie\\\/\"},\"wordCount\":115,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-valleiry-haute-savoie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/valleiry74-300x200.jpg\",\"articleSection\":[\"73 - Savoie\",\"histoire locale\",\"patrimoine\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-valleiry-haute-savoie\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-valleiry-haute-savoie\\\/\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-valleiry-haute-savoie\\\/\",\"name\":\"Histoire et patrimoine de Valleiry (Haute-Savoie) - Histoire de France - Communiqu\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-valleiry-haute-savoie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-valleiry-haute-savoie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/valleiry74-300x200.jpg\",\"datePublished\":\"2020-05-27T19:31:56+00:00\",\"dateModified\":\"2026-03-27T08:38:57+00:00\",\"description\":\"Valleiry doit probablement son nom \u00e0 Vallerius Ca\u00efus, fils de Titus, tribun militaire romain de la seconde l\u00e9gion\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-valleiry-haute-savoie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-valleiry-haute-savoie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-valleiry-haute-savoie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/valleiry74.jpg\",\"contentUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/valleiry74.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-valleiry-haute-savoie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Histoire et patrimoine de Valleiry (Haute-Savoie)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\",\"name\":\"Histoire de France - Communiqu\u00e9s\",\"description\":\"Histoire et patrimoine\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\",\"name\":\"administrateur\",\"logo\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.charles-de-flahaut.fr\",\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\",\"name\":\"administrateur\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/author\\\/hist_8la_ad\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire et patrimoine de Valleiry (Haute-Savoie) - Histoire de France - Communiqu\u00e9s","description":"Valleiry doit probablement son nom \u00e0 Vallerius Ca\u00efus, fils de Titus, tribun militaire romain de la seconde l\u00e9gion","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-valleiry-haute-savoie\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire et patrimoine de Valleiry (Haute-Savoie) - Histoire de France - Communiqu\u00e9s","og_description":"Valleiry doit probablement son nom \u00e0 Vallerius Ca\u00efus, fils de Titus, tribun militaire romain de la seconde l\u00e9gion","og_url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-valleiry-haute-savoie\/","og_site_name":"Histoire de France - Communiqu\u00e9s","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_published_time":"2020-05-27T19:31:56+00:00","article_modified_time":"2026-03-27T08:38:57+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2020\/05\/valleiry74.jpg","type":"image\/jpeg"}],"author":"administrateur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"administrateur","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-valleiry-haute-savoie\/#article","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-valleiry-haute-savoie\/"},"author":{"name":"administrateur","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56"},"headline":"Histoire et patrimoine de Valleiry (Haute-Savoie)","datePublished":"2020-05-27T19:31:56+00:00","dateModified":"2026-03-27T08:38:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-valleiry-haute-savoie\/"},"wordCount":115,"commentCount":0,"publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-valleiry-haute-savoie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2020\/05\/valleiry74-300x200.jpg","articleSection":["73 - Savoie","histoire locale","patrimoine"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-valleiry-haute-savoie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-valleiry-haute-savoie\/","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-valleiry-haute-savoie\/","name":"Histoire et patrimoine de Valleiry (Haute-Savoie) - Histoire de France - Communiqu\u00e9s","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-valleiry-haute-savoie\/#primaryimage"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-valleiry-haute-savoie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2020\/05\/valleiry74-300x200.jpg","datePublished":"2020-05-27T19:31:56+00:00","dateModified":"2026-03-27T08:38:57+00:00","description":"Valleiry doit probablement son nom \u00e0 Vallerius Ca\u00efus, fils de Titus, tribun militaire romain de la seconde l\u00e9gion","breadcrumb":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-valleiry-haute-savoie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-valleiry-haute-savoie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-valleiry-haute-savoie\/#primaryimage","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2020\/05\/valleiry74.jpg","contentUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2020\/05\/valleiry74.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-valleiry-haute-savoie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Histoire et patrimoine de Valleiry (Haute-Savoie)"}]},{"@type":"WebSite","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/","name":"Histoire de France - Communiqu\u00e9s","description":"Histoire et patrimoine","publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9","name":"administrateur","logo":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/www.charles-de-flahaut.fr","https:\/\/www.facebook.com\/Sites.HistoiredeFrance"]},{"@type":"Person","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56","name":"administrateur","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/author\/hist_8la_ad\/"}]}},"views":191,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/75044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=75044"}],"version-history":[{"count":4,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/75044\/revisions"}],"predecessor-version":[{"id":116667,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/75044\/revisions\/116667"}],"wp:attachment":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=75044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=75044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=75044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}