{"id":62166,"date":"2018-11-28T10:36:08","date_gmt":"2018-11-28T09:36:08","guid":{"rendered":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?p=62166"},"modified":"2018-11-28T10:36:08","modified_gmt":"2018-11-28T09:36:08","slug":"histoire-et-patrimoine-de-saint-jean-des-bois-orne","status":"publish","type":"post","link":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\/","title":{"rendered":"Histoire et patrimoine de Saint Jean des Bois (Orne)"},"content":{"rendered":"<p><strong>Histoire et patrimoine de Saint Jean des Bois (Orne)<\/strong><br \/>\n<a href=\"http:\/\/www.saint-jean-des-bois.fr\/fr\/patrimoine\" target=\"_blank\" rel=\"noopener\">http:\/\/www.saint-jean-des-bois.fr\/fr\/patrimoine<\/a><\/p>\n<p style=\"text-align: justify;\"><em><a href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2018\/11\/saintjeandesbois61.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-62167\" src=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2018\/11\/saintjeandesbois61-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2018\/11\/saintjeandesbois61-300x225.jpg 300w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2018\/11\/saintjeandesbois61.jpg 750w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>un site r\u00e9f\u00e9renc\u00e9 sur le nouvel\u00a0\u00a0<a href=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\" target=\"_blank\" rel=\"noopener noreferrer\">Annuaire Historique des Communes de France<\/a><\/em><\/p>\n<p style=\"text-align: justify;\">L&rsquo;\u00e9glise Saint-Jean-Baptiste\u00a0datant du XIX\u00e8 si\u00e8cle. historique (cette recherche a \u00e9t\u00e9 faite par Gerard VILLEROY ,dans le cadre de l&rsquo;association dont il est pr\u00e9sident d&rsquo;honneur)<br \/>\nManoir de la Guyonni\u00e8re&#8230;<\/p>\n<p><em>(image et extrait du site officiel de la commune&#8230; <a href=\"http:\/\/www.saint-jean-des-bois.fr\/fr\/patrimoine\" target=\"_blank\" rel=\"noopener\">lire la suite<\/a>)<\/em><\/p>\n<p><iframe style=\"width: 120px; height: 240px;\" src=\"\/\/ws-eu.amazon-adsystem.com\/widgets\/q?ServiceVersion=20070822&amp;OneJS=1&amp;Operation=GetAdHtml&amp;MarketPlace=FR&amp;source=ac&amp;ref=tf_til&amp;ad_type=product_link&amp;tracking_id=charledeflaha-21&amp;marketplace=amazon&amp;region=FR&amp;placement=2915907951&amp;asins=2915907951&amp;linkId=G4UYU6CQ2XYR7HX3&amp;show_border=true&amp;link_opens_in_new_window=true\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><br \/>\n<\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Histoire et patrimoine de Saint Jean des Bois (Orne) http:\/\/www.saint-jean-des-bois.fr\/fr\/patrimoine un site r\u00e9f\u00e9renc\u00e9 sur le nouvel\u00a0\u00a0Annuaire Historique des Communes de France L&rsquo;\u00e9glise Saint-Jean-Baptiste\u00a0datant du XIX\u00e8 si\u00e8cle. historique (cette recherche a \u00e9t\u00e9 faite par Gerard VILLEROY ,dans le cadre de l&rsquo;association dont il est pr\u00e9sident d&rsquo;honneur) Manoir de la Guyonni\u00e8re&#8230; (image et extrait du site officiel &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":117,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[149,16,8],"tags":[],"class_list":["post-62166","post","type-post","status-publish","format-standard","hentry","category-61-orne","category-histoire-regionale","category-patrimoine","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire et patrimoine de Saint Jean des Bois (Orne) - Histoire de France - Communiqu\u00e9s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire et patrimoine de Saint Jean des Bois (Orne) - Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Histoire et patrimoine de Saint Jean des Bois (Orne) http:\/\/www.saint-jean-des-bois.fr\/fr\/patrimoine un site r\u00e9f\u00e9renc\u00e9 sur le nouvel\u00a0\u00a0Annuaire Historique des Communes de France L&rsquo;\u00e9glise Saint-Jean-Baptiste\u00a0datant du XIX\u00e8 si\u00e8cle. historique (cette recherche a \u00e9t\u00e9 faite par Gerard VILLEROY ,dans le cadre de l&rsquo;association dont il est pr\u00e9sident d&rsquo;honneur) Manoir de la Guyonni\u00e8re&#8230; (image et extrait du site officiel &hellip; Lire la suite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\/\" \/>\n<meta property=\"og:site_name\" content=\"Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-28T09:36:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2018\/11\/saintjeandesbois61-300x225.jpg\" \/>\n<meta name=\"author\" content=\"administrateur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrateur\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\\\/\"},\"author\":{\"name\":\"administrateur\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\"},\"headline\":\"Histoire et patrimoine de Saint Jean des Bois (Orne)\",\"datePublished\":\"2018-11-28T09:36:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\\\/\"},\"wordCount\":85,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/saintjeandesbois61-300x225.jpg\",\"articleSection\":[\"61 - Orne\",\"histoire locale\",\"patrimoine\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\\\/\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\\\/\",\"name\":\"Histoire et patrimoine de Saint Jean des Bois (Orne) - Histoire de France - Communiqu\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/saintjeandesbois61-300x225.jpg\",\"datePublished\":\"2018-11-28T09:36:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/saintjeandesbois61.jpg\",\"contentUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/saintjeandesbois61.jpg\",\"width\":750,\"height\":562},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Histoire et patrimoine de Saint Jean des Bois (Orne)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\",\"name\":\"Histoire de France - Communiqu\u00e9s\",\"description\":\"Histoire et patrimoine\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\",\"name\":\"administrateur\",\"logo\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.charles-de-flahaut.fr\",\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\",\"name\":\"administrateur\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/author\\\/hist_8la_ad\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire et patrimoine de Saint Jean des Bois (Orne) - Histoire de France - Communiqu\u00e9s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire et patrimoine de Saint Jean des Bois (Orne) - Histoire de France - Communiqu\u00e9s","og_description":"Histoire et patrimoine de Saint Jean des Bois (Orne) http:\/\/www.saint-jean-des-bois.fr\/fr\/patrimoine un site r\u00e9f\u00e9renc\u00e9 sur le nouvel\u00a0\u00a0Annuaire Historique des Communes de France L&rsquo;\u00e9glise Saint-Jean-Baptiste\u00a0datant du XIX\u00e8 si\u00e8cle. historique (cette recherche a \u00e9t\u00e9 faite par Gerard VILLEROY ,dans le cadre de l&rsquo;association dont il est pr\u00e9sident d&rsquo;honneur) Manoir de la Guyonni\u00e8re&#8230; (image et extrait du site officiel &hellip; Lire la suite","og_url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\/","og_site_name":"Histoire de France - Communiqu\u00e9s","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_published_time":"2018-11-28T09:36:08+00:00","og_image":[{"url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2018\/11\/saintjeandesbois61-300x225.jpg","type":"","width":"","height":""}],"author":"administrateur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"administrateur"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\/#article","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\/"},"author":{"name":"administrateur","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56"},"headline":"Histoire et patrimoine de Saint Jean des Bois (Orne)","datePublished":"2018-11-28T09:36:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\/"},"wordCount":85,"commentCount":0,"publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2018\/11\/saintjeandesbois61-300x225.jpg","articleSection":["61 - Orne","histoire locale","patrimoine"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\/","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\/","name":"Histoire et patrimoine de Saint Jean des Bois (Orne) - Histoire de France - Communiqu\u00e9s","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\/#primaryimage"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2018\/11\/saintjeandesbois61-300x225.jpg","datePublished":"2018-11-28T09:36:08+00:00","breadcrumb":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\/#primaryimage","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2018\/11\/saintjeandesbois61.jpg","contentUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2018\/11\/saintjeandesbois61.jpg","width":750,"height":562},{"@type":"BreadcrumbList","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saint-jean-des-bois-orne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Histoire et patrimoine de Saint Jean des Bois (Orne)"}]},{"@type":"WebSite","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/","name":"Histoire de France - Communiqu\u00e9s","description":"Histoire et patrimoine","publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9","name":"administrateur","logo":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/www.charles-de-flahaut.fr","https:\/\/www.facebook.com\/Sites.HistoiredeFrance"]},{"@type":"Person","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56","name":"administrateur","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/author\/hist_8la_ad\/"}]}},"views":87,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/62166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=62166"}],"version-history":[{"count":1,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/62166\/revisions"}],"predecessor-version":[{"id":62168,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/62166\/revisions\/62168"}],"wp:attachment":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=62166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=62166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=62166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}