{"id":62078,"date":"2018-11-25T17:44:57","date_gmt":"2018-11-25T16:44:57","guid":{"rendered":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?p=62078"},"modified":"2018-11-25T17:44:57","modified_gmt":"2018-11-25T16:44:57","slug":"histoire-de-neuvy-marne","status":"publish","type":"post","link":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-neuvy-marne\/","title":{"rendered":"Histoire de Neuvy (Marne)"},"content":{"rendered":"<p><strong>Histoire de Neuvy (Marne)<\/strong><br \/>\n<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Neuvy_(Marne)#Histoire\" target=\"_blank\" rel=\"noopener\">https:\/\/fr.wikipedia.org\/wiki\/Neuvy_(Marne)#Histoire<\/a><\/p>\n<p style=\"text-align: justify;\"><em><a href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2018\/11\/neuvy51.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-62079\" src=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2018\/11\/neuvy51.jpg\" alt=\"\" width=\"280\" height=\"179\" \/><\/a>un site r\u00e9f\u00e9renc\u00e9 sur le nouvel\u00a0\u00a0<a href=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\" target=\"_blank\" rel=\"noopener noreferrer\">Annuaire Historique des Communes de France<\/a><\/em><\/p>\n<p style=\"text-align: justify;\">Trois maisons fortes existaient sur le territoire de la commune. S&rsquo;il ne subsiste que quelques ruines de celle de Condry ; celle des Pr\u00e9s poss\u00e8de encore des tours. La maison forte de Nogentel (dite \u00ab Ch\u00e2teau de Nogentel \u00bb), datant du xiiie si\u00e8cle, a \u00e9t\u00e9 restaur\u00e9e au cours du xixe si\u00e8cle&#8230;<\/p>\n<p style=\"text-align: justify;\"><em>(source wikipedia&#8230; <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Neuvy_(Marne)#Histoire\" target=\"_blank\" rel=\"noopener\">lire la suite<\/a>)<\/em><\/p>\n<p><iframe style=\"width: 120px; height: 240px;\" src=\"\/\/ws-eu.amazon-adsystem.com\/widgets\/q?ServiceVersion=20070822&amp;OneJS=1&amp;Operation=GetAdHtml&amp;MarketPlace=FR&amp;source=ac&amp;ref=tf_til&amp;ad_type=product_link&amp;tracking_id=charledeflaha-21&amp;marketplace=amazon&amp;region=FR&amp;placement=2843784670&amp;asins=2843784670&amp;linkId=RQJKSWKVURYGKRQS&amp;show_border=true&amp;link_opens_in_new_window=true\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><br \/>\n<\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Histoire de Neuvy (Marne) https:\/\/fr.wikipedia.org\/wiki\/Neuvy_(Marne)#Histoire un site r\u00e9f\u00e9renc\u00e9 sur le nouvel\u00a0\u00a0Annuaire Historique des Communes de France Trois maisons fortes existaient sur le territoire de la commune. S&rsquo;il ne subsiste que quelques ruines de celle de Condry ; celle des Pr\u00e9s poss\u00e8de encore des tours. La maison forte de Nogentel (dite \u00ab Ch\u00e2teau de Nogentel \u00bb), &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-neuvy-marne\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":117,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[139,16],"tags":[],"class_list":["post-62078","post","type-post","status-publish","format-standard","hentry","category-51-marne","category-histoire-regionale","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire de Neuvy (Marne) - Histoire de France - Communiqu\u00e9s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-neuvy-marne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire de Neuvy (Marne) - Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Histoire de Neuvy (Marne) https:\/\/fr.wikipedia.org\/wiki\/Neuvy_(Marne)#Histoire un site r\u00e9f\u00e9renc\u00e9 sur le nouvel\u00a0\u00a0Annuaire Historique des Communes de France Trois maisons fortes existaient sur le territoire de la commune. S&rsquo;il ne subsiste que quelques ruines de celle de Condry ; celle des Pr\u00e9s poss\u00e8de encore des tours. La maison forte de Nogentel (dite \u00ab Ch\u00e2teau de Nogentel \u00bb), &hellip; Lire la suite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-neuvy-marne\/\" \/>\n<meta property=\"og:site_name\" content=\"Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-25T16:44:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2018\/11\/neuvy51.jpg\" \/>\n<meta name=\"author\" content=\"administrateur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrateur\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-neuvy-marne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-neuvy-marne\\\/\"},\"author\":{\"name\":\"administrateur\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\"},\"headline\":\"Histoire de Neuvy (Marne)\",\"datePublished\":\"2018-11-25T16:44:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-neuvy-marne\\\/\"},\"wordCount\":90,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-neuvy-marne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/neuvy51.jpg\",\"articleSection\":[\"51 - Marne\",\"histoire locale\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-neuvy-marne\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-neuvy-marne\\\/\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-neuvy-marne\\\/\",\"name\":\"Histoire de Neuvy (Marne) - Histoire de France - Communiqu\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-neuvy-marne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-neuvy-marne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/neuvy51.jpg\",\"datePublished\":\"2018-11-25T16:44:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-neuvy-marne\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-neuvy-marne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-neuvy-marne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/neuvy51.jpg\",\"contentUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/neuvy51.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-neuvy-marne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Histoire de Neuvy (Marne)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\",\"name\":\"Histoire de France - Communiqu\u00e9s\",\"description\":\"Histoire et patrimoine\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\",\"name\":\"administrateur\",\"logo\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.charles-de-flahaut.fr\",\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\",\"name\":\"administrateur\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/author\\\/hist_8la_ad\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire de Neuvy (Marne) - Histoire de France - Communiqu\u00e9s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-neuvy-marne\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire de Neuvy (Marne) - Histoire de France - Communiqu\u00e9s","og_description":"Histoire de Neuvy (Marne) https:\/\/fr.wikipedia.org\/wiki\/Neuvy_(Marne)#Histoire un site r\u00e9f\u00e9renc\u00e9 sur le nouvel\u00a0\u00a0Annuaire Historique des Communes de France Trois maisons fortes existaient sur le territoire de la commune. S&rsquo;il ne subsiste que quelques ruines de celle de Condry ; celle des Pr\u00e9s poss\u00e8de encore des tours. La maison forte de Nogentel (dite \u00ab Ch\u00e2teau de Nogentel \u00bb), &hellip; Lire la suite","og_url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-neuvy-marne\/","og_site_name":"Histoire de France - Communiqu\u00e9s","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_published_time":"2018-11-25T16:44:57+00:00","og_image":[{"url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2018\/11\/neuvy51.jpg","type":"","width":"","height":""}],"author":"administrateur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"administrateur"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-neuvy-marne\/#article","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-neuvy-marne\/"},"author":{"name":"administrateur","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56"},"headline":"Histoire de Neuvy (Marne)","datePublished":"2018-11-25T16:44:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-neuvy-marne\/"},"wordCount":90,"commentCount":0,"publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-neuvy-marne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2018\/11\/neuvy51.jpg","articleSection":["51 - Marne","histoire locale"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-neuvy-marne\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-neuvy-marne\/","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-neuvy-marne\/","name":"Histoire de Neuvy (Marne) - Histoire de France - Communiqu\u00e9s","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-neuvy-marne\/#primaryimage"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-neuvy-marne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2018\/11\/neuvy51.jpg","datePublished":"2018-11-25T16:44:57+00:00","breadcrumb":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-neuvy-marne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-neuvy-marne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-neuvy-marne\/#primaryimage","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2018\/11\/neuvy51.jpg","contentUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2018\/11\/neuvy51.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-neuvy-marne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Histoire de Neuvy (Marne)"}]},{"@type":"WebSite","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/","name":"Histoire de France - Communiqu\u00e9s","description":"Histoire et patrimoine","publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9","name":"administrateur","logo":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/www.charles-de-flahaut.fr","https:\/\/www.facebook.com\/Sites.HistoiredeFrance"]},{"@type":"Person","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56","name":"administrateur","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/author\/hist_8la_ad\/"}]}},"views":112,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/62078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=62078"}],"version-history":[{"count":1,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/62078\/revisions"}],"predecessor-version":[{"id":62080,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/62078\/revisions\/62080"}],"wp:attachment":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=62078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=62078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=62078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}