{"id":58064,"date":"2018-03-30T12:39:42","date_gmt":"2018-03-30T11:39:42","guid":{"rendered":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/?p=58064"},"modified":"2018-03-30T12:39:42","modified_gmt":"2018-03-30T11:39:42","slug":"histoire-et-patrimoine-de-port-brillet-mayenne","status":"publish","type":"post","link":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-port-brillet-mayenne\/","title":{"rendered":"Histoire et patrimoine de Port-Brillet (Mayenne)"},"content":{"rendered":"<p><strong>Histoire et patrimoine de Port-Brillet (Mayenne)<\/strong><br \/>\n<a href=\"http:\/\/www.port-brillet.fr\/index.php?page=affichpage&amp;num=1\" target=\"_blank\" rel=\"noopener\">http:\/\/www.port-brillet.fr\/index.php?page=affichpage&amp;num=1<\/a><\/p>\n<p style=\"text-align: justify;\"><em><a href=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2018\/03\/portbrillet53.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-58065\" src=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2018\/03\/portbrillet53.jpeg\" alt=\"\" width=\"200\" height=\"277\" \/><\/a>un site r\u00e9f\u00e9renc\u00e9 sur le nouvel\u00a0\u00a0<a href=\"http:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\" target=\"_blank\" rel=\"noopener noreferrer\">Annuaire Historique des Communes de France<\/a><\/em><\/p>\n<div style=\"text-align: justify;\"><strong>La l\u00e9gende<\/strong><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.port-brillet.fr\/docs\/upload\/images\/image1939.jpeg\" alt=\"\" width=\"200\" height=\"277\" \/><\/div>\n<div style=\"text-align: justify;\">Un jour, Guy IV de Laval, chassait dans la for\u00eat et faillit perdre la vie. Dans ce moment critique, il fit v\u0153u \u00e0 sainte Marie-Madeleine d&rsquo;\u00e9riger une chapelle s&rsquo;il \u00e9chappait au danger, ce qu\u2019il fit. C\u2019\u00e9tait en l\u2019an 1100. Aujourd\u2019hui une r\u00e9plique de cette chapelle existe sur la commune&#8230;<\/div>\n<div style=\"text-align: justify;\"><em>(image et extrait du site officiel de la commune&#8230; <a href=\"http:\/\/www.port-brillet.fr\/index.php?page=affichpage&amp;num=1\" target=\"_blank\" rel=\"noopener\">lire la suite<\/a>)<\/em><\/div>\n<p><iframe loading=\"lazy\" style=\"width: 120px; height: 240px;\" src=\"\/\/ws-eu.amazon-adsystem.com\/widgets\/q?ServiceVersion=20070822&amp;OneJS=1&amp;Operation=GetAdHtml&amp;MarketPlace=FR&amp;source=ac&amp;ref=tf_til&amp;ad_type=product_link&amp;tracking_id=charledeflaha-21&amp;marketplace=amazon&amp;region=FR&amp;placement=2903504172&amp;asins=2903504172&amp;linkId=TNF3CYCFTDZ4EZQN&amp;show_border=true&amp;link_opens_in_new_window=true\" width=\"300\" height=\"150\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><br \/>\n<\/iframe><iframe loading=\"lazy\" style=\"width: 120px; height: 240px;\" src=\"\/\/ws-eu.amazon-adsystem.com\/widgets\/q?ServiceVersion=20070822&amp;OneJS=1&amp;Operation=GetAdHtml&amp;MarketPlace=FR&amp;source=ac&amp;ref=tf_til&amp;ad_type=product_link&amp;tracking_id=charledeflaha-21&amp;marketplace=amazon&amp;region=FR&amp;placement=2915907641&amp;asins=2915907641&amp;linkId=NN7VOSLPJFF544JE&amp;show_border=true&amp;link_opens_in_new_window=true\" width=\"300\" height=\"150\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><br \/>\n<\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Histoire et patrimoine de Port-Brillet (Mayenne) http:\/\/www.port-brillet.fr\/index.php?page=affichpage&amp;num=1 un site r\u00e9f\u00e9renc\u00e9 sur le nouvel\u00a0\u00a0Annuaire Historique des Communes de France La l\u00e9gende Un jour, Guy IV de Laval, chassait dans la for\u00eat et faillit perdre la vie. Dans ce moment critique, il fit v\u0153u \u00e0 sainte Marie-Madeleine d&rsquo;\u00e9riger une chapelle s&rsquo;il \u00e9chappait au danger, ce qu\u2019il fit. &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-port-brillet-mayenne\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":117,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[141,16,8],"tags":[],"class_list":["post-58064","post","type-post","status-publish","format-standard","hentry","category-53-mayenne","category-histoire-regionale","category-patrimoine","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire et patrimoine de Port-Brillet (Mayenne) - Histoire de France - Communiqu\u00e9s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-port-brillet-mayenne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire et patrimoine de Port-Brillet (Mayenne) - Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Histoire et patrimoine de Port-Brillet (Mayenne) http:\/\/www.port-brillet.fr\/index.php?page=affichpage&amp;num=1 un site r\u00e9f\u00e9renc\u00e9 sur le nouvel\u00a0\u00a0Annuaire Historique des Communes de France La l\u00e9gende Un jour, Guy IV de Laval, chassait dans la for\u00eat et faillit perdre la vie. Dans ce moment critique, il fit v\u0153u \u00e0 sainte Marie-Madeleine d&rsquo;\u00e9riger une chapelle s&rsquo;il \u00e9chappait au danger, ce qu\u2019il fit. &hellip; Lire la suite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-port-brillet-mayenne\/\" \/>\n<meta property=\"og:site_name\" content=\"Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-30T11:39:42+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2018\/03\/portbrillet53.jpeg\" \/>\n<meta name=\"author\" content=\"administrateur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrateur\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-port-brillet-mayenne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-port-brillet-mayenne\\\/\"},\"author\":{\"name\":\"administrateur\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\"},\"headline\":\"Histoire et patrimoine de Port-Brillet (Mayenne)\",\"datePublished\":\"2018-03-30T11:39:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-port-brillet-mayenne\\\/\"},\"wordCount\":107,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-port-brillet-mayenne\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/portbrillet53.jpeg\",\"articleSection\":[\"53 - Mayenne\",\"histoire locale\",\"patrimoine\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-port-brillet-mayenne\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-port-brillet-mayenne\\\/\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-port-brillet-mayenne\\\/\",\"name\":\"Histoire et patrimoine de Port-Brillet (Mayenne) - Histoire de France - Communiqu\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-port-brillet-mayenne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-port-brillet-mayenne\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/portbrillet53.jpeg\",\"datePublished\":\"2018-03-30T11:39:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-port-brillet-mayenne\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-port-brillet-mayenne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-port-brillet-mayenne\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/portbrillet53.jpeg\",\"contentUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/portbrillet53.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-port-brillet-mayenne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Histoire et patrimoine de Port-Brillet (Mayenne)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\",\"name\":\"Histoire de France - Communiqu\u00e9s\",\"description\":\"Histoire et patrimoine\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\",\"name\":\"administrateur\",\"logo\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.charles-de-flahaut.fr\",\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\",\"name\":\"administrateur\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/author\\\/hist_8la_ad\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire et patrimoine de Port-Brillet (Mayenne) - Histoire de France - Communiqu\u00e9s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-port-brillet-mayenne\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire et patrimoine de Port-Brillet (Mayenne) - Histoire de France - Communiqu\u00e9s","og_description":"Histoire et patrimoine de Port-Brillet (Mayenne) http:\/\/www.port-brillet.fr\/index.php?page=affichpage&amp;num=1 un site r\u00e9f\u00e9renc\u00e9 sur le nouvel\u00a0\u00a0Annuaire Historique des Communes de France La l\u00e9gende Un jour, Guy IV de Laval, chassait dans la for\u00eat et faillit perdre la vie. Dans ce moment critique, il fit v\u0153u \u00e0 sainte Marie-Madeleine d&rsquo;\u00e9riger une chapelle s&rsquo;il \u00e9chappait au danger, ce qu\u2019il fit. &hellip; Lire la suite","og_url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-port-brillet-mayenne\/","og_site_name":"Histoire de France - Communiqu\u00e9s","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_published_time":"2018-03-30T11:39:42+00:00","og_image":[{"url":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2018\/03\/portbrillet53.jpeg","type":"","width":"","height":""}],"author":"administrateur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"administrateur","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-port-brillet-mayenne\/#article","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-port-brillet-mayenne\/"},"author":{"name":"administrateur","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56"},"headline":"Histoire et patrimoine de Port-Brillet (Mayenne)","datePublished":"2018-03-30T11:39:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-port-brillet-mayenne\/"},"wordCount":107,"commentCount":0,"publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-port-brillet-mayenne\/#primaryimage"},"thumbnailUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2018\/03\/portbrillet53.jpeg","articleSection":["53 - Mayenne","histoire locale","patrimoine"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-port-brillet-mayenne\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-port-brillet-mayenne\/","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-port-brillet-mayenne\/","name":"Histoire et patrimoine de Port-Brillet (Mayenne) - Histoire de France - Communiqu\u00e9s","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-port-brillet-mayenne\/#primaryimage"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-port-brillet-mayenne\/#primaryimage"},"thumbnailUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2018\/03\/portbrillet53.jpeg","datePublished":"2018-03-30T11:39:42+00:00","breadcrumb":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-port-brillet-mayenne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-port-brillet-mayenne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-port-brillet-mayenne\/#primaryimage","url":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2018\/03\/portbrillet53.jpeg","contentUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2018\/03\/portbrillet53.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-port-brillet-mayenne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Histoire et patrimoine de Port-Brillet (Mayenne)"}]},{"@type":"WebSite","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/","name":"Histoire de France - Communiqu\u00e9s","description":"Histoire et patrimoine","publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9","name":"administrateur","logo":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/www.charles-de-flahaut.fr","https:\/\/www.facebook.com\/Sites.HistoiredeFrance"]},{"@type":"Person","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56","name":"administrateur","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/author\/hist_8la_ad\/"}]}},"views":116,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/58064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=58064"}],"version-history":[{"count":1,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/58064\/revisions"}],"predecessor-version":[{"id":58066,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/58064\/revisions\/58066"}],"wp:attachment":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=58064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=58064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=58064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}