{"id":5445,"date":"2014-01-28T17:40:47","date_gmt":"2014-01-28T16:40:47","guid":{"rendered":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/?p=5445"},"modified":"2015-06-03T20:18:57","modified_gmt":"2015-06-03T19:18:57","slug":"histoire-et-patrimoine-de-fromereville-les-vallons-meuse","status":"publish","type":"post","link":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\/","title":{"rendered":"Histoire et patrimoine de Fromer\u00e9ville Les Vallons (Meuse)"},"content":{"rendered":"<p>Un nouveau site r\u00e9f\u00e9renc\u00e9 sur <a href=\"http:\/\/www.histoire-communes.jpflahaut.fr\/\" target=\"_blank\">Annuaire Histoire<\/a> :<\/p>\n<p><strong>Histoire et patrimoine de Fromer\u00e9ville Les Vallons (Meuse)<\/strong><br \/>\n<a href=\"http:\/\/fromereville-les-vallons.fr\/fr\/information\/31653\/historique\" target=\"_blank\">http:\/\/fromereville-les-vallons.fr\/fr\/information\/31653\/historique<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2014\/01\/fromereville.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-5446\" src=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2014\/01\/fromereville-300x202.jpg\" alt=\"fromereville\" width=\"300\" height=\"202\" srcset=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2014\/01\/fromereville-300x202.jpg 300w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2014\/01\/fromereville.jpg 380w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Le nom \u00ab\u00a0Fromer\u00e9ville\u00a0\u00bb est \u00e9tymologiquement compos\u00e9 du mot latin \u00ab\u00a0villa\u00a0\u00bb (domaine) et de l&rsquo;anthroponyme germanique \u00ab\u00a0Frumar\u00a0\u00bb.<\/p>\n<p>La voie romaine d&rsquo;ordre inf\u00e9rieur de Verdun \u00e0 Romagne-sous-Montfaucon prend naissance au sud du territoire de Fromer\u00e9ville, qu&rsquo;elle traverse.<\/p>\n<p><em>(image et extrait du site officiel de la commune &#8230; <a href=\"http:\/\/fromereville-les-vallons.fr\/fr\/information\/31653\/historique\" target=\"_blank\">lire la suite<\/a>)<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Quelques pages sur le patrimoine :<\/strong><\/p>\n<ul>\n<li><a title=\"Photos d'antan\" href=\"http:\/\/fromereville-les-vallons.fr\/fr\/information\/31312\/photos-antan\">Photos d&rsquo;antan<\/a><\/li>\n<li><a title=\"Monuments\" href=\"http:\/\/fromereville-les-vallons.fr\/fr\/information\/31290\/monuments\">Monuments<\/a><\/li>\n<li><a title=\"Lavoirs\" href=\"http:\/\/fromereville-les-vallons.fr\/fr\/information\/31307\/lavoirs\">Lavoirs<\/a><\/li>\n<li><a title=\"Fontaines &amp; Abreuvoirs\" href=\"http:\/\/fromereville-les-vallons.fr\/fr\/information\/31311\/fontaines-abreuvoirs\">Fontaines &amp; Abreuvoirs<\/a><\/li>\n<li><a title=\"Personnes illustres.\" href=\"http:\/\/fromereville-les-vallons.fr\/fr\/information\/31428\/personnes-illustres\">Personnes illustres.<\/a><\/li>\n<li><a title=\"Forts\" href=\"http:\/\/fromereville-les-vallons.fr\/fr\/information\/31414\/forts\">Forts<\/a><\/li>\n<li><a title=\"For\u00eat\" href=\"http:\/\/fromereville-les-vallons.fr\/fr\/information\/31819\/foret\">For\u00eat<\/a><\/li>\n<li><a title=\"Divers\" href=\"http:\/\/fromereville-les-vallons.fr\/fr\/information\/31432\/divers\">Divers<\/a><\/li>\n<\/ul>\n<p><iframe style=\"width:120px;height:240px;\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" frameborder=\"0\" src=\"\/\/ws-eu.amazon-adsystem.com\/widgets\/q?ServiceVersion=20070822&#038;OneJS=1&#038;Operation=GetAdHtml&#038;MarketPlace=FR&#038;source=ac&#038;ref=tf_til&#038;ad_type=product_link&#038;tracking_id=charledeflaha-21&#038;marketplace=amazon&#038;region=FR&#038;placement=2915907730&#038;asins=2915907730&#038;linkId=4B74BVVA5LIFDLTI&#038;show_border=true&#038;link_opens_in_new_window=true\"><br \/>\n<\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un nouveau site r\u00e9f\u00e9renc\u00e9 sur Annuaire Histoire : Histoire et patrimoine de Fromer\u00e9ville Les Vallons (Meuse) http:\/\/fromereville-les-vallons.fr\/fr\/information\/31653\/historique Le nom \u00ab\u00a0Fromer\u00e9ville\u00a0\u00bb est \u00e9tymologiquement compos\u00e9 du mot latin \u00ab\u00a0villa\u00a0\u00bb (domaine) et de l&rsquo;anthroponyme germanique \u00ab\u00a0Frumar\u00a0\u00bb. La voie romaine d&rsquo;ordre inf\u00e9rieur de Verdun \u00e0 Romagne-sous-Montfaucon prend naissance au sud du territoire de Fromer\u00e9ville, qu&rsquo;elle traverse. (image et extrait &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[143,16,8],"tags":[],"class_list":["post-5445","post","type-post","status-publish","format-standard","hentry","category-55-meuse","category-histoire-regionale","category-patrimoine","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire et patrimoine de Fromer\u00e9ville Les Vallons (Meuse) - Histoire de France - Communiqu\u00e9s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire et patrimoine de Fromer\u00e9ville Les Vallons (Meuse) - Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Un nouveau site r\u00e9f\u00e9renc\u00e9 sur Annuaire Histoire : Histoire et patrimoine de Fromer\u00e9ville Les Vallons (Meuse) http:\/\/fromereville-les-vallons.fr\/fr\/information\/31653\/historique Le nom \u00ab\u00a0Fromer\u00e9ville\u00a0\u00bb est \u00e9tymologiquement compos\u00e9 du mot latin \u00ab\u00a0villa\u00a0\u00bb (domaine) et de l&rsquo;anthroponyme germanique \u00ab\u00a0Frumar\u00a0\u00bb. La voie romaine d&rsquo;ordre inf\u00e9rieur de Verdun \u00e0 Romagne-sous-Montfaucon prend naissance au sud du territoire de Fromer\u00e9ville, qu&rsquo;elle traverse. (image et extrait &hellip; Lire la suite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\/\" \/>\n<meta property=\"og:site_name\" content=\"Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:published_time\" content=\"2014-01-28T16:40:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-06-03T19:18:57+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2014\/01\/fromereville-300x202.jpg\" \/>\n<meta name=\"author\" content=\"administrateur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrateur\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\\\/\"},\"author\":{\"name\":\"administrateur\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"headline\":\"Histoire et patrimoine de Fromer\u00e9ville Les Vallons (Meuse)\",\"datePublished\":\"2014-01-28T16:40:47+00:00\",\"dateModified\":\"2015-06-03T19:18:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\\\/\"},\"wordCount\":104,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/fromereville-300x202.jpg\",\"articleSection\":[\"55 - Meuse\",\"histoire locale\",\"patrimoine\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\\\/\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\\\/\",\"name\":\"Histoire et patrimoine de Fromer\u00e9ville Les Vallons (Meuse) - Histoire de France - Communiqu\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/fromereville-300x202.jpg\",\"datePublished\":\"2014-01-28T16:40:47+00:00\",\"dateModified\":\"2015-06-03T19:18:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/fromereville.jpg\",\"contentUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/fromereville.jpg\",\"width\":380,\"height\":256},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Histoire et patrimoine de Fromer\u00e9ville Les Vallons (Meuse)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\",\"name\":\"Histoire de France - Communiqu\u00e9s\",\"description\":\"Histoire et patrimoine\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\",\"name\":\"administrateur\",\"logo\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.charles-de-flahaut.fr\",\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"],\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire et patrimoine de Fromer\u00e9ville Les Vallons (Meuse) - Histoire de France - Communiqu\u00e9s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire et patrimoine de Fromer\u00e9ville Les Vallons (Meuse) - Histoire de France - Communiqu\u00e9s","og_description":"Un nouveau site r\u00e9f\u00e9renc\u00e9 sur Annuaire Histoire : Histoire et patrimoine de Fromer\u00e9ville Les Vallons (Meuse) http:\/\/fromereville-les-vallons.fr\/fr\/information\/31653\/historique Le nom \u00ab\u00a0Fromer\u00e9ville\u00a0\u00bb est \u00e9tymologiquement compos\u00e9 du mot latin \u00ab\u00a0villa\u00a0\u00bb (domaine) et de l&rsquo;anthroponyme germanique \u00ab\u00a0Frumar\u00a0\u00bb. La voie romaine d&rsquo;ordre inf\u00e9rieur de Verdun \u00e0 Romagne-sous-Montfaucon prend naissance au sud du territoire de Fromer\u00e9ville, qu&rsquo;elle traverse. (image et extrait &hellip; Lire la suite","og_url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\/","og_site_name":"Histoire de France - Communiqu\u00e9s","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_author":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_published_time":"2014-01-28T16:40:47+00:00","article_modified_time":"2015-06-03T19:18:57+00:00","og_image":[{"url":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2014\/01\/fromereville-300x202.jpg","type":"","width":"","height":""}],"author":"administrateur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"administrateur"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\/#article","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\/"},"author":{"name":"administrateur","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"headline":"Histoire et patrimoine de Fromer\u00e9ville Les Vallons (Meuse)","datePublished":"2014-01-28T16:40:47+00:00","dateModified":"2015-06-03T19:18:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\/"},"wordCount":104,"commentCount":0,"publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\/#primaryimage"},"thumbnailUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2014\/01\/fromereville-300x202.jpg","articleSection":["55 - Meuse","histoire locale","patrimoine"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\/","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\/","name":"Histoire et patrimoine de Fromer\u00e9ville Les Vallons (Meuse) - Histoire de France - Communiqu\u00e9s","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\/#primaryimage"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\/#primaryimage"},"thumbnailUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2014\/01\/fromereville-300x202.jpg","datePublished":"2014-01-28T16:40:47+00:00","dateModified":"2015-06-03T19:18:57+00:00","breadcrumb":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\/#primaryimage","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2014\/01\/fromereville.jpg","contentUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2014\/01\/fromereville.jpg","width":380,"height":256},{"@type":"BreadcrumbList","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-fromereville-les-vallons-meuse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Histoire et patrimoine de Fromer\u00e9ville Les Vallons (Meuse)"}]},{"@type":"WebSite","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/","name":"Histoire de France - Communiqu\u00e9s","description":"Histoire et patrimoine","publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9","name":"administrateur","logo":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/www.charles-de-flahaut.fr","https:\/\/www.facebook.com\/Sites.HistoiredeFrance"],"url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/author\/admin\/"}]}},"views":773,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/5445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=5445"}],"version-history":[{"count":7,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/5445\/revisions"}],"predecessor-version":[{"id":13875,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/5445\/revisions\/13875"}],"wp:attachment":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=5445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=5445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=5445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}