{"id":5344,"date":"2014-01-23T12:55:41","date_gmt":"2014-01-23T11:55:41","guid":{"rendered":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/?p=5344"},"modified":"2015-06-07T16:02:35","modified_gmt":"2015-06-07T15:02:35","slug":"histoire-de-tucquegnieux-meurthe-et-moselle","status":"publish","type":"post","link":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-tucquegnieux-meurthe-et-moselle\/","title":{"rendered":"Histoire de Tucquegnieux (Meurthe-et-Moselle)"},"content":{"rendered":"<p><em>un nouveau site r\u00e9f\u00e9renc\u00e9 sur <a href=\"http:\/\/www.histoire-communes.jpflahaut.fr\/\" target=\"_blank\">Histoire et patrimoine des villes et villages de France<\/a><\/em><\/p>\n<p><strong>Histoire de Tucquegnieux (Meurthe-et-Moselle)<\/strong><br \/>\n<a href=\"http:\/\/www.ville-tucquegnieux.fr\/ACCUEIL\/PAGES\/presentation.HTM\" target=\"_blank\">http:\/\/www.ville-tucquegnieux.fr\/ACCUEIL\/PAGES\/presentation.HTM<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2014\/01\/tucquegnieux.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-5345\" src=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2014\/01\/tucquegnieux-300x235.jpg\" alt=\"tucquegnieux\" width=\"300\" height=\"235\" srcset=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2014\/01\/tucquegnieux-300x235.jpg 300w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2014\/01\/tucquegnieux-1024x802.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>TUCQUEGNIEUX se composait \u00e0 l\u2019origine, de chaumi\u00e8res construites avec des claies, des branchages entortill\u00e9s. Les interstices \u00e9taient bouch\u00e9s avec de la terre glaise, de la boue ou du torchis.<br \/>\nLe nom de TUCQUEGNIEUX contient en lui-m\u00eame son origine :<br \/>\nTU : du latin tugurium qui signifie chaumi\u00e8re.<br \/>\nQUE : quercetum qui signifie ch\u00eanaie.<br \/>\nNIEUX : d\u00e9riv\u00e9 de nexus : entrelacement.<\/p>\n<p><em>(image et extrait du site officiel de la commune &#8230; <a href=\"http:\/\/www.ville-tucquegnieux.fr\/ACCUEIL\/PAGES\/presentation.HTM\" target=\"_blank\">lire la suite<\/a>)<\/em><\/p>\n<p><iframe style=\"width:120px;height:240px;\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" frameborder=\"0\" src=\"\/\/ws-eu.amazon-adsystem.com\/widgets\/q?ServiceVersion=20070822&#038;OneJS=1&#038;Operation=GetAdHtml&#038;MarketPlace=FR&#038;source=ac&#038;ref=tf_til&#038;ad_type=product_link&#038;tracking_id=charledeflaha-21&#038;marketplace=amazon&#038;region=FR&#038;placement=2915907579&#038;asins=2915907579&#038;linkId=NTSFUYFZQKYUPVE5&#038;show_border=true&#038;link_opens_in_new_window=true\"><br \/>\n<\/iframe><iframe style=\"width:120px;height:240px;\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" frameborder=\"0\" src=\"\/\/ws-eu.amazon-adsystem.com\/widgets\/q?ServiceVersion=20070822&#038;OneJS=1&#038;Operation=GetAdHtml&#038;MarketPlace=FR&#038;source=ac&#038;ref=tf_til&#038;ad_type=product_link&#038;tracking_id=charledeflaha-21&#038;marketplace=amazon&#038;region=FR&#038;placement=2876929392&#038;asins=2876929392&#038;linkId=I54YMFB4KIHEG7PW&#038;show_border=true&#038;link_opens_in_new_window=true\"><br \/>\n<\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>un nouveau site r\u00e9f\u00e9renc\u00e9 sur Histoire et patrimoine des villes et villages de France Histoire de Tucquegnieux (Meurthe-et-Moselle) http:\/\/www.ville-tucquegnieux.fr\/ACCUEIL\/PAGES\/presentation.HTM TUCQUEGNIEUX se composait \u00e0 l\u2019origine, de chaumi\u00e8res construites avec des claies, des branchages entortill\u00e9s. Les interstices \u00e9taient bouch\u00e9s avec de la terre glaise, de la boue ou du torchis. Le nom de TUCQUEGNIEUX contient en lui-m\u00eame &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-tucquegnieux-meurthe-et-moselle\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[142,16],"tags":[],"class_list":["post-5344","post","type-post","status-publish","format-standard","hentry","category-54-meurthe-et-moselle","category-histoire-regionale","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire de Tucquegnieux (Meurthe-et-Moselle) - Histoire de France - Communiqu\u00e9s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-tucquegnieux-meurthe-et-moselle\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire de Tucquegnieux (Meurthe-et-Moselle) - Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"og:description\" content=\"un nouveau site r\u00e9f\u00e9renc\u00e9 sur Histoire et patrimoine des villes et villages de France Histoire de Tucquegnieux (Meurthe-et-Moselle) http:\/\/www.ville-tucquegnieux.fr\/ACCUEIL\/PAGES\/presentation.HTM TUCQUEGNIEUX se composait \u00e0 l\u2019origine, de chaumi\u00e8res construites avec des claies, des branchages entortill\u00e9s. Les interstices \u00e9taient bouch\u00e9s avec de la terre glaise, de la boue ou du torchis. Le nom de TUCQUEGNIEUX contient en lui-m\u00eame &hellip; Lire la suite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-tucquegnieux-meurthe-et-moselle\/\" \/>\n<meta property=\"og:site_name\" content=\"Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:published_time\" content=\"2014-01-23T11:55:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-06-07T15:02:35+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2014\/01\/tucquegnieux-300x235.jpg\" \/>\n<meta name=\"author\" content=\"administrateur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrateur\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-tucquegnieux-meurthe-et-moselle\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-tucquegnieux-meurthe-et-moselle\\\/\"},\"author\":{\"name\":\"administrateur\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"headline\":\"Histoire de Tucquegnieux (Meurthe-et-Moselle)\",\"datePublished\":\"2014-01-23T11:55:41+00:00\",\"dateModified\":\"2015-06-07T15:02:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-tucquegnieux-meurthe-et-moselle\\\/\"},\"wordCount\":106,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-tucquegnieux-meurthe-et-moselle\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/tucquegnieux-300x235.jpg\",\"articleSection\":[\"54 - Meurthe-et-Moselle\",\"histoire locale\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-tucquegnieux-meurthe-et-moselle\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-tucquegnieux-meurthe-et-moselle\\\/\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-tucquegnieux-meurthe-et-moselle\\\/\",\"name\":\"Histoire de Tucquegnieux (Meurthe-et-Moselle) - Histoire de France - Communiqu\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-tucquegnieux-meurthe-et-moselle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-tucquegnieux-meurthe-et-moselle\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/tucquegnieux-300x235.jpg\",\"datePublished\":\"2014-01-23T11:55:41+00:00\",\"dateModified\":\"2015-06-07T15:02:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-tucquegnieux-meurthe-et-moselle\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-tucquegnieux-meurthe-et-moselle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-tucquegnieux-meurthe-et-moselle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/tucquegnieux.jpg\",\"contentUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/tucquegnieux.jpg\",\"width\":2779,\"height\":2179},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-tucquegnieux-meurthe-et-moselle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Histoire de Tucquegnieux (Meurthe-et-Moselle)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\",\"name\":\"Histoire de France - Communiqu\u00e9s\",\"description\":\"Histoire et patrimoine\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\",\"name\":\"administrateur\",\"logo\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.charles-de-flahaut.fr\",\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"],\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire de Tucquegnieux (Meurthe-et-Moselle) - Histoire de France - Communiqu\u00e9s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-tucquegnieux-meurthe-et-moselle\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire de Tucquegnieux (Meurthe-et-Moselle) - Histoire de France - Communiqu\u00e9s","og_description":"un nouveau site r\u00e9f\u00e9renc\u00e9 sur Histoire et patrimoine des villes et villages de France Histoire de Tucquegnieux (Meurthe-et-Moselle) http:\/\/www.ville-tucquegnieux.fr\/ACCUEIL\/PAGES\/presentation.HTM TUCQUEGNIEUX se composait \u00e0 l\u2019origine, de chaumi\u00e8res construites avec des claies, des branchages entortill\u00e9s. Les interstices \u00e9taient bouch\u00e9s avec de la terre glaise, de la boue ou du torchis. Le nom de TUCQUEGNIEUX contient en lui-m\u00eame &hellip; Lire la suite","og_url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-tucquegnieux-meurthe-et-moselle\/","og_site_name":"Histoire de France - Communiqu\u00e9s","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_author":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_published_time":"2014-01-23T11:55:41+00:00","article_modified_time":"2015-06-07T15:02:35+00:00","og_image":[{"url":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2014\/01\/tucquegnieux-300x235.jpg","type":"","width":"","height":""}],"author":"administrateur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"administrateur","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-tucquegnieux-meurthe-et-moselle\/#article","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-tucquegnieux-meurthe-et-moselle\/"},"author":{"name":"administrateur","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"headline":"Histoire de Tucquegnieux (Meurthe-et-Moselle)","datePublished":"2014-01-23T11:55:41+00:00","dateModified":"2015-06-07T15:02:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-tucquegnieux-meurthe-et-moselle\/"},"wordCount":106,"commentCount":0,"publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-tucquegnieux-meurthe-et-moselle\/#primaryimage"},"thumbnailUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2014\/01\/tucquegnieux-300x235.jpg","articleSection":["54 - Meurthe-et-Moselle","histoire locale"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-tucquegnieux-meurthe-et-moselle\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-tucquegnieux-meurthe-et-moselle\/","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-tucquegnieux-meurthe-et-moselle\/","name":"Histoire de Tucquegnieux (Meurthe-et-Moselle) - Histoire de France - Communiqu\u00e9s","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-tucquegnieux-meurthe-et-moselle\/#primaryimage"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-tucquegnieux-meurthe-et-moselle\/#primaryimage"},"thumbnailUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2014\/01\/tucquegnieux-300x235.jpg","datePublished":"2014-01-23T11:55:41+00:00","dateModified":"2015-06-07T15:02:35+00:00","breadcrumb":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-tucquegnieux-meurthe-et-moselle\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-tucquegnieux-meurthe-et-moselle\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-tucquegnieux-meurthe-et-moselle\/#primaryimage","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2014\/01\/tucquegnieux.jpg","contentUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2014\/01\/tucquegnieux.jpg","width":2779,"height":2179},{"@type":"BreadcrumbList","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-tucquegnieux-meurthe-et-moselle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Histoire de Tucquegnieux (Meurthe-et-Moselle)"}]},{"@type":"WebSite","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/","name":"Histoire de France - Communiqu\u00e9s","description":"Histoire et patrimoine","publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9","name":"administrateur","logo":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/www.charles-de-flahaut.fr","https:\/\/www.facebook.com\/Sites.HistoiredeFrance"],"url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/author\/admin\/"}]}},"views":2034,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/5344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=5344"}],"version-history":[{"count":4,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/5344\/revisions"}],"predecessor-version":[{"id":13907,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/5344\/revisions\/13907"}],"wp:attachment":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=5344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=5344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=5344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}