{"id":4690,"date":"2013-12-15T14:56:22","date_gmt":"2013-12-15T13:56:22","guid":{"rendered":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/?p=4690"},"modified":"2015-06-09T21:04:27","modified_gmt":"2015-06-09T20:04:27","slug":"histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine","status":"publish","type":"post","link":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\/","title":{"rendered":"Histoire et patrimoine de Bain-de-Bretagne (Ille-et-Vilaine)"},"content":{"rendered":"<p>Un nouveau site r\u00e9f\u00e9renc\u00e9 sur <a href=\"http:\/\/www.histoire-communes.jpflahaut.fr\/\" target=\"_blank\">Annuaire Histoire<\/a> :<\/p>\n<p><strong>Histoire et patrimoine de Bain-de-Bretagne (Ille-et-Vilaine)<\/strong><br \/>\n<a href=\"http:\/\/www.baindebretagne.fr\/module-pagesetter-viewpub-tid-2-pid-27.html\" target=\"_blank\">http:\/\/www.baindebretagne.fr\/module-pagesetter-viewpub-tid-2-pid-27.html<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2013\/12\/baindebretagne.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-4691\" src=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2013\/12\/baindebretagne.jpg\" alt=\"baindebretagne\" width=\"208\" height=\"156\" \/><\/a>\u00c0 l&rsquo;origine, un Romain (Baenus ou Balnus), propri\u00e9taire d&rsquo;une villa, habitait au bord de l&rsquo;\u00e9tang avec ses paysans vers l&rsquo;actuel abri des p\u00eacheurs, l\u00e0 o\u00f9 les Romains construisirent la digue.<br \/>\nPlus pr\u00e8s de nous, la route royale de Nantes (capitale de la Bretagne) \u00e0 Rennes traversait la ville par l&rsquo;actuelle avenue Guillotin de Corson&#8230;<\/p>\n<p><em>(image et extrait du site officiel de la commune &#8230; <a href=\"http:\/\/www.baindebretagne.fr\/module-pagesetter-viewpub-tid-2-pid-27.html\" target=\"_blank\">lire la suite<\/a>)<\/em><br \/>\n<br \/><iframe style=\"width:120px;height:240px;\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" frameborder=\"0\" src=\"\/\/ws-eu.amazon-adsystem.com\/widgets\/q?ServiceVersion=20070822&#038;OneJS=1&#038;Operation=GetAdHtml&#038;MarketPlace=FR&#038;source=ac&#038;ref=tf_til&#038;ad_type=product_link&#038;tracking_id=charledeflaha-21&#038;marketplace=amazon&#038;region=FR&#038;placement=2841780791&#038;asins=2841780791&#038;linkId=HOT27DQCW77VPJ4U&#038;show_border=true&#038;link_opens_in_new_window=true\"><br \/>\n<\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un nouveau site r\u00e9f\u00e9renc\u00e9 sur Annuaire Histoire : Histoire et patrimoine de Bain-de-Bretagne (Ille-et-Vilaine) http:\/\/www.baindebretagne.fr\/module-pagesetter-viewpub-tid-2-pid-27.html \u00c0 l&rsquo;origine, un Romain (Baenus ou Balnus), propri\u00e9taire d&rsquo;une villa, habitait au bord de l&rsquo;\u00e9tang avec ses paysans vers l&rsquo;actuel abri des p\u00eacheurs, l\u00e0 o\u00f9 les Romains construisirent la digue. Plus pr\u00e8s de nous, la route royale de Nantes (capitale &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[123,16,8],"tags":[],"class_list":["post-4690","post","type-post","status-publish","format-standard","hentry","category-35-ille-et-vilaine","category-histoire-regionale","category-patrimoine","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire et patrimoine de Bain-de-Bretagne (Ille-et-Vilaine) - Histoire de France - Communiqu\u00e9s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire et patrimoine de Bain-de-Bretagne (Ille-et-Vilaine) - Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Un nouveau site r\u00e9f\u00e9renc\u00e9 sur Annuaire Histoire : Histoire et patrimoine de Bain-de-Bretagne (Ille-et-Vilaine) http:\/\/www.baindebretagne.fr\/module-pagesetter-viewpub-tid-2-pid-27.html \u00c0 l&rsquo;origine, un Romain (Baenus ou Balnus), propri\u00e9taire d&rsquo;une villa, habitait au bord de l&rsquo;\u00e9tang avec ses paysans vers l&rsquo;actuel abri des p\u00eacheurs, l\u00e0 o\u00f9 les Romains construisirent la digue. Plus pr\u00e8s de nous, la route royale de Nantes (capitale &hellip; Lire la suite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\/\" \/>\n<meta property=\"og:site_name\" content=\"Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:published_time\" content=\"2013-12-15T13:56:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-06-09T20:04:27+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2013\/12\/baindebretagne.jpg\" \/>\n<meta name=\"author\" content=\"administrateur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrateur\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\\\/\"},\"author\":{\"name\":\"administrateur\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"headline\":\"Histoire et patrimoine de Bain-de-Bretagne (Ille-et-Vilaine)\",\"datePublished\":\"2013-12-15T13:56:22+00:00\",\"dateModified\":\"2015-06-09T20:04:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\\\/\"},\"wordCount\":100,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/baindebretagne.jpg\",\"articleSection\":[\"35 - Ille-et-Vilaine\",\"histoire locale\",\"patrimoine\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\\\/\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\\\/\",\"name\":\"Histoire et patrimoine de Bain-de-Bretagne (Ille-et-Vilaine) - Histoire de France - Communiqu\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/baindebretagne.jpg\",\"datePublished\":\"2013-12-15T13:56:22+00:00\",\"dateModified\":\"2015-06-09T20:04:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/baindebretagne.jpg\",\"contentUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/baindebretagne.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Histoire et patrimoine de Bain-de-Bretagne (Ille-et-Vilaine)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\",\"name\":\"Histoire de France - Communiqu\u00e9s\",\"description\":\"Histoire et patrimoine\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\",\"name\":\"administrateur\",\"logo\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.charles-de-flahaut.fr\",\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"],\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire et patrimoine de Bain-de-Bretagne (Ille-et-Vilaine) - Histoire de France - Communiqu\u00e9s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire et patrimoine de Bain-de-Bretagne (Ille-et-Vilaine) - Histoire de France - Communiqu\u00e9s","og_description":"Un nouveau site r\u00e9f\u00e9renc\u00e9 sur Annuaire Histoire : Histoire et patrimoine de Bain-de-Bretagne (Ille-et-Vilaine) http:\/\/www.baindebretagne.fr\/module-pagesetter-viewpub-tid-2-pid-27.html \u00c0 l&rsquo;origine, un Romain (Baenus ou Balnus), propri\u00e9taire d&rsquo;une villa, habitait au bord de l&rsquo;\u00e9tang avec ses paysans vers l&rsquo;actuel abri des p\u00eacheurs, l\u00e0 o\u00f9 les Romains construisirent la digue. Plus pr\u00e8s de nous, la route royale de Nantes (capitale &hellip; Lire la suite","og_url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\/","og_site_name":"Histoire de France - Communiqu\u00e9s","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_author":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_published_time":"2013-12-15T13:56:22+00:00","article_modified_time":"2015-06-09T20:04:27+00:00","og_image":[{"url":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2013\/12\/baindebretagne.jpg","type":"","width":"","height":""}],"author":"administrateur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"administrateur"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\/#article","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\/"},"author":{"name":"administrateur","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"headline":"Histoire et patrimoine de Bain-de-Bretagne (Ille-et-Vilaine)","datePublished":"2013-12-15T13:56:22+00:00","dateModified":"2015-06-09T20:04:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\/"},"wordCount":100,"commentCount":0,"publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\/#primaryimage"},"thumbnailUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2013\/12\/baindebretagne.jpg","articleSection":["35 - Ille-et-Vilaine","histoire locale","patrimoine"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\/","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\/","name":"Histoire et patrimoine de Bain-de-Bretagne (Ille-et-Vilaine) - Histoire de France - Communiqu\u00e9s","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\/#primaryimage"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\/#primaryimage"},"thumbnailUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2013\/12\/baindebretagne.jpg","datePublished":"2013-12-15T13:56:22+00:00","dateModified":"2015-06-09T20:04:27+00:00","breadcrumb":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\/#primaryimage","url":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2013\/12\/baindebretagne.jpg","contentUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2013\/12\/baindebretagne.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-bain-de-bretagne-ille-et-vilaine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Histoire et patrimoine de Bain-de-Bretagne (Ille-et-Vilaine)"}]},{"@type":"WebSite","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/","name":"Histoire de France - Communiqu\u00e9s","description":"Histoire et patrimoine","publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9","name":"administrateur","logo":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/www.charles-de-flahaut.fr","https:\/\/www.facebook.com\/Sites.HistoiredeFrance"],"url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/author\/admin\/"}]}},"views":398,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/4690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=4690"}],"version-history":[{"count":4,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/4690\/revisions"}],"predecessor-version":[{"id":14074,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/4690\/revisions\/14074"}],"wp:attachment":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=4690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=4690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=4690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}