{"id":46518,"date":"2017-08-15T08:14:23","date_gmt":"2017-08-15T07:14:23","guid":{"rendered":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/?p=46518"},"modified":"2025-06-25T15:10:23","modified_gmt":"2025-06-25T14:10:23","slug":"histoire-damfroipret-nord","status":"publish","type":"post","link":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-damfroipret-nord\/","title":{"rendered":"Histoire d&rsquo;Amfroipret (Nord)"},"content":{"rendered":"<p><strong>Histoire d&rsquo;Amfroipret (Nord)<\/strong><br \/>\n<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Amfroipret#Histoire\" target=\"_blank\" rel=\"noopener\">https:\/\/fr.wikipedia.org\/wiki\/Amfroipret#Histoire<\/a><\/p>\n<p style=\"text-align: justify;\"><em><a href=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2017\/08\/amfroipret59.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-46519\" src=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2017\/08\/amfroipret59-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2017\/08\/amfroipret59-225x300.jpg 225w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2017\/08\/amfroipret59.jpg 280w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>un site r\u00e9f\u00e9renc\u00e9 sur le nouvel <a href=\"http:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\" target=\"_blank\" rel=\"noopener noreferrer\">Annuaire Historique des Communes de France<\/a><\/em><\/p>\n<p style=\"text-align: justify;\">En 1340, au d\u00e9but de la guerre de Cent Ans, les Fran\u00e7ais br\u00fbl\u00e8rent le village.<\/p>\n<p style=\"text-align: justify;\">D&rsquo;apr\u00e8s une gouache des Albums de Cro\u00ff, Amfroipret poss\u00e9dait au d\u00e9but du <abbr class=\"abbr\" title=\"17\u1d49 si\u00e8cle\"><span class=\"romain\">XVII<\/span><sup>e<\/sup><\/abbr>\u00a0si\u00e8cle, un important ch\u00e2teau m\u00e9di\u00e9val qui comprenait de nombreuses tours carr\u00e9es de hauteurs in\u00e9gales; \u00e0 l&rsquo;une d&rsquo;elles \u00e9tait adoss\u00e9e une svelte tourelle cylindrique coiff\u00e9e d&rsquo;une fl\u00e8che aig\u00fce&#8230;<\/p>\n<p style=\"text-align: justify;\"><em>(source wikipedia&#8230; <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Amfroipret#Histoire\" target=\"_blank\" rel=\"noopener\">lire la suite<\/a>)<\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/amzn.to\/4nkpNBW\" target=\"_blank\" rel=\"noopener\"><strong>Ouvrages sur Amfroipret<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/amzn.to\/4nkpNBW\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-106023 alignnone\" src=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2017\/08\/amfroipret.jpg\" alt=\"\" width=\"264\" height=\"445\" srcset=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2017\/08\/amfroipret.jpg 264w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2017\/08\/amfroipret-178x300.jpg 178w\" sizes=\"auto, (max-width: 264px) 100vw, 264px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Histoire d&rsquo;Amfroipret (Nord) https:\/\/fr.wikipedia.org\/wiki\/Amfroipret#Histoire un site r\u00e9f\u00e9renc\u00e9 sur le nouvel Annuaire Historique des Communes de France En 1340, au d\u00e9but de la guerre de Cent Ans, les Fran\u00e7ais br\u00fbl\u00e8rent le village. D&rsquo;apr\u00e8s une gouache des Albums de Cro\u00ff, Amfroipret poss\u00e9dait au d\u00e9but du XVIIe\u00a0si\u00e8cle, un important ch\u00e2teau m\u00e9di\u00e9val qui comprenait de nombreuses tours carr\u00e9es de &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-damfroipret-nord\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":117,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[147,16],"tags":[],"class_list":["post-46518","post","type-post","status-publish","format-standard","hentry","category-59-nord","category-histoire-regionale","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire d&#039;Amfroipret (Nord) - Histoire de France - Communiqu\u00e9s<\/title>\n<meta name=\"description\" content=\"D&#039;apr\u00e8s une gouache des Albums de Cro\u00ff, Amfroipret poss\u00e9dait au d\u00e9but du XVIIe\u00a0si\u00e8cle, un important ch\u00e2teau m\u00e9di\u00e9val\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-damfroipret-nord\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire d&#039;Amfroipret (Nord) - Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"og:description\" content=\"D&#039;apr\u00e8s une gouache des Albums de Cro\u00ff, Amfroipret poss\u00e9dait au d\u00e9but du XVIIe\u00a0si\u00e8cle, un important ch\u00e2teau m\u00e9di\u00e9val\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-damfroipret-nord\/\" \/>\n<meta property=\"og:site_name\" content=\"Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-15T07:14:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-25T14:10:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2017\/08\/amfroipret59.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"280\" \/>\n\t<meta property=\"og:image:height\" content=\"373\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"administrateur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrateur\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-damfroipret-nord\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-damfroipret-nord\\\/\"},\"author\":{\"name\":\"administrateur\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\"},\"headline\":\"Histoire d&rsquo;Amfroipret (Nord)\",\"datePublished\":\"2017-08-15T07:14:23+00:00\",\"dateModified\":\"2025-06-25T14:10:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-damfroipret-nord\\\/\"},\"wordCount\":112,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-damfroipret-nord\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/amfroipret59-225x300.jpg\",\"articleSection\":[\"59 - Nord\",\"histoire locale\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-damfroipret-nord\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-damfroipret-nord\\\/\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-damfroipret-nord\\\/\",\"name\":\"Histoire d'Amfroipret (Nord) - Histoire de France - Communiqu\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-damfroipret-nord\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-damfroipret-nord\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/amfroipret59-225x300.jpg\",\"datePublished\":\"2017-08-15T07:14:23+00:00\",\"dateModified\":\"2025-06-25T14:10:23+00:00\",\"description\":\"D'apr\u00e8s une gouache des Albums de Cro\u00ff, Amfroipret poss\u00e9dait au d\u00e9but du XVIIe\u00a0si\u00e8cle, un important ch\u00e2teau m\u00e9di\u00e9val\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-damfroipret-nord\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-damfroipret-nord\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-damfroipret-nord\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/amfroipret59.jpg\",\"contentUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/amfroipret59.jpg\",\"width\":280,\"height\":373},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-damfroipret-nord\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Histoire d&rsquo;Amfroipret (Nord)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\",\"name\":\"Histoire de France - Communiqu\u00e9s\",\"description\":\"Histoire et patrimoine\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\",\"name\":\"administrateur\",\"logo\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.charles-de-flahaut.fr\",\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\",\"name\":\"administrateur\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/author\\\/hist_8la_ad\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire d'Amfroipret (Nord) - Histoire de France - Communiqu\u00e9s","description":"D'apr\u00e8s une gouache des Albums de Cro\u00ff, Amfroipret poss\u00e9dait au d\u00e9but du XVIIe\u00a0si\u00e8cle, un important ch\u00e2teau m\u00e9di\u00e9val","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-damfroipret-nord\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire d'Amfroipret (Nord) - Histoire de France - Communiqu\u00e9s","og_description":"D'apr\u00e8s une gouache des Albums de Cro\u00ff, Amfroipret poss\u00e9dait au d\u00e9but du XVIIe\u00a0si\u00e8cle, un important ch\u00e2teau m\u00e9di\u00e9val","og_url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-damfroipret-nord\/","og_site_name":"Histoire de France - Communiqu\u00e9s","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_published_time":"2017-08-15T07:14:23+00:00","article_modified_time":"2025-06-25T14:10:23+00:00","og_image":[{"width":280,"height":373,"url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2017\/08\/amfroipret59.jpg","type":"image\/jpeg"}],"author":"administrateur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"administrateur","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-damfroipret-nord\/#article","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-damfroipret-nord\/"},"author":{"name":"administrateur","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56"},"headline":"Histoire d&rsquo;Amfroipret (Nord)","datePublished":"2017-08-15T07:14:23+00:00","dateModified":"2025-06-25T14:10:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-damfroipret-nord\/"},"wordCount":112,"commentCount":0,"publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-damfroipret-nord\/#primaryimage"},"thumbnailUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2017\/08\/amfroipret59-225x300.jpg","articleSection":["59 - Nord","histoire locale"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-damfroipret-nord\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-damfroipret-nord\/","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-damfroipret-nord\/","name":"Histoire d'Amfroipret (Nord) - Histoire de France - Communiqu\u00e9s","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-damfroipret-nord\/#primaryimage"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-damfroipret-nord\/#primaryimage"},"thumbnailUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2017\/08\/amfroipret59-225x300.jpg","datePublished":"2017-08-15T07:14:23+00:00","dateModified":"2025-06-25T14:10:23+00:00","description":"D'apr\u00e8s une gouache des Albums de Cro\u00ff, Amfroipret poss\u00e9dait au d\u00e9but du XVIIe\u00a0si\u00e8cle, un important ch\u00e2teau m\u00e9di\u00e9val","breadcrumb":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-damfroipret-nord\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-damfroipret-nord\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-damfroipret-nord\/#primaryimage","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2017\/08\/amfroipret59.jpg","contentUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2017\/08\/amfroipret59.jpg","width":280,"height":373},{"@type":"BreadcrumbList","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-damfroipret-nord\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Histoire d&rsquo;Amfroipret (Nord)"}]},{"@type":"WebSite","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/","name":"Histoire de France - Communiqu\u00e9s","description":"Histoire et patrimoine","publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9","name":"administrateur","logo":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/www.charles-de-flahaut.fr","https:\/\/www.facebook.com\/Sites.HistoiredeFrance"]},{"@type":"Person","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56","name":"administrateur","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/author\/hist_8la_ad\/"}]}},"views":135,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/46518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=46518"}],"version-history":[{"count":4,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/46518\/revisions"}],"predecessor-version":[{"id":106025,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/46518\/revisions\/106025"}],"wp:attachment":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=46518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=46518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=46518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}