{"id":43198,"date":"2017-02-15T14:43:16","date_gmt":"2017-02-15T13:43:16","guid":{"rendered":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/?p=43198"},"modified":"2025-08-15T14:59:49","modified_gmt":"2025-08-15T13:59:49","slug":"histoire-dharavilliers-val-doise","status":"publish","type":"post","link":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-dharavilliers-val-doise\/","title":{"rendered":"Histoire d&rsquo;Haravilliers (Val d&rsquo;Oise)"},"content":{"rendered":"<p><strong>Histoire d&rsquo;Haravilliers (Val d&rsquo;Oise)<\/strong><br \/>\n<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Haravilliers#Histoire\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/fr.wikipedia.org\/wiki\/Haravilliers#Histoire<\/a><\/p>\n<p style=\"text-align: justify;\"><em><a href=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2017\/02\/haravilliers95.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-43199\" src=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2017\/02\/haravilliers95-226x300.jpg\" alt=\"\" width=\"226\" height=\"300\" srcset=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2017\/02\/haravilliers95-226x300.jpg 226w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2017\/02\/haravilliers95.jpg 280w\" sizes=\"auto, (max-width: 226px) 100vw, 226px\" \/><\/a>un site r\u00e9f\u00e9renc\u00e9 sur le nouvel <a href=\"http:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\" target=\"_blank\" rel=\"noopener noreferrer\">Annuaire Historique des Communes de France<\/a><\/em><\/p>\n<p style=\"text-align: justify;\">Le lieu est occup\u00e9 d\u00e8s la pr\u00e9histoire, comme l&rsquo;atteste la d\u00e9couverte de nombreux silex taill\u00e9s et pierres polies sur le territoire de la commune. Deux sites d&rsquo;habitat et un atelier de potier de l&rsquo;\u00e9poque gallo-romaine ont \u00e9galement \u00e9t\u00e9 d\u00e9couverts. La dimension de l&rsquo;\u00e9glise indique l&rsquo;importance de la paroisse au Moyen \u00c2ge; le lieu se nomme Haradvilerio en 1099. La population est r\u00e9partie dans de nombreux hameaux, et la situation pose probl\u00e8me sous l&rsquo;Ancien R\u00e9gime&#8230;<br \/>\n<em>(source wikipedia&#8230; <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Haravilliers#Histoire\" target=\"_blank\" rel=\"noopener noreferrer\">lire la suite<\/a>)<\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/amzn.to\/3Jizdyf\" target=\"_blank\" rel=\"noopener\"><strong>Ouvrages sur le Val d&rsquo;Oise<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/amzn.to\/3Jizdyf\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-105815 aligncenter\" src=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2025\/06\/valdoise1.jpg\" alt=\"\" width=\"339\" height=\"445\" srcset=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2025\/06\/valdoise1.jpg 339w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2025\/06\/valdoise1-229x300.jpg 229w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Histoire d&rsquo;Haravilliers (Val d&rsquo;Oise) https:\/\/fr.wikipedia.org\/wiki\/Haravilliers#Histoire un site r\u00e9f\u00e9renc\u00e9 sur le nouvel Annuaire Historique des Communes de France Le lieu est occup\u00e9 d\u00e8s la pr\u00e9histoire, comme l&rsquo;atteste la d\u00e9couverte de nombreux silex taill\u00e9s et pierres polies sur le territoire de la commune. Deux sites d&rsquo;habitat et un atelier de potier de l&rsquo;\u00e9poque gallo-romaine ont \u00e9galement \u00e9t\u00e9 &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-dharavilliers-val-doise\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":117,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[183,16],"tags":[],"class_list":["post-43198","post","type-post","status-publish","format-standard","hentry","category-95-val-doise","category-histoire-regionale","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire d&#039;Haravilliers (Val d&#039;Oise) - Histoire de France - Communiqu\u00e9s<\/title>\n<meta name=\"description\" content=\"Le lieu est occup\u00e9 d\u00e8s la pr\u00e9histoire, comme l&#039;atteste la d\u00e9couverte de nombreux silex taill\u00e9s et pierres polies sur le territoire\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-dharavilliers-val-doise\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire d&#039;Haravilliers (Val d&#039;Oise) - Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Le lieu est occup\u00e9 d\u00e8s la pr\u00e9histoire, comme l&#039;atteste la d\u00e9couverte de nombreux silex taill\u00e9s et pierres polies sur le territoire\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-dharavilliers-val-doise\/\" \/>\n<meta property=\"og:site_name\" content=\"Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-15T13:43:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-15T13:59:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2017\/02\/haravilliers95.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"280\" \/>\n\t<meta property=\"og:image:height\" content=\"372\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"administrateur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrateur\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-dharavilliers-val-doise\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-dharavilliers-val-doise\\\/\"},\"author\":{\"name\":\"administrateur\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\"},\"headline\":\"Histoire d&rsquo;Haravilliers (Val d&rsquo;Oise)\",\"datePublished\":\"2017-02-15T13:43:16+00:00\",\"dateModified\":\"2025-08-15T13:59:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-dharavilliers-val-doise\\\/\"},\"wordCount\":131,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-dharavilliers-val-doise\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/haravilliers95-226x300.jpg\",\"articleSection\":[\"95 - Val d'Oise\",\"histoire locale\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-dharavilliers-val-doise\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-dharavilliers-val-doise\\\/\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-dharavilliers-val-doise\\\/\",\"name\":\"Histoire d'Haravilliers (Val d'Oise) - Histoire de France - Communiqu\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-dharavilliers-val-doise\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-dharavilliers-val-doise\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/haravilliers95-226x300.jpg\",\"datePublished\":\"2017-02-15T13:43:16+00:00\",\"dateModified\":\"2025-08-15T13:59:49+00:00\",\"description\":\"Le lieu est occup\u00e9 d\u00e8s la pr\u00e9histoire, comme l'atteste la d\u00e9couverte de nombreux silex taill\u00e9s et pierres polies sur le territoire\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-dharavilliers-val-doise\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-dharavilliers-val-doise\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-dharavilliers-val-doise\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/haravilliers95.jpg\",\"contentUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/haravilliers95.jpg\",\"width\":280,\"height\":372},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-dharavilliers-val-doise\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Histoire d&rsquo;Haravilliers (Val d&rsquo;Oise)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\",\"name\":\"Histoire de France - Communiqu\u00e9s\",\"description\":\"Histoire et patrimoine\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\",\"name\":\"administrateur\",\"logo\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.charles-de-flahaut.fr\",\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\",\"name\":\"administrateur\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/author\\\/hist_8la_ad\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire d'Haravilliers (Val d'Oise) - Histoire de France - Communiqu\u00e9s","description":"Le lieu est occup\u00e9 d\u00e8s la pr\u00e9histoire, comme l'atteste la d\u00e9couverte de nombreux silex taill\u00e9s et pierres polies sur le territoire","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-dharavilliers-val-doise\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire d'Haravilliers (Val d'Oise) - Histoire de France - Communiqu\u00e9s","og_description":"Le lieu est occup\u00e9 d\u00e8s la pr\u00e9histoire, comme l'atteste la d\u00e9couverte de nombreux silex taill\u00e9s et pierres polies sur le territoire","og_url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-dharavilliers-val-doise\/","og_site_name":"Histoire de France - Communiqu\u00e9s","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_published_time":"2017-02-15T13:43:16+00:00","article_modified_time":"2025-08-15T13:59:49+00:00","og_image":[{"width":280,"height":372,"url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2017\/02\/haravilliers95.jpg","type":"image\/jpeg"}],"author":"administrateur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"administrateur","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-dharavilliers-val-doise\/#article","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-dharavilliers-val-doise\/"},"author":{"name":"administrateur","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56"},"headline":"Histoire d&rsquo;Haravilliers (Val d&rsquo;Oise)","datePublished":"2017-02-15T13:43:16+00:00","dateModified":"2025-08-15T13:59:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-dharavilliers-val-doise\/"},"wordCount":131,"commentCount":0,"publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-dharavilliers-val-doise\/#primaryimage"},"thumbnailUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2017\/02\/haravilliers95-226x300.jpg","articleSection":["95 - Val d'Oise","histoire locale"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-dharavilliers-val-doise\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-dharavilliers-val-doise\/","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-dharavilliers-val-doise\/","name":"Histoire d'Haravilliers (Val d'Oise) - Histoire de France - Communiqu\u00e9s","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-dharavilliers-val-doise\/#primaryimage"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-dharavilliers-val-doise\/#primaryimage"},"thumbnailUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2017\/02\/haravilliers95-226x300.jpg","datePublished":"2017-02-15T13:43:16+00:00","dateModified":"2025-08-15T13:59:49+00:00","description":"Le lieu est occup\u00e9 d\u00e8s la pr\u00e9histoire, comme l'atteste la d\u00e9couverte de nombreux silex taill\u00e9s et pierres polies sur le territoire","breadcrumb":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-dharavilliers-val-doise\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-dharavilliers-val-doise\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-dharavilliers-val-doise\/#primaryimage","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2017\/02\/haravilliers95.jpg","contentUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2017\/02\/haravilliers95.jpg","width":280,"height":372},{"@type":"BreadcrumbList","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-dharavilliers-val-doise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Histoire d&rsquo;Haravilliers (Val d&rsquo;Oise)"}]},{"@type":"WebSite","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/","name":"Histoire de France - Communiqu\u00e9s","description":"Histoire et patrimoine","publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9","name":"administrateur","logo":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/www.charles-de-flahaut.fr","https:\/\/www.facebook.com\/Sites.HistoiredeFrance"]},{"@type":"Person","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56","name":"administrateur","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/author\/hist_8la_ad\/"}]}},"views":289,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/43198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=43198"}],"version-history":[{"count":4,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/43198\/revisions"}],"predecessor-version":[{"id":107813,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/43198\/revisions\/107813"}],"wp:attachment":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=43198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=43198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=43198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}