{"id":38565,"date":"2016-11-17T11:47:43","date_gmt":"2016-11-17T10:47:43","guid":{"rendered":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/?p=38565"},"modified":"2025-10-13T16:45:13","modified_gmt":"2025-10-13T15:45:13","slug":"histoire-desparros-hautes-pyrenees","status":"publish","type":"post","link":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-desparros-hautes-pyrenees\/","title":{"rendered":"Histoire d&rsquo;Esparros (Hautes-Pyr\u00e9n\u00e9es)"},"content":{"rendered":"<p><strong>Histoire d&rsquo;Esparros (Hautes-Pyr\u00e9n\u00e9es)<\/strong><br \/>\n<a href=\"http:\/\/www.esparros.com\/\" target=\"_blank\" rel=\"noopener\">http:\/\/www.esparros.com\/<\/a><\/p>\n<p style=\"text-align: justify;\"><em><a href=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2016\/11\/esparros65.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-38566\" src=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2016\/11\/esparros65.jpg\" alt=\"esparros65\" width=\"280\" height=\"218\" \/><\/a>un site r\u00e9f\u00e9renc\u00e9 sur le nouvel <a href=\"http:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\" target=\"_blank\" rel=\"noopener noreferrer\">Annuaire Historique des Communes de France<\/a><\/em><\/p>\n<p style=\"text-align: justify;\">Esparros \u00e9tait le si\u00e8ge d&rsquo;une baronnie s&rsquo;\u00e9tendant sur quatre paroisses (Esparros, Labastide, Laborde et Arrodets) mentionn\u00e9es au XIIe si\u00e8cle. C&rsquo;est de la baronnie d&rsquo;Esparros que vient le nom des Baronnies des Pyr\u00e9n\u00e9es, attribu\u00e9 r\u00e9cemment \u00e0 tout le bassin du Haut Arros ; les seigneurs d&rsquo;Esparros sont cit\u00e9s au XIe si\u00e8cle&#8230;<br \/>\n<em> (source wikipedia &#8230; <a href=\"http:\/\/www.esparros.com\/\" target=\"_blank\" rel=\"noopener\">lire la suite<\/a>)<\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/amzn.to\/3KLtYbb\" target=\"_blank\" rel=\"noopener\"><strong>Ouvrages sur les Hautes-Pyr\u00e9n\u00e9es<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/amzn.to\/3KLtYbb\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-103876 aligncenter\" src=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2025\/04\/hautespyrenees2.jpg\" alt=\"\" width=\"342\" height=\"274\" srcset=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2025\/04\/hautespyrenees2.jpg 342w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2025\/04\/hautespyrenees2-300x240.jpg 300w\" sizes=\"auto, (max-width: 342px) 100vw, 342px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Histoire d&rsquo;Esparros (Hautes-Pyr\u00e9n\u00e9es) http:\/\/www.esparros.com\/ un site r\u00e9f\u00e9renc\u00e9 sur le nouvel Annuaire Historique des Communes de France Esparros \u00e9tait le si\u00e8ge d&rsquo;une baronnie s&rsquo;\u00e9tendant sur quatre paroisses (Esparros, Labastide, Laborde et Arrodets) mentionn\u00e9es au XIIe si\u00e8cle. C&rsquo;est de la baronnie d&rsquo;Esparros que vient le nom des Baronnies des Pyr\u00e9n\u00e9es, attribu\u00e9 r\u00e9cemment \u00e0 tout le bassin du &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-desparros-hautes-pyrenees\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":117,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[153,16],"tags":[],"class_list":["post-38565","post","type-post","status-publish","format-standard","hentry","category-65-hautes-pyrenees","category-histoire-regionale","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire d&#039;Esparros (Hautes-Pyr\u00e9n\u00e9es) - Histoire de France - Communiqu\u00e9s<\/title>\n<meta name=\"description\" content=\"Esparros \u00e9tait le si\u00e8ge d&#039;une baronnie s&#039;\u00e9tendant sur quatre paroisses (Esparros, Labastide, Laborde et Arrodets)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-desparros-hautes-pyrenees\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire d&#039;Esparros (Hautes-Pyr\u00e9n\u00e9es) - Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Esparros \u00e9tait le si\u00e8ge d&#039;une baronnie s&#039;\u00e9tendant sur quatre paroisses (Esparros, Labastide, Laborde et Arrodets)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-desparros-hautes-pyrenees\/\" \/>\n<meta property=\"og:site_name\" content=\"Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-17T10:47:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-13T15:45:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2016\/11\/esparros65.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"280\" \/>\n\t<meta property=\"og:image:height\" content=\"218\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"administrateur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrateur\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-desparros-hautes-pyrenees\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-desparros-hautes-pyrenees\\\/\"},\"author\":{\"name\":\"administrateur\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\"},\"headline\":\"Histoire d&rsquo;Esparros (Hautes-Pyr\u00e9n\u00e9es)\",\"datePublished\":\"2016-11-17T10:47:43+00:00\",\"dateModified\":\"2025-10-13T15:45:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-desparros-hautes-pyrenees\\\/\"},\"wordCount\":102,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-desparros-hautes-pyrenees\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/esparros65.jpg\",\"articleSection\":[\"65 - Hautes-Pyr\u00e9n\u00e9es\",\"histoire locale\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-desparros-hautes-pyrenees\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-desparros-hautes-pyrenees\\\/\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-desparros-hautes-pyrenees\\\/\",\"name\":\"Histoire d'Esparros (Hautes-Pyr\u00e9n\u00e9es) - Histoire de France - Communiqu\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-desparros-hautes-pyrenees\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-desparros-hautes-pyrenees\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/esparros65.jpg\",\"datePublished\":\"2016-11-17T10:47:43+00:00\",\"dateModified\":\"2025-10-13T15:45:13+00:00\",\"description\":\"Esparros \u00e9tait le si\u00e8ge d'une baronnie s'\u00e9tendant sur quatre paroisses (Esparros, Labastide, Laborde et Arrodets)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-desparros-hautes-pyrenees\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-desparros-hautes-pyrenees\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-desparros-hautes-pyrenees\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/esparros65.jpg\",\"contentUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/esparros65.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-desparros-hautes-pyrenees\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Histoire d&rsquo;Esparros (Hautes-Pyr\u00e9n\u00e9es)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\",\"name\":\"Histoire de France - Communiqu\u00e9s\",\"description\":\"Histoire et patrimoine\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\",\"name\":\"administrateur\",\"logo\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.charles-de-flahaut.fr\",\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\",\"name\":\"administrateur\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/author\\\/hist_8la_ad\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire d'Esparros (Hautes-Pyr\u00e9n\u00e9es) - Histoire de France - Communiqu\u00e9s","description":"Esparros \u00e9tait le si\u00e8ge d'une baronnie s'\u00e9tendant sur quatre paroisses (Esparros, Labastide, Laborde et Arrodets)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-desparros-hautes-pyrenees\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire d'Esparros (Hautes-Pyr\u00e9n\u00e9es) - Histoire de France - Communiqu\u00e9s","og_description":"Esparros \u00e9tait le si\u00e8ge d'une baronnie s'\u00e9tendant sur quatre paroisses (Esparros, Labastide, Laborde et Arrodets)","og_url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-desparros-hautes-pyrenees\/","og_site_name":"Histoire de France - Communiqu\u00e9s","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_published_time":"2016-11-17T10:47:43+00:00","article_modified_time":"2025-10-13T15:45:13+00:00","og_image":[{"width":280,"height":218,"url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2016\/11\/esparros65.jpg","type":"image\/jpeg"}],"author":"administrateur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"administrateur","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-desparros-hautes-pyrenees\/#article","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-desparros-hautes-pyrenees\/"},"author":{"name":"administrateur","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56"},"headline":"Histoire d&rsquo;Esparros (Hautes-Pyr\u00e9n\u00e9es)","datePublished":"2016-11-17T10:47:43+00:00","dateModified":"2025-10-13T15:45:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-desparros-hautes-pyrenees\/"},"wordCount":102,"commentCount":0,"publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-desparros-hautes-pyrenees\/#primaryimage"},"thumbnailUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2016\/11\/esparros65.jpg","articleSection":["65 - Hautes-Pyr\u00e9n\u00e9es","histoire locale"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-desparros-hautes-pyrenees\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-desparros-hautes-pyrenees\/","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-desparros-hautes-pyrenees\/","name":"Histoire d'Esparros (Hautes-Pyr\u00e9n\u00e9es) - Histoire de France - Communiqu\u00e9s","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-desparros-hautes-pyrenees\/#primaryimage"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-desparros-hautes-pyrenees\/#primaryimage"},"thumbnailUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2016\/11\/esparros65.jpg","datePublished":"2016-11-17T10:47:43+00:00","dateModified":"2025-10-13T15:45:13+00:00","description":"Esparros \u00e9tait le si\u00e8ge d'une baronnie s'\u00e9tendant sur quatre paroisses (Esparros, Labastide, Laborde et Arrodets)","breadcrumb":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-desparros-hautes-pyrenees\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-desparros-hautes-pyrenees\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-desparros-hautes-pyrenees\/#primaryimage","url":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2016\/11\/esparros65.jpg","contentUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2016\/11\/esparros65.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-desparros-hautes-pyrenees\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Histoire d&rsquo;Esparros (Hautes-Pyr\u00e9n\u00e9es)"}]},{"@type":"WebSite","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/","name":"Histoire de France - Communiqu\u00e9s","description":"Histoire et patrimoine","publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9","name":"administrateur","logo":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/www.charles-de-flahaut.fr","https:\/\/www.facebook.com\/Sites.HistoiredeFrance"]},{"@type":"Person","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56","name":"administrateur","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/author\/hist_8la_ad\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/38565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=38565"}],"version-history":[{"count":4,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/38565\/revisions"}],"predecessor-version":[{"id":111084,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/38565\/revisions\/111084"}],"wp:attachment":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=38565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=38565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=38565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}