{"id":2569,"date":"2013-06-23T10:45:58","date_gmt":"2013-06-23T09:45:58","guid":{"rendered":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/?p=2569"},"modified":"2024-01-26T11:59:30","modified_gmt":"2024-01-26T10:59:30","slug":"histoire-de-scolca-haute-corse","status":"publish","type":"post","link":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-scolca-haute-corse\/","title":{"rendered":"Histoire de Scolca (Haute-Corse)"},"content":{"rendered":"<p>Un nouveau site r\u00e9f\u00e9renc\u00e9 sur <a href=\"http:\/\/www.histoire-communes.jpflahaut.fr\/\" target=\"_blank\" rel=\"noopener\">Annuaire Histoire<\/a> :<\/p>\n<p><strong>Histoire de Scolca (Haute-Corse)<\/strong><br \/>\n<a href=\"http:\/\/scolca.fr\/?page_id=2\" target=\"_blank\" rel=\"noopener\">http:\/\/scolca.fr\/?page_id=2<\/a><\/p>\n<p><a href=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2013\/06\/scolca.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-2570\" title=\"scolca\" src=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2013\/06\/scolca-224x300.jpg\" alt=\"\" width=\"157\" height=\"210\" srcset=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2013\/06\/scolca-224x300.jpg 224w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2013\/06\/scolca.jpg 440w\" sizes=\"auto, (max-width: 157px) 100vw, 157px\" \/><\/a>Liste des documents publi\u00e9s<\/p>\n<p>01. Scolca mon village (Jean-Fran\u00e7ois Bonetti)<br \/>\n02. Recensement de 1770 (Jean-Fran\u00e7ois Bonetti, Toussaint Romani)<br \/>\n03. Recensement de 1846 (Jean-Fran\u00e7ois Bonetti)<br \/>\n04. Mariages de 1665 \u00e0 1710 (Jean-Fran\u00e7ois Bonetti, Toussaint Romani)<br \/>\n05. Naissances de 1770 \u00e0 1900 (Jean-Fran\u00e7ois Bonetti, Toussaint Romani)<br \/>\n06. Mariages de 1771 \u00e0 1907 (Jean-Fran\u00e7ois Bonetti, Toussaint Romani)<\/p>\n<p><em>(photo et extrait du site de la commune)<\/em><\/p>\n<p><a href=\"https:\/\/amzn.to\/3ScvZx8\" target=\"_blank\" rel=\"noopener\"><strong>Ouvrages sur la Corse<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un nouveau site r\u00e9f\u00e9renc\u00e9 sur Annuaire Histoire : Histoire de Scolca (Haute-Corse) http:\/\/scolca.fr\/?page_id=2 Liste des documents publi\u00e9s 01. Scolca mon village (Jean-Fran\u00e7ois Bonetti) 02. Recensement de 1770 (Jean-Fran\u00e7ois Bonetti, Toussaint Romani) 03. Recensement de 1846 (Jean-Fran\u00e7ois Bonetti) 04. Mariages de 1665 \u00e0 1710 (Jean-Fran\u00e7ois Bonetti, Toussaint Romani) 05. Naissances de 1770 \u00e0 1900 (Jean-Fran\u00e7ois Bonetti, &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-scolca-haute-corse\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[185,16],"tags":[],"class_list":["post-2569","post","type-post","status-publish","format-standard","hentry","category-2b-haute-corse","category-histoire-regionale","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire de Scolca (Haute-Corse) - Histoire de France - Communiqu\u00e9s<\/title>\n<meta name=\"description\" content=\"01. Scolca mon village (Jean-Fran\u00e7ois Bonetti)02. Recensement de 1770 (Jean-Fran\u00e7ois Bonetti, Toussaint Romani)03. Recensement de 1846\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-scolca-haute-corse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire de Scolca (Haute-Corse) - Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"og:description\" content=\"01. Scolca mon village (Jean-Fran\u00e7ois Bonetti)02. Recensement de 1770 (Jean-Fran\u00e7ois Bonetti, Toussaint Romani)03. Recensement de 1846\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-scolca-haute-corse\/\" \/>\n<meta property=\"og:site_name\" content=\"Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:published_time\" content=\"2013-06-23T09:45:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-26T10:59:30+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2013\/06\/scolca-224x300.jpg\" \/>\n<meta name=\"author\" content=\"administrateur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrateur\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-scolca-haute-corse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-scolca-haute-corse\\\/\"},\"author\":{\"name\":\"administrateur\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"headline\":\"Histoire de Scolca (Haute-Corse)\",\"datePublished\":\"2013-06-23T09:45:58+00:00\",\"dateModified\":\"2024-01-26T10:59:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-scolca-haute-corse\\\/\"},\"wordCount\":78,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-scolca-haute-corse\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/scolca-224x300.jpg\",\"articleSection\":[\"2B - Haute-Corse\",\"histoire locale\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-scolca-haute-corse\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-scolca-haute-corse\\\/\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-scolca-haute-corse\\\/\",\"name\":\"Histoire de Scolca (Haute-Corse) - Histoire de France - Communiqu\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-scolca-haute-corse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-scolca-haute-corse\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/scolca-224x300.jpg\",\"datePublished\":\"2013-06-23T09:45:58+00:00\",\"dateModified\":\"2024-01-26T10:59:30+00:00\",\"description\":\"01. Scolca mon village (Jean-Fran\u00e7ois Bonetti)02. Recensement de 1770 (Jean-Fran\u00e7ois Bonetti, Toussaint Romani)03. Recensement de 1846\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-scolca-haute-corse\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-scolca-haute-corse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-scolca-haute-corse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/scolca.jpg\",\"contentUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/scolca.jpg\",\"width\":\"440\",\"height\":\"587\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-de-scolca-haute-corse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Histoire de Scolca (Haute-Corse)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\",\"name\":\"Histoire de France - Communiqu\u00e9s\",\"description\":\"Histoire et patrimoine\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\",\"name\":\"administrateur\",\"logo\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.charles-de-flahaut.fr\",\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"],\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire de Scolca (Haute-Corse) - Histoire de France - Communiqu\u00e9s","description":"01. Scolca mon village (Jean-Fran\u00e7ois Bonetti)02. Recensement de 1770 (Jean-Fran\u00e7ois Bonetti, Toussaint Romani)03. Recensement de 1846","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-scolca-haute-corse\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire de Scolca (Haute-Corse) - Histoire de France - Communiqu\u00e9s","og_description":"01. Scolca mon village (Jean-Fran\u00e7ois Bonetti)02. Recensement de 1770 (Jean-Fran\u00e7ois Bonetti, Toussaint Romani)03. Recensement de 1846","og_url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-scolca-haute-corse\/","og_site_name":"Histoire de France - Communiqu\u00e9s","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_author":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_published_time":"2013-06-23T09:45:58+00:00","article_modified_time":"2024-01-26T10:59:30+00:00","og_image":[{"url":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2013\/06\/scolca-224x300.jpg","type":"","width":"","height":""}],"author":"administrateur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"administrateur","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-scolca-haute-corse\/#article","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-scolca-haute-corse\/"},"author":{"name":"administrateur","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"headline":"Histoire de Scolca (Haute-Corse)","datePublished":"2013-06-23T09:45:58+00:00","dateModified":"2024-01-26T10:59:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-scolca-haute-corse\/"},"wordCount":78,"commentCount":0,"publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-scolca-haute-corse\/#primaryimage"},"thumbnailUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2013\/06\/scolca-224x300.jpg","articleSection":["2B - Haute-Corse","histoire locale"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-scolca-haute-corse\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-scolca-haute-corse\/","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-scolca-haute-corse\/","name":"Histoire de Scolca (Haute-Corse) - Histoire de France - Communiqu\u00e9s","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-scolca-haute-corse\/#primaryimage"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-scolca-haute-corse\/#primaryimage"},"thumbnailUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2013\/06\/scolca-224x300.jpg","datePublished":"2013-06-23T09:45:58+00:00","dateModified":"2024-01-26T10:59:30+00:00","description":"01. Scolca mon village (Jean-Fran\u00e7ois Bonetti)02. Recensement de 1770 (Jean-Fran\u00e7ois Bonetti, Toussaint Romani)03. Recensement de 1846","breadcrumb":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-scolca-haute-corse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-scolca-haute-corse\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-scolca-haute-corse\/#primaryimage","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2013\/06\/scolca.jpg","contentUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2013\/06\/scolca.jpg","width":"440","height":"587"},{"@type":"BreadcrumbList","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-de-scolca-haute-corse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Histoire de Scolca (Haute-Corse)"}]},{"@type":"WebSite","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/","name":"Histoire de France - Communiqu\u00e9s","description":"Histoire et patrimoine","publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9","name":"administrateur","logo":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/www.charles-de-flahaut.fr","https:\/\/www.facebook.com\/Sites.HistoiredeFrance"],"url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/author\/admin\/"}]}},"views":909,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/2569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=2569"}],"version-history":[{"count":10,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/2569\/revisions"}],"predecessor-version":[{"id":95462,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/2569\/revisions\/95462"}],"wp:attachment":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=2569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=2569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=2569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}