{"id":1983,"date":"2013-05-17T08:21:28","date_gmt":"2013-05-17T07:21:28","guid":{"rendered":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/?p=1983"},"modified":"2024-01-23T17:10:39","modified_gmt":"2024-01-23T16:10:39","slug":"histoire-et-patrimoine-de-saillac-correze","status":"publish","type":"post","link":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saillac-correze\/","title":{"rendered":"Histoire et patrimoine de Saillac (Corr\u00e9ze)"},"content":{"rendered":"<p>Une nouvelle page r\u00e9f\u00e9renc\u00e9e sur <a href=\"http:\/\/www.histoire-communes.jpflahaut.fr\/\" target=\"_blank\" rel=\"noopener\">Annuaire Histoire<\/a> :<\/p>\n<p><strong>Histoire et patrimoine de Saillac (Corr\u00e9ze)<\/strong><br \/>\n<a href=\"http:\/\/www.ot-collonges.fr\/Saillac\" target=\"_blank\" rel=\"noopener\">http:\/\/www.ot-collonges.fr\/Saillac<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2013\/05\/saillac1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-1984\" title=\"saillac1\" src=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2013\/05\/saillac1-300x200.jpg\" alt=\"\" width=\"210\" height=\"140\" srcset=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2013\/05\/saillac1-300x200.jpg 300w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2013\/05\/saillac1.jpg 1000w\" sizes=\"auto, (max-width: 210px) 100vw, 210px\" \/><\/a>Entre les sites que sont Collonges-la-Rouge, Curemonte, Meyssac et Turenne, Saillac appara\u00eet le petit village \u00e0 ne pas laisser sur le bord de la route tant la chaleur de vivre et la qualit\u00e9 du patrimoine lui font honneur.<br \/>\nL\u2019\u00e9glise du XII\u00e8me si\u00e8cle fortifi\u00e9e, avec un tympan en pierre polychrome repr\u00e9sentant une sc\u00e8ne de l\u2019adoration des mages, un v\u00e9ritable chef d\u2019\u0153uvre du moyen \u00e2ge ( restaur\u00e9 fra\u00eechement en 2010 ) .Le tout class\u00e9 aux monuments historiques depuis le 23 Janvier 2007&#8230;<\/p>\n<p>(photo et extrait du site de l&rsquo;OT Collonges la Rouge &#8230; <a href=\"http:\/\/www.ot-collonges.fr\/Saillac\" target=\"_blank\" rel=\"noopener\">lire la suite<\/a>)<\/p>\n<p><a href=\"https:\/\/amzn.to\/4946kxl\" target=\"_blank\" rel=\"noopener\"><strong>Ouvrages sur la Corr\u00e8ze<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une nouvelle page r\u00e9f\u00e9renc\u00e9e sur Annuaire Histoire : Histoire et patrimoine de Saillac (Corr\u00e9ze) http:\/\/www.ot-collonges.fr\/Saillac Entre les sites que sont Collonges-la-Rouge, Curemonte, Meyssac et Turenne, Saillac appara\u00eet le petit village \u00e0 ne pas laisser sur le bord de la route tant la chaleur de vivre et la qualit\u00e9 du patrimoine lui font honneur. L\u2019\u00e9glise du &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saillac-correze\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[108,16,8],"tags":[],"class_list":["post-1983","post","type-post","status-publish","format-standard","hentry","category-19-correze","category-histoire-regionale","category-patrimoine","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire et patrimoine de Saillac (Corr\u00e9ze) - Histoire de France - Communiqu\u00e9s<\/title>\n<meta name=\"description\" content=\"Entre les sites que sont Collonges-la-Rouge, Curemonte, Meyssac et Turenne, Saillac appara\u00eet le petit village \u00e0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saillac-correze\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire et patrimoine de Saillac (Corr\u00e9ze) - Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Entre les sites que sont Collonges-la-Rouge, Curemonte, Meyssac et Turenne, Saillac appara\u00eet le petit village \u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saillac-correze\/\" \/>\n<meta property=\"og:site_name\" content=\"Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-17T07:21:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-23T16:10:39+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2013\/05\/saillac1-300x200.jpg\" \/>\n<meta name=\"author\" content=\"administrateur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrateur\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saillac-correze\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saillac-correze\\\/\"},\"author\":{\"name\":\"administrateur\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"headline\":\"Histoire et patrimoine de Saillac (Corr\u00e9ze)\",\"datePublished\":\"2013-05-17T07:21:28+00:00\",\"dateModified\":\"2024-01-23T16:10:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saillac-correze\\\/\"},\"wordCount\":133,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saillac-correze\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/saillac1-300x200.jpg\",\"articleSection\":[\"19 - Corr\u00e8ze\",\"histoire locale\",\"patrimoine\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saillac-correze\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saillac-correze\\\/\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saillac-correze\\\/\",\"name\":\"Histoire et patrimoine de Saillac (Corr\u00e9ze) - Histoire de France - Communiqu\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saillac-correze\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saillac-correze\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/saillac1-300x200.jpg\",\"datePublished\":\"2013-05-17T07:21:28+00:00\",\"dateModified\":\"2024-01-23T16:10:39+00:00\",\"description\":\"Entre les sites que sont Collonges-la-Rouge, Curemonte, Meyssac et Turenne, Saillac appara\u00eet le petit village \u00e0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saillac-correze\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saillac-correze\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saillac-correze\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/saillac1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/saillac1.jpg\",\"width\":\"1000\",\"height\":\"667\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-patrimoine-de-saillac-correze\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Histoire et patrimoine de Saillac (Corr\u00e9ze)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\",\"name\":\"Histoire de France - Communiqu\u00e9s\",\"description\":\"Histoire et patrimoine\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\",\"name\":\"administrateur\",\"logo\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.charles-de-flahaut.fr\",\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"],\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire et patrimoine de Saillac (Corr\u00e9ze) - Histoire de France - Communiqu\u00e9s","description":"Entre les sites que sont Collonges-la-Rouge, Curemonte, Meyssac et Turenne, Saillac appara\u00eet le petit village \u00e0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saillac-correze\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire et patrimoine de Saillac (Corr\u00e9ze) - Histoire de France - Communiqu\u00e9s","og_description":"Entre les sites que sont Collonges-la-Rouge, Curemonte, Meyssac et Turenne, Saillac appara\u00eet le petit village \u00e0","og_url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saillac-correze\/","og_site_name":"Histoire de France - Communiqu\u00e9s","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_author":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_published_time":"2013-05-17T07:21:28+00:00","article_modified_time":"2024-01-23T16:10:39+00:00","og_image":[{"url":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2013\/05\/saillac1-300x200.jpg","type":"","width":"","height":""}],"author":"administrateur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"administrateur","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saillac-correze\/#article","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saillac-correze\/"},"author":{"name":"administrateur","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"headline":"Histoire et patrimoine de Saillac (Corr\u00e9ze)","datePublished":"2013-05-17T07:21:28+00:00","dateModified":"2024-01-23T16:10:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saillac-correze\/"},"wordCount":133,"commentCount":0,"publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saillac-correze\/#primaryimage"},"thumbnailUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2013\/05\/saillac1-300x200.jpg","articleSection":["19 - Corr\u00e8ze","histoire locale","patrimoine"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saillac-correze\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saillac-correze\/","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saillac-correze\/","name":"Histoire et patrimoine de Saillac (Corr\u00e9ze) - Histoire de France - Communiqu\u00e9s","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saillac-correze\/#primaryimage"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saillac-correze\/#primaryimage"},"thumbnailUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2013\/05\/saillac1-300x200.jpg","datePublished":"2013-05-17T07:21:28+00:00","dateModified":"2024-01-23T16:10:39+00:00","description":"Entre les sites que sont Collonges-la-Rouge, Curemonte, Meyssac et Turenne, Saillac appara\u00eet le petit village \u00e0","breadcrumb":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saillac-correze\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saillac-correze\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saillac-correze\/#primaryimage","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2013\/05\/saillac1.jpg","contentUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2013\/05\/saillac1.jpg","width":"1000","height":"667"},{"@type":"BreadcrumbList","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-patrimoine-de-saillac-correze\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Histoire et patrimoine de Saillac (Corr\u00e9ze)"}]},{"@type":"WebSite","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/","name":"Histoire de France - Communiqu\u00e9s","description":"Histoire et patrimoine","publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9","name":"administrateur","logo":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/www.charles-de-flahaut.fr","https:\/\/www.facebook.com\/Sites.HistoiredeFrance"],"url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/author\/admin\/"}]}},"views":321,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/1983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=1983"}],"version-history":[{"count":9,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/1983\/revisions"}],"predecessor-version":[{"id":95203,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/1983\/revisions\/95203"}],"wp:attachment":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=1983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=1983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=1983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}