{"id":17315,"date":"2015-11-18T16:05:00","date_gmt":"2015-11-18T15:05:00","guid":{"rendered":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/?p=17315"},"modified":"2019-10-31T18:32:04","modified_gmt":"2019-10-31T17:32:04","slug":"historique-et-patrimoine-davord-cher","status":"publish","type":"post","link":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/historique-et-patrimoine-davord-cher\/","title":{"rendered":"Historique et patrimoine d&rsquo;Avord (Cher)"},"content":{"rendered":"<p><strong>Historique et patrimoine d&rsquo;Avord (Cher)<\/strong><br \/>\n<a href=\"http:\/\/www.ville-avord.fr\/-Historique-d-Avord-.html\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/www.ville-avord.fr\/-Historique-d-Avord-.html<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/11\/avord18.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-17316\" src=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/11\/avord18-300x225.jpg\" alt=\"avord18\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/11\/avord18-300x225.jpg 300w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/11\/avord18.jpg 425w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><em>un site r\u00e9f\u00e9renc\u00e9 sur le nouvel&nbsp;&nbsp;<a href=\"http:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\" target=\"_blank\" rel=\"noopener noreferrer\">Annuaire Historique des Communes de France<\/a><\/em><\/p>\n<p style=\"text-align: justify;\">AVORD s&rsquo;\u00e9crivait VOR en 1064, AVOR en 1123, 1164, 1229, AVOUR en 1409 et 1523, AVORZ en 1219, AVORD en 1507 et 1665.<br \/>\nAVORD d\u00fbt \u00eatre tr\u00e8s t\u00f4t un centre d&rsquo;habitat et devint un centre religieux dont t\u00e9moigne encore l&rsquo;\u00e9glise par ses parties les plus anciennes remontant au XIe si\u00e8cle.<br \/>\nAutrefois, l&rsquo;\u00e9conomie de la commune \u00e9tait totalement agricole&#8230;<br \/>\n<em>(image et extrait du site officiel de la commune &#8230; <a href=\"http:\/\/www.ville-avord.fr\/-Historique-d-Avord-.html\" target=\"_blank\" rel=\"noopener noreferrer\">lire la suite<\/a>)<\/em><\/p>\n<p><iframe loading=\"lazy\" style=\"width: 120px; height: 240px;\" src=\"\/\/ws-eu.amazon-adsystem.com\/widgets\/q?ServiceVersion=20070822&amp;OneJS=1&amp;Operation=GetAdHtml&amp;MarketPlace=FR&amp;source=ac&amp;ref=tf_til&amp;ad_type=product_link&amp;tracking_id=charledeflaha-21&amp;marketplace=amazon&amp;region=FR&amp;placement=2915907897&amp;asins=2915907897&amp;linkId=4KYQWXAN52ZERSHI&amp;show_border=true&amp;link_opens_in_new_window=true\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" width=\"300\" height=\"150\" frameborder=\"0\"><br \/>\n<\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Historique et patrimoine d&rsquo;Avord (Cher) http:\/\/www.ville-avord.fr\/-Historique-d-Avord-.html un site r\u00e9f\u00e9renc\u00e9 sur le nouvel&nbsp;&nbsp;Annuaire Historique des Communes de France AVORD s&rsquo;\u00e9crivait VOR en 1064, AVOR en 1123, 1164, 1229, AVOUR en 1409 et 1523, AVORZ en 1219, AVORD en 1507 et 1665. AVORD d\u00fbt \u00eatre tr\u00e8s t\u00f4t un centre d&rsquo;habitat et devint un centre religieux dont t\u00e9moigne &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/historique-et-patrimoine-davord-cher\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":117,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[107,16,8],"tags":[],"class_list":["post-17315","post","type-post","status-publish","format-standard","hentry","category-18-cher","category-histoire-regionale","category-patrimoine","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Historique et patrimoine d&#039;Avord (Cher) - Histoire de France - Communiqu\u00e9s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/historique-et-patrimoine-davord-cher\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Historique et patrimoine d&#039;Avord (Cher) - Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Historique et patrimoine d&rsquo;Avord (Cher) http:\/\/www.ville-avord.fr\/-Historique-d-Avord-.html un site r\u00e9f\u00e9renc\u00e9 sur le nouvel&nbsp;&nbsp;Annuaire Historique des Communes de France AVORD s&rsquo;\u00e9crivait VOR en 1064, AVOR en 1123, 1164, 1229, AVOUR en 1409 et 1523, AVORZ en 1219, AVORD en 1507 et 1665. AVORD d\u00fbt \u00eatre tr\u00e8s t\u00f4t un centre d&rsquo;habitat et devint un centre religieux dont t\u00e9moigne &hellip; Lire la suite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/historique-et-patrimoine-davord-cher\/\" \/>\n<meta property=\"og:site_name\" content=\"Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-18T15:05:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-31T17:32:04+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/11\/avord18-300x225.jpg\" \/>\n<meta name=\"author\" content=\"administrateur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrateur\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/historique-et-patrimoine-davord-cher\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/historique-et-patrimoine-davord-cher\\\/\"},\"author\":{\"name\":\"administrateur\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\"},\"headline\":\"Historique et patrimoine d&rsquo;Avord (Cher)\",\"datePublished\":\"2015-11-18T15:05:00+00:00\",\"dateModified\":\"2019-10-31T17:32:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/historique-et-patrimoine-davord-cher\\\/\"},\"wordCount\":104,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/historique-et-patrimoine-davord-cher\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/avord18-300x225.jpg\",\"articleSection\":[\"18 - Cher\",\"histoire locale\",\"patrimoine\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/historique-et-patrimoine-davord-cher\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/historique-et-patrimoine-davord-cher\\\/\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/historique-et-patrimoine-davord-cher\\\/\",\"name\":\"Historique et patrimoine d'Avord (Cher) - Histoire de France - Communiqu\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/historique-et-patrimoine-davord-cher\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/historique-et-patrimoine-davord-cher\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/avord18-300x225.jpg\",\"datePublished\":\"2015-11-18T15:05:00+00:00\",\"dateModified\":\"2019-10-31T17:32:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/historique-et-patrimoine-davord-cher\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/historique-et-patrimoine-davord-cher\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/historique-et-patrimoine-davord-cher\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/avord18.jpg\",\"contentUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/avord18.jpg\",\"width\":425,\"height\":319},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/historique-et-patrimoine-davord-cher\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Historique et patrimoine d&rsquo;Avord (Cher)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\",\"name\":\"Histoire de France - Communiqu\u00e9s\",\"description\":\"Histoire et patrimoine\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\",\"name\":\"administrateur\",\"logo\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.charles-de-flahaut.fr\",\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\",\"name\":\"administrateur\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/author\\\/hist_8la_ad\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Historique et patrimoine d'Avord (Cher) - Histoire de France - Communiqu\u00e9s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/historique-et-patrimoine-davord-cher\/","og_locale":"fr_FR","og_type":"article","og_title":"Historique et patrimoine d'Avord (Cher) - Histoire de France - Communiqu\u00e9s","og_description":"Historique et patrimoine d&rsquo;Avord (Cher) http:\/\/www.ville-avord.fr\/-Historique-d-Avord-.html un site r\u00e9f\u00e9renc\u00e9 sur le nouvel&nbsp;&nbsp;Annuaire Historique des Communes de France AVORD s&rsquo;\u00e9crivait VOR en 1064, AVOR en 1123, 1164, 1229, AVOUR en 1409 et 1523, AVORZ en 1219, AVORD en 1507 et 1665. AVORD d\u00fbt \u00eatre tr\u00e8s t\u00f4t un centre d&rsquo;habitat et devint un centre religieux dont t\u00e9moigne &hellip; Lire la suite","og_url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/historique-et-patrimoine-davord-cher\/","og_site_name":"Histoire de France - Communiqu\u00e9s","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_published_time":"2015-11-18T15:05:00+00:00","article_modified_time":"2019-10-31T17:32:04+00:00","og_image":[{"url":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/11\/avord18-300x225.jpg","type":"","width":"","height":""}],"author":"administrateur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"administrateur"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/historique-et-patrimoine-davord-cher\/#article","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/historique-et-patrimoine-davord-cher\/"},"author":{"name":"administrateur","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56"},"headline":"Historique et patrimoine d&rsquo;Avord (Cher)","datePublished":"2015-11-18T15:05:00+00:00","dateModified":"2019-10-31T17:32:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/historique-et-patrimoine-davord-cher\/"},"wordCount":104,"commentCount":0,"publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/historique-et-patrimoine-davord-cher\/#primaryimage"},"thumbnailUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/11\/avord18-300x225.jpg","articleSection":["18 - Cher","histoire locale","patrimoine"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/historique-et-patrimoine-davord-cher\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/historique-et-patrimoine-davord-cher\/","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/historique-et-patrimoine-davord-cher\/","name":"Historique et patrimoine d'Avord (Cher) - Histoire de France - Communiqu\u00e9s","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/historique-et-patrimoine-davord-cher\/#primaryimage"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/historique-et-patrimoine-davord-cher\/#primaryimage"},"thumbnailUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/11\/avord18-300x225.jpg","datePublished":"2015-11-18T15:05:00+00:00","dateModified":"2019-10-31T17:32:04+00:00","breadcrumb":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/historique-et-patrimoine-davord-cher\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/historique-et-patrimoine-davord-cher\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/historique-et-patrimoine-davord-cher\/#primaryimage","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/11\/avord18.jpg","contentUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/11\/avord18.jpg","width":425,"height":319},{"@type":"BreadcrumbList","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/historique-et-patrimoine-davord-cher\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Historique et patrimoine d&rsquo;Avord (Cher)"}]},{"@type":"WebSite","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/","name":"Histoire de France - Communiqu\u00e9s","description":"Histoire et patrimoine","publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9","name":"administrateur","logo":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/www.charles-de-flahaut.fr","https:\/\/www.facebook.com\/Sites.HistoiredeFrance"]},{"@type":"Person","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56","name":"administrateur","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/author\/hist_8la_ad\/"}]}},"views":416,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/17315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=17315"}],"version-history":[{"count":4,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/17315\/revisions"}],"predecessor-version":[{"id":70949,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/17315\/revisions\/70949"}],"wp:attachment":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=17315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=17315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=17315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}