{"id":12266,"date":"2015-05-08T11:21:17","date_gmt":"2015-05-08T10:21:17","guid":{"rendered":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/?p=12266"},"modified":"2015-05-08T11:21:17","modified_gmt":"2015-05-08T10:21:17","slug":"histoire-et-traditions-populaires-le-billot-calvados","status":"publish","type":"post","link":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-traditions-populaires-le-billot-calvados\/","title":{"rendered":"Histoire et Traditions Populaires &#8211; Le Billot (Calvados)"},"content":{"rendered":"<p>Histoire et Traditions Populaires &#8211; Le Billot (Calvados)<br \/>\nhttp:\/\/le.billot.pagesperso-orange.fr\/<\/p>\n<p><em><a href=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/05\/lebillot.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-12267\" src=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/05\/lebillot-300x205.jpg\" alt=\"lebillot\" width=\"252\" height=\"172\" srcset=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/05\/lebillot-300x205.jpg 300w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/05\/lebillot.jpg 700w\" sizes=\"auto, (max-width: 252px) 100vw, 252px\" \/><\/a>un nouveau site r\u00e9f\u00e9renc\u00e9 sur <a href=\"http:\/\/www.histoire-communes.jpflahaut.fr\/\" target=\"_blank\">Histoire et patrimoine des villes et villages de France<\/a><\/em><\/p>\n<p>Le Foyer rural du Billot, Grand prix d\u00e9partemental du Tourisme en 1997, organise chaque ann\u00e9e depuis 1974 une exposition \u00e0 th\u00e8me sur l&rsquo;histoire rurale et les traditions populaires du Pays d&rsquo;Auge. (extrait du site)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Histoire et Traditions Populaires &#8211; Le Billot (Calvados) http:\/\/le.billot.pagesperso-orange.fr\/ un nouveau site r\u00e9f\u00e9renc\u00e9 sur Histoire et patrimoine des villes et villages de France Le Foyer rural du Billot, Grand prix d\u00e9partemental du Tourisme en 1997, organise chaque ann\u00e9e depuis 1974 une exposition \u00e0 th\u00e8me sur l&rsquo;histoire rurale et les traditions populaires du Pays d&rsquo;Auge. (extrait &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-traditions-populaires-le-billot-calvados\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":117,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[103,16],"tags":[],"class_list":["post-12266","post","type-post","status-publish","format-standard","hentry","category-14-calvados","category-histoire-regionale","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire et Traditions Populaires - Le Billot (Calvados) - Histoire de France - Communiqu\u00e9s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-traditions-populaires-le-billot-calvados\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire et Traditions Populaires - Le Billot (Calvados) - Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Histoire et Traditions Populaires &#8211; Le Billot (Calvados) http:\/\/le.billot.pagesperso-orange.fr\/ un nouveau site r\u00e9f\u00e9renc\u00e9 sur Histoire et patrimoine des villes et villages de France Le Foyer rural du Billot, Grand prix d\u00e9partemental du Tourisme en 1997, organise chaque ann\u00e9e depuis 1974 une exposition \u00e0 th\u00e8me sur l&rsquo;histoire rurale et les traditions populaires du Pays d&rsquo;Auge. (extrait &hellip; Lire la suite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-traditions-populaires-le-billot-calvados\/\" \/>\n<meta property=\"og:site_name\" content=\"Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-08T10:21:17+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/05\/lebillot-300x205.jpg\" \/>\n<meta name=\"author\" content=\"administrateur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrateur\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-traditions-populaires-le-billot-calvados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-traditions-populaires-le-billot-calvados\\\/\"},\"author\":{\"name\":\"administrateur\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\"},\"headline\":\"Histoire et Traditions Populaires &#8211; Le Billot (Calvados)\",\"datePublished\":\"2015-05-08T10:21:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-traditions-populaires-le-billot-calvados\\\/\"},\"wordCount\":73,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-traditions-populaires-le-billot-calvados\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/lebillot-300x205.jpg\",\"articleSection\":[\"14 - Calvados\",\"histoire locale\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-traditions-populaires-le-billot-calvados\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-traditions-populaires-le-billot-calvados\\\/\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-traditions-populaires-le-billot-calvados\\\/\",\"name\":\"Histoire et Traditions Populaires - Le Billot (Calvados) - Histoire de France - Communiqu\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-traditions-populaires-le-billot-calvados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-traditions-populaires-le-billot-calvados\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/lebillot-300x205.jpg\",\"datePublished\":\"2015-05-08T10:21:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-traditions-populaires-le-billot-calvados\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-traditions-populaires-le-billot-calvados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-traditions-populaires-le-billot-calvados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/lebillot.jpg\",\"contentUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/lebillot.jpg\",\"width\":700,\"height\":478},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/histoire-et-traditions-populaires-le-billot-calvados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Histoire et Traditions Populaires &#8211; Le Billot (Calvados)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\",\"name\":\"Histoire de France - Communiqu\u00e9s\",\"description\":\"Histoire et patrimoine\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\",\"name\":\"administrateur\",\"logo\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.charles-de-flahaut.fr\",\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\",\"name\":\"administrateur\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/author\\\/hist_8la_ad\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire et Traditions Populaires - Le Billot (Calvados) - Histoire de France - Communiqu\u00e9s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-traditions-populaires-le-billot-calvados\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire et Traditions Populaires - Le Billot (Calvados) - Histoire de France - Communiqu\u00e9s","og_description":"Histoire et Traditions Populaires &#8211; Le Billot (Calvados) http:\/\/le.billot.pagesperso-orange.fr\/ un nouveau site r\u00e9f\u00e9renc\u00e9 sur Histoire et patrimoine des villes et villages de France Le Foyer rural du Billot, Grand prix d\u00e9partemental du Tourisme en 1997, organise chaque ann\u00e9e depuis 1974 une exposition \u00e0 th\u00e8me sur l&rsquo;histoire rurale et les traditions populaires du Pays d&rsquo;Auge. (extrait &hellip; Lire la suite","og_url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-traditions-populaires-le-billot-calvados\/","og_site_name":"Histoire de France - Communiqu\u00e9s","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_published_time":"2015-05-08T10:21:17+00:00","og_image":[{"url":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/05\/lebillot-300x205.jpg","type":"","width":"","height":""}],"author":"administrateur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"administrateur"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-traditions-populaires-le-billot-calvados\/#article","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-traditions-populaires-le-billot-calvados\/"},"author":{"name":"administrateur","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56"},"headline":"Histoire et Traditions Populaires &#8211; Le Billot (Calvados)","datePublished":"2015-05-08T10:21:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-traditions-populaires-le-billot-calvados\/"},"wordCount":73,"commentCount":0,"publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-traditions-populaires-le-billot-calvados\/#primaryimage"},"thumbnailUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/05\/lebillot-300x205.jpg","articleSection":["14 - Calvados","histoire locale"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-traditions-populaires-le-billot-calvados\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-traditions-populaires-le-billot-calvados\/","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-traditions-populaires-le-billot-calvados\/","name":"Histoire et Traditions Populaires - Le Billot (Calvados) - Histoire de France - Communiqu\u00e9s","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-traditions-populaires-le-billot-calvados\/#primaryimage"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-traditions-populaires-le-billot-calvados\/#primaryimage"},"thumbnailUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/05\/lebillot-300x205.jpg","datePublished":"2015-05-08T10:21:17+00:00","breadcrumb":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-traditions-populaires-le-billot-calvados\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-traditions-populaires-le-billot-calvados\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-traditions-populaires-le-billot-calvados\/#primaryimage","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/05\/lebillot.jpg","contentUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/05\/lebillot.jpg","width":700,"height":478},{"@type":"BreadcrumbList","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/histoire-et-traditions-populaires-le-billot-calvados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Histoire et Traditions Populaires &#8211; Le Billot (Calvados)"}]},{"@type":"WebSite","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/","name":"Histoire de France - Communiqu\u00e9s","description":"Histoire et patrimoine","publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9","name":"administrateur","logo":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/www.charles-de-flahaut.fr","https:\/\/www.facebook.com\/Sites.HistoiredeFrance"]},{"@type":"Person","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56","name":"administrateur","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/author\/hist_8la_ad\/"}]}},"views":718,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/12266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=12266"}],"version-history":[{"count":1,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/12266\/revisions"}],"predecessor-version":[{"id":12268,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/12266\/revisions\/12268"}],"wp:attachment":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=12266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=12266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=12266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}