{"id":12084,"date":"2015-05-05T17:18:58","date_gmt":"2015-05-05T16:18:58","guid":{"rendered":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/?p=12084"},"modified":"2015-05-05T17:18:58","modified_gmt":"2015-05-05T16:18:58","slug":"empire-de-la-basse-chesnaie-ille-et-villaine","status":"publish","type":"post","link":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/empire-de-la-basse-chesnaie-ille-et-villaine\/","title":{"rendered":"Empire de la Basse Chesnaie  (Ille et Villaine)"},"content":{"rendered":"<p><strong>Empire de la Basse Chesnaie\u00a0 (Ille et Villaine)<\/strong><br \/>\n<a href=\"http:\/\/www.empirebc.fr\" target=\"_blank\">http:\/\/www.empirebc.fr<\/a><\/p>\n<p><em><a href=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/05\/empiredelabassechesnais35.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-12086\" src=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/05\/empiredelabassechesnais35-300x226.jpg\" alt=\"empiredelabassechesnais35\" width=\"232\" height=\"175\" srcset=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/05\/empiredelabassechesnais35-300x226.jpg 300w, https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/05\/empiredelabassechesnais35.jpg 789w\" sizes=\"auto, (max-width: 232px) 100vw, 232px\" \/><\/a>un nouveau site r\u00e9f\u00e9renc\u00e9 sur <a href=\"http:\/\/www.histoire-communes.jpflahaut.fr\/\" target=\"_blank\">Histoire et patrimoine des villes et villages de France<\/a><\/em><\/p>\n<p style=\"text-align: justify;\">L&rsquo;Empire de la Basse Chesnaie est un empire ind\u00e9pendant et donc \u00e9tat libre, enclav\u00e9 sur le territoire Fran\u00e7ais.<br \/>\nInd\u00e9pendant depuis 1996, cet \u00e9tat est dirig\u00e9 par l&rsquo;Empereur Frank-Marc 1er, fondateur de sa dynastie. D&rsquo;une superficie de 1,1 hectare, l&rsquo;Empire de la Basse Chesnaie est donc une des plus petites micronations du monde&#8230; (extrait du site)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Empire de la Basse Chesnaie\u00a0 (Ille et Villaine) http:\/\/www.empirebc.fr un nouveau site r\u00e9f\u00e9renc\u00e9 sur Histoire et patrimoine des villes et villages de France L&rsquo;Empire de la Basse Chesnaie est un empire ind\u00e9pendant et donc \u00e9tat libre, enclav\u00e9 sur le territoire Fran\u00e7ais. Ind\u00e9pendant depuis 1996, cet \u00e9tat est dirig\u00e9 par l&rsquo;Empereur Frank-Marc 1er, fondateur de sa &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/empire-de-la-basse-chesnaie-ille-et-villaine\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":117,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[123,16],"tags":[],"class_list":["post-12084","post","type-post","status-publish","format-standard","hentry","category-35-ille-et-vilaine","category-histoire-regionale","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Empire de la Basse Chesnaie (Ille et Villaine) - Histoire de France - Communiqu\u00e9s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/empire-de-la-basse-chesnaie-ille-et-villaine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Empire de la Basse Chesnaie (Ille et Villaine) - Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Empire de la Basse Chesnaie\u00a0 (Ille et Villaine) http:\/\/www.empirebc.fr un nouveau site r\u00e9f\u00e9renc\u00e9 sur Histoire et patrimoine des villes et villages de France L&rsquo;Empire de la Basse Chesnaie est un empire ind\u00e9pendant et donc \u00e9tat libre, enclav\u00e9 sur le territoire Fran\u00e7ais. Ind\u00e9pendant depuis 1996, cet \u00e9tat est dirig\u00e9 par l&rsquo;Empereur Frank-Marc 1er, fondateur de sa &hellip; Lire la suite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.charles-de-flahaut.fr\/wordpress\/empire-de-la-basse-chesnaie-ille-et-villaine\/\" \/>\n<meta property=\"og:site_name\" content=\"Histoire de France - Communiqu\u00e9s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-05T16:18:58+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/05\/empiredelabassechesnais35-300x226.jpg\" \/>\n<meta name=\"author\" content=\"administrateur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrateur\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/empire-de-la-basse-chesnaie-ille-et-villaine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/empire-de-la-basse-chesnaie-ille-et-villaine\\\/\"},\"author\":{\"name\":\"administrateur\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\"},\"headline\":\"Empire de la Basse Chesnaie (Ille et Villaine)\",\"datePublished\":\"2015-05-05T16:18:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/empire-de-la-basse-chesnaie-ille-et-villaine\\\/\"},\"wordCount\":96,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/empire-de-la-basse-chesnaie-ille-et-villaine\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/empiredelabassechesnais35-300x226.jpg\",\"articleSection\":[\"35 - Ille-et-Vilaine\",\"histoire locale\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/empire-de-la-basse-chesnaie-ille-et-villaine\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/empire-de-la-basse-chesnaie-ille-et-villaine\\\/\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/empire-de-la-basse-chesnaie-ille-et-villaine\\\/\",\"name\":\"Empire de la Basse Chesnaie (Ille et Villaine) - Histoire de France - Communiqu\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/empire-de-la-basse-chesnaie-ille-et-villaine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/empire-de-la-basse-chesnaie-ille-et-villaine\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/empiredelabassechesnais35-300x226.jpg\",\"datePublished\":\"2015-05-05T16:18:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/empire-de-la-basse-chesnaie-ille-et-villaine\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/empire-de-la-basse-chesnaie-ille-et-villaine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/empire-de-la-basse-chesnaie-ille-et-villaine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/empiredelabassechesnais35.jpg\",\"contentUrl\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/empiredelabassechesnais35.jpg\",\"width\":789,\"height\":594},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/empire-de-la-basse-chesnaie-ille-et-villaine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empire de la Basse Chesnaie (Ille et Villaine)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/\",\"name\":\"Histoire de France - Communiqu\u00e9s\",\"description\":\"Histoire et patrimoine\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/81011c8b61bc74c05499365a506d49a9\",\"name\":\"administrateur\",\"logo\":{\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.charles-de-flahaut.fr\",\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/41c41eaf9ae1d70810ff74a04a786c56\",\"name\":\"administrateur\",\"url\":\"https:\\\/\\\/www.charles-de-flahaut.fr\\\/wordpress\\\/author\\\/hist_8la_ad\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Empire de la Basse Chesnaie (Ille et Villaine) - Histoire de France - Communiqu\u00e9s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/empire-de-la-basse-chesnaie-ille-et-villaine\/","og_locale":"fr_FR","og_type":"article","og_title":"Empire de la Basse Chesnaie (Ille et Villaine) - Histoire de France - Communiqu\u00e9s","og_description":"Empire de la Basse Chesnaie\u00a0 (Ille et Villaine) http:\/\/www.empirebc.fr un nouveau site r\u00e9f\u00e9renc\u00e9 sur Histoire et patrimoine des villes et villages de France L&rsquo;Empire de la Basse Chesnaie est un empire ind\u00e9pendant et donc \u00e9tat libre, enclav\u00e9 sur le territoire Fran\u00e7ais. Ind\u00e9pendant depuis 1996, cet \u00e9tat est dirig\u00e9 par l&rsquo;Empereur Frank-Marc 1er, fondateur de sa &hellip; Lire la suite","og_url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/empire-de-la-basse-chesnaie-ille-et-villaine\/","og_site_name":"Histoire de France - Communiqu\u00e9s","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_published_time":"2015-05-05T16:18:58+00:00","og_image":[{"url":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/05\/empiredelabassechesnais35-300x226.jpg","type":"","width":"","height":""}],"author":"administrateur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"administrateur"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/empire-de-la-basse-chesnaie-ille-et-villaine\/#article","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/empire-de-la-basse-chesnaie-ille-et-villaine\/"},"author":{"name":"administrateur","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56"},"headline":"Empire de la Basse Chesnaie (Ille et Villaine)","datePublished":"2015-05-05T16:18:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/empire-de-la-basse-chesnaie-ille-et-villaine\/"},"wordCount":96,"commentCount":0,"publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/empire-de-la-basse-chesnaie-ille-et-villaine\/#primaryimage"},"thumbnailUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/05\/empiredelabassechesnais35-300x226.jpg","articleSection":["35 - Ille-et-Vilaine","histoire locale"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/empire-de-la-basse-chesnaie-ille-et-villaine\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/empire-de-la-basse-chesnaie-ille-et-villaine\/","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/empire-de-la-basse-chesnaie-ille-et-villaine\/","name":"Empire de la Basse Chesnaie (Ille et Villaine) - Histoire de France - Communiqu\u00e9s","isPartOf":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/empire-de-la-basse-chesnaie-ille-et-villaine\/#primaryimage"},"image":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/empire-de-la-basse-chesnaie-ille-et-villaine\/#primaryimage"},"thumbnailUrl":"http:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/05\/empiredelabassechesnais35-300x226.jpg","datePublished":"2015-05-05T16:18:58+00:00","breadcrumb":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/empire-de-la-basse-chesnaie-ille-et-villaine\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.charles-de-flahaut.fr\/wordpress\/empire-de-la-basse-chesnaie-ille-et-villaine\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/empire-de-la-basse-chesnaie-ille-et-villaine\/#primaryimage","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/05\/empiredelabassechesnais35.jpg","contentUrl":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-content\/uploads\/2015\/05\/empiredelabassechesnais35.jpg","width":789,"height":594},{"@type":"BreadcrumbList","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/empire-de-la-basse-chesnaie-ille-et-villaine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Empire de la Basse Chesnaie (Ille et Villaine)"}]},{"@type":"WebSite","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#website","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/","name":"Histoire de France - Communiqu\u00e9s","description":"Histoire et patrimoine","publisher":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/81011c8b61bc74c05499365a506d49a9","name":"administrateur","logo":{"@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/www.charles-de-flahaut.fr","https:\/\/www.facebook.com\/Sites.HistoiredeFrance"]},{"@type":"Person","@id":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/#\/schema\/person\/41c41eaf9ae1d70810ff74a04a786c56","name":"administrateur","url":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/author\/hist_8la_ad\/"}]}},"views":1085,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/12084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=12084"}],"version-history":[{"count":2,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/12084\/revisions"}],"predecessor-version":[{"id":12087,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/posts\/12084\/revisions\/12087"}],"wp:attachment":[{"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=12084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=12084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charles-de-flahaut.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=12084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}